{"id":4092,"date":"2021-04-09T03:28:05","date_gmt":"2021-04-09T03:28:05","guid":{"rendered":"http:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/"},"modified":"2021-04-09T03:28:05","modified_gmt":"2021-04-09T03:28:05","slug":"vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria","status":"publish","type":"post","link":"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/","title":{"rendered":"Vuelve Instagram Lite pensada para celulares con poca memoria"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Instagram relanz\u00f3 <strong>Instagram Lite<\/strong>, una versi\u00f3n optimizada pensada para celulares m\u00e1s viejos o bien nuevos pero con escasos recursos, por tratarse de equipos de gama baja. Se trata de una nueva edici\u00f3n de ese mismo servicio que se hab\u00eda lanzado en 2018 y luego se dio de baja. La novedad es que ahora desembarca en 170 pa\u00edses y cuenta con varias mejoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Est\u00e1 disponible s\u00f3lo para Android<\/strong> y se puede descargar desde Google Play. Por el momento no hay planes de lanzar una edici\u00f3n para iOS. Cabe se\u00f1alar que como se trata de un lanzamiento global, puede haber demoras en la disponibilidad del producto. As\u00ed que es posible que hoy algunos usuarios no puedan descargar la plataforma pero en los pr\u00f3ximos d\u00edas ya contar\u00e1n con la posibilidad de hacerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva versi\u00f3n de Instagram Lite mejor\u00f3 la velocidad, el rendimiento y la capacidad de respuesta, seg\u00fan destacan desde la compa\u00f1\u00eda. Cuentan que este desarrollo se bas\u00f3 en Facebook Lite, que se ide\u00f3 en 2015, una edici\u00f3n tambi\u00e9n m\u00e1s liviana de la red social que tambi\u00e9n apunta a optimizar recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los puntos m\u00e1s importantes es que ocupa menos espacio. Mientras la aplicaci\u00f3n original de Instagram tiene un tama\u00f1o de 30 MB, y Lite tiene menos de 2 MB. Para lograr esta importante reducci\u00f3n de tama\u00f1o, se recurri\u00f3 a un importante redise\u00f1o y algunas modificaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lite cuenta con pr\u00e1cticamente todas las funciones que la versi\u00f3n original, incluyendo la funci\u00f3n Explorar o la posibilidad de a\u00f1adir stickers o GIF a las historias por ejemplo, as\u00ed como grabar y publicar videos o enviar mensajes directos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De todos modos, se<strong> tuvieron que dejar de lado algunas caracter\u00edsticas que consumen muchos recursos<\/strong>. De ah\u00ed que no cuente con los filtros de realidad aumentada, una funci\u00f3n que implica mucha exigencia para los equipos m\u00e1s b\u00e1sicos. Tambi\u00e9n se modific\u00f3 el dise\u00f1o de algunos \u00edconos y si bien los usuarios pueden mirar Reels, no pueden generarlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que tener en cuenta que se busc\u00f3 desarrollar una soluci\u00f3n pensada para m\u00f3viles con escasa memoria y acceso a redes de telefon\u00eda lentas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el momento, la aplicaci\u00f3n no tiene anuncios, aunque desde Instagram afirman que est\u00e1n \u201ccomprometidos a ofrecer la suite completa de herramientas de monetizaci\u00f3n\u201d, seg\u00fan public\u00f3 The Verge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nueva versi\u00f3n \u00abpesa\u00bb solo 2 MB, mucho menor a los 30 MB de la original. Se trata de una nueva edici\u00f3n del servicio lanzado en 2018 y luego suspendido. La novedad es que ahora desembarca en 170 pa\u00edses y cuenta con varias mejoras. Por ahora est\u00e1 disponible s\u00f3lo para Android.<\/p>\n","protected":false},"author":1,"featured_media":4093,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[51,52],"class_list":["post-4092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-y-tecnologia","tag-instagram","tag-redes-sociales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vuelve Instagram Lite pensada para celulares con poca memoria - Informatepy<\/title>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vuelve Instagram Lite pensada para celulares con poca memoria - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La nueva versi\u00f3n &quot;pesa&quot; solo 2 MB, mucho menor a los 30 MB de la original. Se trata de una nueva edici\u00f3n del servicio lanzado en 2018 y luego suspendido. La novedad es que ahora desembarca en 170 pa\u00edses y cuenta con varias mejoras. Por ahora est\u00e1 disponible s\u00f3lo para Android.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-09T03:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/news\/wp-content\/uploads\/2021\/04\/instagram-lite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data1\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/informatepy.com\/news\/#website\",\"url\":\"https:\/\/informatepy.com\/news\/\",\"name\":\"Informatepy\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/informatepy.com\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/informatepy.com\/news\/wp-content\/uploads\/2021\/04\/instagram-lite.jpg\",\"contentUrl\":\"https:\/\/informatepy.com\/news\/wp-content\/uploads\/2021\/04\/instagram-lite.jpg\",\"width\":800,\"height\":534},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/#webpage\",\"url\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/\",\"name\":\"Vuelve Instagram Lite pensada para celulares con poca memoria - Informatepy\",\"isPartOf\":{\"@id\":\"https:\/\/informatepy.com\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/#primaryimage\"},\"datePublished\":\"2021-04-09T03:28:05+00:00\",\"dateModified\":\"2021-04-09T03:28:05+00:00\",\"author\":{\"@id\":\"https:\/\/informatepy.com\/news\/#\/schema\/person\/36745e555080581fda8f41e82a159086\"},\"breadcrumb\":{\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informatepy.com\/news\/\",\"url\":\"https:\/\/informatepy.com\/news\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/\",\"url\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/vuelve-instagram-lite-pensada-para-celulares-con-poca-memoria\/\",\"name\":\"Vuelve Instagram Lite pensada para celulares con poca memoria\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/informatepy.com\/news\/#\/schema\/person\/36745e555080581fda8f41e82a159086\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/informatepy.com\/news\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/informatepy.com\/news\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","amp_validity":null,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/posts\/4092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/comments?post=4092"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/posts\/4092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/media\/4093"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/media?parent=4092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/categories?post=4092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/tags?post=4092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}