{"id":3987,"date":"2021-04-09T03:17:44","date_gmt":"2021-04-09T03:17:44","guid":{"rendered":"http:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/"},"modified":"2021-04-09T03:17:44","modified_gmt":"2021-04-09T03:17:44","slug":"detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate","status":"publish","type":"post","link":"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/","title":{"rendered":"Detuvieron al ex presidente del Barcelona, Josep Mar\u00eda Bartomeu, por el Bar\u00e7aGate"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este lunes por la ma\u00f1ana fue detenido el ex presidente del Barcelona\u00a0<strong>Josep Mar\u00eda Bartomeu<\/strong>\u00a0en el marco de la causa denominada como\u00a0<strong>Bar\u00e7aGate.<\/strong>\u00a0El ex directivo, cuya renuncia al cargo se hizo efectiva en octubre del a\u00f1o pasado, es uno de los involucrados en el esc\u00e1ndalo por la campa\u00f1a que presuntamente se llev\u00f3 adelante desde el club para\u00a0<strong>desprestigiar en redes sociales a jugadores de la propia instituci\u00f3n y a otras personas contrarias a las autoridades de aquel momento.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan inform\u00f3 la prensa espa\u00f1ola, fueron cuatro las detenciones en el marco de la causa que investiga la Justicia. Tambi\u00e9n fueron apresados\u00a0<strong>\u00d2scar Grau\u00a0<\/strong>y\u00a0<strong>Rom\u00e0 G\u00f3mez Ponti<\/strong>, CEO y director del departamento jur\u00eddico del club, y\u00a0<strong>Jaume Masferre<\/strong>r, quien fuera uno de los asesores con m\u00e1s llegada a Bartomeu durante su gesti\u00f3n en la entidad Azulgrana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Minutos antes, el club se hab\u00eda visto intervenido por agentes del\u00a0<strong>\u00c1rea Central de Delitos Econ\u00f3micos de los Mossos d\u2019Esquadra<\/strong>, quienes registraron las oficinas del F\u00fatbol Club Barcelona, seg\u00fan informaron a la agencia EFE fuentes policiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Cadena Ser-Barcelona adelant\u00f3 que ese procedimiento estuvo vinculado al denominado Bar\u00e7aGate en el que se investiga si una empresa contratada por el club azulgrana llev\u00f3 a cabo una campa\u00f1a de desprestigio en las redes sociales de jugadores y entidades contrarias a la directiva del expresidente Josep Maria Bartomeu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto el procedimiento en las oficinas del Barcelona como las detenciones fueron ordenadas por el juzgado n\u00famero 13 de Barcelona, que investiga un\u00a0<strong>presunto delito de administraci\u00f3n desleal y corrupci\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infobae<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ex presidente del Barcelona est\u00e1 vinculado a la causa por la campa\u00f1a de desprestigio en redes sociales a jugadores del club y otras personas contrarias a su gesti\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":3988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-3987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detuvieron al ex presidente del Barcelona, Josep Mar\u00eda Bartomeu, por el Bar\u00e7aGate - Informatepy<\/title>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detuvieron al ex presidente del Barcelona, Josep Mar\u00eda Bartomeu, por el Bar\u00e7aGate - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El ex presidente del Barcelona est\u00e1 vinculado a la causa por la campa\u00f1a de desprestigio en redes sociales a jugadores del club y otras personas contrarias a su gesti\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-09T03:17:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/news\/wp-content\/uploads\/2021\/04\/bartomeu.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data1\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/informatepy.com\/news\/#website\",\"url\":\"https:\/\/informatepy.com\/news\/\",\"name\":\"Informatepy\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/informatepy.com\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/informatepy.com\/news\/wp-content\/uploads\/2021\/04\/bartomeu.jpeg\",\"contentUrl\":\"https:\/\/informatepy.com\/news\/wp-content\/uploads\/2021\/04\/bartomeu.jpeg\",\"width\":1200,\"height\":738},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/#webpage\",\"url\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/\",\"name\":\"Detuvieron al ex presidente del Barcelona, Josep Mar\\u00eda Bartomeu, por el Bar\\u00e7aGate - Informatepy\",\"isPartOf\":{\"@id\":\"https:\/\/informatepy.com\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/#primaryimage\"},\"datePublished\":\"2021-04-09T03:17:44+00:00\",\"dateModified\":\"2021-04-09T03:17:44+00:00\",\"author\":{\"@id\":\"https:\/\/informatepy.com\/news\/#\/schema\/person\/36745e555080581fda8f41e82a159086\"},\"breadcrumb\":{\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informatepy.com\/news\/\",\"url\":\"https:\/\/informatepy.com\/news\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/\",\"url\":\"https:\/\/informatepy.com\/news\/2021\/04\/09\/detuvieron-al-ex-presidente-del-barcelona-josep-maria-bartomeu-por-el-barcagate\/\",\"name\":\"Detuvieron al ex presidente del Barcelona, Josep Mar\\u00eda Bartomeu, por el Bar\\u00e7aGate\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/informatepy.com\/news\/#\/schema\/person\/36745e555080581fda8f41e82a159086\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/informatepy.com\/news\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/informatepy.com\/news\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","amp_validity":null,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/posts\/3987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/comments?post=3987"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/posts\/3987\/revisions"}],"predecessor-version":[{"id":3989,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/posts\/3987\/revisions\/3989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/media\/3988"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/media?parent=3987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/categories?post=3987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/news\/wp-json\/wp\/v2\/tags?post=3987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}