{"id":9922,"date":"2023-02-17T19:04:18","date_gmt":"2023-02-17T18:04:18","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/"},"modified":"2023-02-17T19:04:18","modified_gmt":"2023-02-17T18:04:18","slug":"mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/","title":{"rendered":"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">En la ocasi\u00f3n, el mandatario paraguayo se interioriz\u00f3 sobre la poderosa estructura militar que posee la isla, compuesto por un complejo de t\u00faneles subterr\u00e1neos altamente fortificados, ubicado en el condado de Hualien, en la costa este de Taiw\u00e1n.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La presidenta taiwanesa se pronunci\u00f3 a trav\u00e9s su cuenta oficial en Twitter sobre el recorrido que realiz\u00f3 con el gobernante paraguayo a la mencionada base a\u00e9rea de su pa\u00eds. <strong><em>\u201cEl presidente @MaritoAbdo se uni\u00f3 a m\u00ed en una base a\u00e9rea de Hualien para presenciar las capacidades militares de Taiw\u00e1n\u201d<\/em><\/strong>, expres\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Asimismo, mencion\u00f3 que, tuvo el placer de presentarle al mandatario, un exparacaidista, el cord\u00f3n de paraca\u00eddas, un s\u00edmbolo del fuerte v\u00ednculo y compromiso de nuestros pa\u00edses con la seguridad nacional.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En ese mismo sentido, el ministro de Relaciones Exteriores, <strong>Joseph Wu<\/strong>, expres\u00f3 a trav\u00e9s de la misma red social que<strong><em> \u201ces emocionante acompa\u00f1ar a @iingwen en un viaje que presenta a nuestro gran aliado y amigo cercano #Paraguay @MaritoAbdo a Hualien, uno de los lugares m\u00e1s hermosos de Taiw\u00e1n y hogar de una destacada base de la fuerza a\u00e9rea\u201d.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Con esta visita, el mandatario paraguayo concluye su segunda visita oficial a Taiw\u00e1n. El primero hab\u00eda sido hace cuatro a\u00f1os, ocasi\u00f3n en la que, al igual que \u00e9sta, renov\u00f3 los lazos de amistad y ratific\u00f3 los hist\u00f3ricos lazos que los mantiene unidos desde hace m\u00e1s de seis d\u00e9cadas.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Con informaci\u00f3n de El Trueno<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ocasi\u00f3n, el mandatario paraguayo se interioriz\u00f3 sobre la poderosa estructura militar que posee la isla, compuesto por un complejo de t\u00faneles subterr\u00e1neos altamente fortificados, ubicado en el condado de Hualien, en la costa este de Taiw\u00e1n. La presidenta taiwanesa se pronunci\u00f3 a trav\u00e9s su cuenta oficial en Twitter sobre el recorrido que realiz\u00f3 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[34],"tags":[831,197,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-9922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-mario-abdo","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En la ocasi\u00f3n, el mandatario paraguayo se interioriz\u00f3 sobre la poderosa estructura militar que posee la isla, compuesto por un complejo de t\u00faneles subterr\u00e1neos altamente fortificados, ubicado en el condado de Hualien, en la costa este de Taiw\u00e1n. La presidenta taiwanesa se pronunci\u00f3 a trav\u00e9s su cuenta oficial en Twitter sobre el recorrido que realiz\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-17T18:04:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"559\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen\",\"datePublished\":\"2023-02-17T18:04:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/\"},\"wordCount\":274,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1\",\"keywords\":[\"destacada\",\"mario abdo\",\"taiwan\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/\",\"name\":\"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1\",\"datePublished\":\"2023-02-17T18:04:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1\",\"width\":1024,\"height\":559},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/17\\\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/","og_locale":"es_ES","og_type":"article","og_title":"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En la ocasi\u00f3n, el mandatario paraguayo se interioriz\u00f3 sobre la poderosa estructura militar que posee la isla, compuesto por un complejo de t\u00faneles subterr\u00e1neos altamente fortificados, ubicado en el condado de Hualien, en la costa este de Taiw\u00e1n. La presidenta taiwanesa se pronunci\u00f3 a trav\u00e9s su cuenta oficial en Twitter sobre el recorrido que realiz\u00f3 [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-02-17T18:04:18+00:00","og_image":[{"width":1024,"height":559,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen","datePublished":"2023-02-17T18:04:18+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/"},"wordCount":274,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1","keywords":["destacada","mario abdo","taiwan"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/","url":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/","name":"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1","datePublished":"2023-02-17T18:04:18+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1","width":1024,"height":559},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/17\/mario-abdo-benitez-presencio-capacidades-militares-de-taiwan-al-visitar-base-area-con-tsai-ing-wen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Mario Abdo Ben\u00edtez presenci\u00f3 capacidades militares de Taiw\u00e1n al visitar base \u00e1rea con Tsai Ing-wen"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/abdo-base-militar-taiwan.jpeg?fit=1024%2C559&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=9922"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/9923"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=9922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=9922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=9922"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=9922"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=9922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}