{"id":9822,"date":"2023-02-08T09:54:00","date_gmt":"2023-02-08T08:54:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/"},"modified":"2023-02-08T09:54:00","modified_gmt":"2023-02-08T08:54:00","slug":"comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/","title":{"rendered":"Comunidad IPy: \u00abQue da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\u00bb"},"content":{"rendered":"\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Por Alfredo Causarano<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Todas las opciones electorales en donde se enfrentaban modelos, ideas y proyectos distintos dentro del Partido han sido sometidas a la consideraci\u00f3n del Pueblo Colorado en diciembre \u00faltimo.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El Pueblo colorado ha hablado, ha decidido, ha dado su veredicto, ha sentenciado que sean Santiago Pe\u00f1a y Pedro Alliana los candidatos oficiales para las elecciones generales, y eso hay que respetar. Ha decidido que el nuevo presidente de la Junta de Gobierno sea Horacio Cartes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Pueblo Colorado ha dicho no a la opci\u00f3n presentada por Marito y su movimiento.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Eso hay que respetar, la lealtad al Partido a al Paraguay lo merecen. El mandato del electorado republicano ha sido someter a la voluntad del pueblo paraguayo la figura de Santi Pe\u00f1a para presidente del Paraguay.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Hoy, a trav\u00e9s de conductas ambiguas, se\u00f1ales contradictorias y comportamientos dudosos por parte del presidente de la Rep\u00fablica, se pretende confundir al pueblo colorado y paraguayo sobre la unidad necesaria para la victoria en abril pr\u00f3ximo.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El derrotado busca v\u00edas indirectas y subterfugios para desconocer la decisi\u00f3n del soberano. Como no lo puede hacer de frente, recurre a conductas que rayan la traici\u00f3n, pone freno al deseo genuino de la dirigencia de su movimiento de apoyar a la lista 1 y extorsiona en silencio las intenciones de lograr la unidad total del coloradismo.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Pero el pueblo se est\u00e1 uniendo en las bases, las dirigencias locales y regionales trabajan unidas en pos de la victoria colorada, las seccionales coloradas empiezan a sentir el fervor de que todos somos 1, al contrario del deseo de una c\u00fapula resentida por la derrota, de ver a su contrincante ocasional tropezar con el fracaso.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">No miran m\u00e1s all\u00e1 del arbusto, no ven el bosque, es m\u00e1s, se enredan con las espinosas ramas de la maleza que los dejar\u00e1n atrapados en el ignominioso hoyo de la traici\u00f3n de donde nunca m\u00e1s saldr\u00e1n si persisten en tan miserable encomienda.<\/p>\n\n\n\n<h6 class=\"has-text-align-justify has-small-font-size wp-block-heading\">Comunidad IPy es un espacio donde nuestros lectores tienen la libertad de expresarse, siempre respetando las normas b\u00e1sicas de urbanidad.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Por Alfredo Causarano Todas las opciones electorales en donde se enfrentaban modelos, ideas y proyectos distintos dentro del Partido han sido sometidas a la consideraci\u00f3n del Pueblo Colorado en diciembre \u00faltimo. El Pueblo colorado ha hablado, ha decidido, ha dado su veredicto, ha sentenciado que sean Santiago Pe\u00f1a y Pedro Alliana los candidatos oficiales para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[138,831,1394,197,286],"jnews-series":[],"ppma_author":[830],"class_list":["post-9822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-anr","tag-destacada","tag-elecciones-2023","tag-mario-abdo","tag-partido-colorado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunidad IPy: &quot;Que da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado&quot; - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidad IPy: &quot;Que da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado&quot; - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Por Alfredo Causarano Todas las opciones electorales en donde se enfrentaban modelos, ideas y proyectos distintos dentro del Partido han sido sometidas a la consideraci\u00f3n del Pueblo Colorado en diciembre \u00faltimo. El Pueblo colorado ha hablado, ha decidido, ha dado su veredicto, ha sentenciado que sean Santiago Pe\u00f1a y Pedro Alliana los candidatos oficiales para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-08T08:54:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Comunidad IPy: \u00abQue da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\u00bb\",\"datePublished\":\"2023-02-08T08:54:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/\"},\"wordCount\":369,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"anr\",\"destacada\",\"elecciones 2023\",\"mario abdo\",\"partido colorado\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/\",\"name\":\"Comunidad IPy: \\\"Que da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\\\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2023-02-08T08:54:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/02\\\/08\\\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidad IPy: \u00abQue da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunidad IPy: \"Que da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/","og_locale":"es_ES","og_type":"article","og_title":"Comunidad IPy: \"Que da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Por Alfredo Causarano Todas las opciones electorales en donde se enfrentaban modelos, ideas y proyectos distintos dentro del Partido han sido sometidas a la consideraci\u00f3n del Pueblo Colorado en diciembre \u00faltimo. El Pueblo colorado ha hablado, ha decidido, ha dado su veredicto, ha sentenciado que sean Santiago Pe\u00f1a y Pedro Alliana los candidatos oficiales para [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-02-08T08:54:00+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Comunidad IPy: \u00abQue da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\u00bb","datePublished":"2023-02-08T08:54:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/"},"wordCount":369,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1","keywords":["anr","destacada","elecciones 2023","mario abdo","partido colorado"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/","url":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/","name":"Comunidad IPy: \"Que da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1","datePublished":"2023-02-08T08:54:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1","width":760,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/02\/08\/comunidad-ipy-que-dano-le-esta-haciendo-marito-al-partido-colorado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Comunidad IPy: \u00abQue da\u00f1o le est\u00e1 haciendo Marito al Partido Colorado\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/mario-abdo-anr.jpg?fit=760%2C420&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=9822"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/9823"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=9822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=9822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=9822"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=9822"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=9822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}