{"id":9455,"date":"2022-12-28T15:21:40","date_gmt":"2022-12-28T14:21:40","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/"},"modified":"2022-12-28T15:21:40","modified_gmt":"2022-12-28T14:21:40","slug":"inauguran-el-paso-en-desnivel-de-3-bocas","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/","title":{"rendered":"Inauguran el paso bajo nivel de \u00ab3 bocas\u00bb"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">En la ma\u00f1ana de hoy fue inaugurado el paso bajo nivel en \u00ab3 Bocas\u00bb. El proyecto era conocido como <strong>\u201cMejoramiento de la Intersecci\u00f3n de las Avenidas Am\u00e9rico Picco, Acceso Sur y Avelino Mart\u00ednez\u201d (Tres Bocas)<\/strong>, y se llev\u00f3 adelante por el Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC), con la colaboraci\u00f3n de la Rep\u00fablica de China (Taiw\u00e1n).<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El nuevo paso qued\u00f3 habilitado parcialmente al tr\u00e1nsito vehicular desde el mediod\u00eda de hoy mi\u00e9rcoles 28 de diciembre.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Ya habilitado el paso, en forma paralela, el Ministerio de Obras P\u00fablicas continuar\u00e1 trabajando en el reacondicionamiento de las redes de servicios, drenajes y dem\u00e1s obras complementarias.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El t\u00fanel tiene 600 metros de longitud y es un tramo estrat\u00e9gico para miles de personas que diariamente se movilizan desde y hacia la capital del pa\u00eds, beneficiando a las ciudades de \u00d1emby, Fernando de la Mora, San Lorenzo y Villa Elisa.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana de hoy fue inaugurado el paso bajo nivel en \u00ab3 Bocas\u00bb. El proyecto era conocido como \u201cMejoramiento de la Intersecci\u00f3n de las Avenidas Am\u00e9rico Picco, Acceso Sur y Avelino Mart\u00ednez\u201d (Tres Bocas), y se llev\u00f3 adelante por el Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC), con la colaboraci\u00f3n de la Rep\u00fablica de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9456,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[34],"tags":[831,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-9455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inauguran el paso bajo nivel de &quot;3 bocas&quot; - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguran el paso bajo nivel de &quot;3 bocas&quot; - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En la ma\u00f1ana de hoy fue inaugurado el paso bajo nivel en \u00ab3 Bocas\u00bb. El proyecto era conocido como \u201cMejoramiento de la Intersecci\u00f3n de las Avenidas Am\u00e9rico Picco, Acceso Sur y Avelino Mart\u00ednez\u201d (Tres Bocas), y se llev\u00f3 adelante por el Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC), con la colaboraci\u00f3n de la Rep\u00fablica de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T14:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/3bocas.jpg?fit=1620%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Inauguran el paso bajo nivel de \u00ab3 bocas\u00bb\",\"datePublished\":\"2022-12-28T14:21:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/\"},\"wordCount\":165,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/3bocas.jpg?fit=1620%2C1080&ssl=1\",\"keywords\":[\"destacada\",\"taiwan\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/\",\"name\":\"Inauguran el paso bajo nivel de \\\"3 bocas\\\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/3bocas.jpg?fit=1620%2C1080&ssl=1\",\"datePublished\":\"2022-12-28T14:21:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/3bocas.jpg?fit=1620%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/3bocas.jpg?fit=1620%2C1080&ssl=1\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/28\\\/inauguran-el-paso-en-desnivel-de-3-bocas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inauguran el paso bajo nivel de \u00ab3 bocas\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inauguran el paso bajo nivel de \"3 bocas\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/","og_locale":"es_ES","og_type":"article","og_title":"Inauguran el paso bajo nivel de \"3 bocas\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En la ma\u00f1ana de hoy fue inaugurado el paso bajo nivel en \u00ab3 Bocas\u00bb. El proyecto era conocido como \u201cMejoramiento de la Intersecci\u00f3n de las Avenidas Am\u00e9rico Picco, Acceso Sur y Avelino Mart\u00ednez\u201d (Tres Bocas), y se llev\u00f3 adelante por el Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC), con la colaboraci\u00f3n de la Rep\u00fablica de [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-12-28T14:21:40+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/3bocas.jpg?fit=1620%2C1080&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Inauguran el paso bajo nivel de \u00ab3 bocas\u00bb","datePublished":"2022-12-28T14:21:40+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/"},"wordCount":165,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/3bocas.jpg?fit=1620%2C1080&ssl=1","keywords":["destacada","taiwan"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/","url":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/","name":"Inauguran el paso bajo nivel de \"3 bocas\" - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/3bocas.jpg?fit=1620%2C1080&ssl=1","datePublished":"2022-12-28T14:21:40+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/3bocas.jpg?fit=1620%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/3bocas.jpg?fit=1620%2C1080&ssl=1","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/28\/inauguran-el-paso-en-desnivel-de-3-bocas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Inauguran el paso bajo nivel de \u00ab3 bocas\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/3bocas.jpg?fit=1620%2C1080&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=9455"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/9456"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=9455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=9455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=9455"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=9455"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=9455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}