{"id":9254,"date":"2022-12-06T11:34:06","date_gmt":"2022-12-06T10:34:06","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/"},"modified":"2022-12-06T11:34:06","modified_gmt":"2022-12-06T10:34:06","slug":"el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/","title":{"rendered":"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Con casi 200 establecimientos de salud incorporados, el Sistema HIS contin\u00faa avanzando en la facilitaci\u00f3n de toda la gesti\u00f3n administrativa y la atenci\u00f3n de los pacientes.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Entre otros beneficios para los pacientes, se destacan menor tiempo de espera para la consulta y m\u00e1s tiempo de calidad en la consulta con el m\u00e9dico, entre otros.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Entre los \u00faltimos establecimientos incorporados, se encuentra el Hospital de la ciudad de Villa Elisa. Su directora, la Dra. Yohana Ben\u00edtez, destac\u00f3 la reducci\u00f3n de papeles y control de stock en farmacia, lo cual facilita la planificaci\u00f3n y solicitud de insumos, entre otros beneficios del HIS en su establecimiento.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud835\udc68\ud835\udc97\ud835\udc82\ud835\udc8f\ud835\udc84\ud835\udc86\ud835\udc94 \ud835\udc6f\ud835\udc70\ud835\udc7a \ud83c\uddf5\ud83c\uddfe\ud83c\uddf9\ud83c\uddfc  <br>La Dra. Yohana Ben\u00edtez, Directora del Hospital de Villa Elisa destaca la reducci\u00f3n de papeles y control de stock en farmacia, lo cual facilita la planificaci\u00f3n y solicitud de insumos, entre otros beneficios del HIS en su establecimiento. <a href=\"https:\/\/t.co\/3Xq1tunQv6\">pic.twitter.com\/3Xq1tunQv6<\/a><\/p>&mdash; Proyecto HIS (@HIS_Paraguay) <a href=\"https:\/\/twitter.com\/HIS_Paraguay\/status\/1599872759500537856?ref_src=twsrc%5Etfw\">December 5, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Este proceso de transformaci\u00f3n digital es encarado en forma conjunta entre el\u00a0<strong>Ministerio de Salud P\u00fablica y Bienestar Social (MSPyBS) y el gobierno de la Rep\u00fablica de China (Taiw\u00e1n), a trav\u00e9s del Proyecto para la \u201cMejora de la Eficiencia en la Gesti\u00f3n de la Inform\u00e1tica en Salud\u201d y cuenta con el apoyo del Ministerio de Tecnolog\u00edas de la Informaci\u00f3n y Comunicaci\u00f3n (MITIC), KOICA, Itaip\u00fa y el BID.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con casi 200 establecimientos de salud incorporados, el Sistema HIS contin\u00faa avanzando en la facilitaci\u00f3n de toda la gesti\u00f3n administrativa y la atenci\u00f3n de los pacientes. Entre otros beneficios para los pacientes, se destacan menor tiempo de espera para la consulta y m\u00e1s tiempo de calidad en la consulta con el m\u00e9dico, entre otros. Entre [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2915,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[36],"tags":[831,178,619,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-9254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-destacada","tag-ministerio-de-salud","tag-mitic","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Con casi 200 establecimientos de salud incorporados, el Sistema HIS contin\u00faa avanzando en la facilitaci\u00f3n de toda la gesti\u00f3n administrativa y la atenci\u00f3n de los pacientes. Entre otros beneficios para los pacientes, se destacan menor tiempo de espera para la consulta y m\u00e1s tiempo de calidad en la consulta con el m\u00e9dico, entre otros. Entre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-06T10:34:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando\",\"datePublished\":\"2022-12-06T10:34:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/\"},\"wordCount\":206,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"keywords\":[\"destacada\",\"ministerio de salud\",\"mitic\",\"taiwan\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/\",\"name\":\"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"datePublished\":\"2022-12-06T10:34:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"width\":1201,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/06\\\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/","og_locale":"es_ES","og_type":"article","og_title":"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Con casi 200 establecimientos de salud incorporados, el Sistema HIS contin\u00faa avanzando en la facilitaci\u00f3n de toda la gesti\u00f3n administrativa y la atenci\u00f3n de los pacientes. Entre otros beneficios para los pacientes, se destacan menor tiempo de espera para la consulta y m\u00e1s tiempo de calidad en la consulta con el m\u00e9dico, entre otros. Entre [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-12-06T10:34:06+00:00","og_image":[{"width":1201,"height":676,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando","datePublished":"2022-12-06T10:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/"},"wordCount":206,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","keywords":["destacada","ministerio de salud","mitic","taiwan"],"articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/","url":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/","name":"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","datePublished":"2022-12-06T10:34:06+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","width":1201,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/06\/el-sistema-his-sistema-de-informacion-de-salud-continua-avanzando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"El sistema HIS (Sistema de Informaci\u00f3n de salud) contin\u00faa avanzando"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=9254"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/2915"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=9254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=9254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=9254"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=9254"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=9254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}