{"id":9229,"date":"2022-12-04T10:50:00","date_gmt":"2022-12-04T09:50:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/"},"modified":"2022-12-04T10:50:00","modified_gmt":"2022-12-04T09:50:00","slug":"bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/","title":{"rendered":"Bolivia no es una democracia en crisis, es un Estado fallido"},"content":{"rendered":"\n<p class=\"has-text-align-justify\"><strong>Bruno Fornillo<\/strong>, uno de los tantos aduladores de <strong>Evo Morales<\/strong>, en su libro: <em>Debatir Bolivia, <\/em>relata que durante los a\u00f1os 90 se fundaron m\u00e1s de 450 ONGS en el pa\u00eds. Muchas de estas instituciones, por no decir todas, estaban imbuidas por corrientes de izquierda. Sus objetos de investigaci\u00f3n eran el indigenismo, el feminismo, el ecologismo y la defensa de la hoja de coca. Pero en honor a la verdad, todas eran simples fachadas para su verdadero objetivo: <em>Desestabilizar la democracia boliviana desde adentro.<\/em> <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Las ONGS, junto con la \u00abDiplomacia de los pueblos\u00bb de <strong>Hugo Ch\u00e1vez<\/strong>, fueron una invasi\u00f3n tipo <em>proxie<\/em>. Es decir, la agresi\u00f3n a la seguridad nacional por parte de otro Estado usando m\u00e9todos no militares. La ventaja de esta modalidad de ataque es su capacidad de pasar desapercibida. Pues nadie pensar\u00eda mal de una instituci\u00f3n que busca, por ejemplo, promover reivindicaciones de los pueblos ind\u00edgenas y productores de coca.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Como podemos apreciar, la lucha entre los cocaleros y el Estado Boliviano fue artificialmente ideologizada por activistas de Derechos Humanos, <strong>Sancha llorenti<\/strong>, entre ellos, operadores medi\u00e1ticos, <strong>Amalia Pando<\/strong> y <strong>Carlos Mesa<\/strong>, por citar un par de casos, y agitadores extranjeros, <strong>Kathryn Ledebur<\/strong>, por ejemplo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/vir-banner.png?resize=547%2C130&#038;ssl=1\" alt=\"\" class=\"wp-image-10087\" width=\"547\" height=\"130\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Las ONGS tambi\u00e9n estuvieron detr\u00e1s de los procesos subversivos que sufri\u00f3 Bolivia los primeros a\u00f1os del siglo 21. Pero fue con el derrocamiento del presidente <strong>Gonzalo S\u00e1nchez de Lozada<\/strong>, 17 de octubre 2003, que culminaron su plan.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La gesti\u00f3n de <strong>Carlos Mesa <\/strong>(2003 \u2013 2005) fue un intento de cogobierno con <strong>Evo Morales<\/strong>. Pero el cocalero, despu\u00e9s de haber conseguido la convocatoria a una Asamblea Constituyente, le baj\u00f3 el pulgar al historiador. El traidor hab\u00eda sido traicionado.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La elecci\u00f3n del 2005 y la convocatoria a la constituyente del 2006 dinamitaron las bases de la institucionalidad democr\u00e1tica, y nos condujeron a convertirnos en un Estado fallido.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El Dr. <strong>Steven Metz<\/strong> y el Teniente Coronel <strong>Raymond Millen<\/strong>, en su ensayo: <em>La relaci\u00f3n entre la insurgencia y las pandillas<\/em>, definen un Estado fallido como:<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Un Estado fallido es un gobierno que se ha vuelto incapaz de proporcionar las funciones y responsabilidades b\u00e1sicas de una naci\u00f3n soberana, como la defensa militar, la aplicaci\u00f3n de la ley, la justicia, la educaci\u00f3n o la estabilidad econ\u00f3mica. Las caracter\u00edsticas comunes de los Estados fallidos incluyen la violencia civil, la corrupci\u00f3n, el crimen, la pobreza, el analfabetismo y la infraestructura en ruinas.<\/p><\/blockquote><\/figure>\n\n\n\n<p>\u00bfPodemos aplicar esta definici\u00f3n a Bolivia?<\/p>\n\n\n\n<p>Claro que s\u00ed. Veamos las razones.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El a\u00f1o 2015, la empresa estadounidense Bloomberg \u2015con datos proporcionados por el Banco Mundial y la OMS\u2015 elabor\u00f3 un informe sobre los sistemas de salud de 108 naciones del mundo. \u00bfQu\u00e9 creen? Pues que ocupamos el \u00faltimo lugar a nivel Sudam\u00e9rica.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">De igual manera, la OMS determin\u00f3 que Bolivia ocupa el primer lugar en muertes por C\u00e1ncer en Cuello Uterino y el segundo lugar con mayor \u00edndice de mortalidad por C\u00e1ncer en Am\u00e9rica del Sur.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En el <em>Tercer Estudio Regional Comparativo y Explicativo (Terce)<\/em> Bolivia ocupa uno de los \u00faltimos lugares en desempe\u00f1o educativo. Lenguaje y ciencias naturales son las materias en las cuales los estudiantes bolivianos de primaria tienen los peores desempe\u00f1os.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En cuanto al \u00e1lgido tema de la justicia, la Organizaci\u00f3n para la transparencia Internacional, en su <em>\u00edndice de percepci\u00f3n de la corrupci\u00f3n 2021, <\/em>muestra que los ciudadanos bolivianos ven a la justicia como uno de los sectores m\u00e1s corruptos del pa\u00eds.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/balderrama-zermat.png?resize=489%2C135&#038;ssl=1\" alt=\"\" class=\"wp-image-10351\" width=\"489\" height=\"135\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Adem\u00e1s, Global Human Rights Leage certifica 164 presos pol\u00edticos en Bolivia y la existencia de m\u00e1s de 8000 bolivianos solicitando asilo o refugio. Todo debido a la situaci\u00f3n de indefensi\u00f3n en la que se encuentran los opositores al r\u00e9gimen.<\/p>\n\n\n\n<p>\u00bfY la econom\u00eda de la que tanto presumen <strong>Arce Catacora <\/strong>y sus ministros?<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Ya nadie, con excepci\u00f3n de los militantes m\u00e1s fan\u00e1ticos de la pandilla azul, cree que Bolivia sea un oasis econ\u00f3mico. Sucede que a partir de la ca\u00edda del precio de las materias primas en 2014 no se recort\u00f3 el gasto p\u00fablico, que hubiese sido ideal, sino que se intent\u00f3 solventar el modelo por medio del incremento de la deuda p\u00fablica. Pero hoy, ni eso ya est\u00e1 funcionando.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La tendencia decreciente de la Reservas Internacionales nos muestra una muy baja capacidad exportadora. Pero tambi\u00e9n un nivel tan bajo de divisas incrementa la presi\u00f3n sobre el tipo de cambio. Es decir, que la estabilidad econ\u00f3mica del pa\u00eds depende de un pilar cada vez m\u00e1s dinamitado por el propio gobierno.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">A modo de cierre, La Carta Democr\u00e1tica Interamericana establece que una democracia saludable debe contener los siguientes elementos: 1) Respeto a los derechos humanos y las libertades fundamentales; 2) Acceso al poder y su ejercicio con sujeci\u00f3n al Estado de Derecho; 3) La celebraci\u00f3n de elecciones peri\u00f3dicas, libres, justas y basadas en el sufragio universal y secreto como expresi\u00f3n de la soberan\u00eda del pueblo; 4) El r\u00e9gimen plural de partidos y organizaciones pol\u00edticas; 5) La separaci\u00f3n e independencia de los poderes p\u00fablicos. Ninguno de esos elementos est\u00e1 presente en el pa\u00eds. Bolivia no es una democracia en crisis, es un Estado fallido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruno Fornillo, uno de los tantos aduladores de Evo Morales, en su libro: Debatir Bolivia, relata que durante los a\u00f1os 90 se fundaron m\u00e1s de 450 ONGS en el pa\u00eds. Muchas de estas instituciones, por no decir todas, estaban imbuidas por corrientes de izquierda. Sus objetos de investigaci\u00f3n eran el indigenismo, el feminismo, el ecologismo [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":4871,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[39],"tags":[577,831],"jnews-series":[],"ppma_author":[1371],"class_list":["post-9229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-bolivia","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolivia no es una democracia en crisis, es un Estado fallido - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia no es una democracia en crisis, es un Estado fallido - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Bruno Fornillo, uno de los tantos aduladores de Evo Morales, en su libro: Debatir Bolivia, relata que durante los a\u00f1os 90 se fundaron m\u00e1s de 450 ONGS en el pa\u00eds. Muchas de estas instituciones, por no decir todas, estaban imbuidas por corrientes de izquierda. Sus objetos de investigaci\u00f3n eran el indigenismo, el feminismo, el ecologismo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-04T09:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hugo Marcelo Balderrama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hugobalderrama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hugo Marcelo Balderrama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/\"},\"author\":{\"name\":\"Hugo Marcelo Balderrama\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\"},\"headline\":\"Bolivia no es una democracia en crisis, es un Estado fallido\",\"datePublished\":\"2022-12-04T09:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/\"},\"wordCount\":889,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"keywords\":[\"Bolivia\",\"destacada\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/\",\"name\":\"Bolivia no es una democracia en crisis, es un Estado fallido - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"datePublished\":\"2022-12-04T09:50:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"width\":1280,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/04\\\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolivia no es una democracia en crisis, es un Estado fallido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\",\"name\":\"Hugo Marcelo Balderrama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"caption\":\"Hugo Marcelo Balderrama\"},\"description\":\"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hugobalderrama\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/hbalderrama\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolivia no es una democracia en crisis, es un Estado fallido - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/","og_locale":"es_ES","og_type":"article","og_title":"Bolivia no es una democracia en crisis, es un Estado fallido - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Bruno Fornillo, uno de los tantos aduladores de Evo Morales, en su libro: Debatir Bolivia, relata que durante los a\u00f1os 90 se fundaron m\u00e1s de 450 ONGS en el pa\u00eds. Muchas de estas instituciones, por no decir todas, estaban imbuidas por corrientes de izquierda. Sus objetos de investigaci\u00f3n eran el indigenismo, el feminismo, el ecologismo [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2022-12-04T09:50:00+00:00","og_image":[{"width":1280,"height":700,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","type":"image\/jpeg"}],"author":"Hugo Marcelo Balderrama","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hugobalderrama","twitter_misc":{"Escrito por":"Hugo Marcelo Balderrama","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/"},"author":{"name":"Hugo Marcelo Balderrama","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde"},"headline":"Bolivia no es una democracia en crisis, es un Estado fallido","datePublished":"2022-12-04T09:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/"},"wordCount":889,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","keywords":["Bolivia","destacada"],"articleSection":["Analisis"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/","url":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/","name":"Bolivia no es una democracia en crisis, es un Estado fallido - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","datePublished":"2022-12-04T09:50:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","width":1280,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/04\/bolivia-no-es-una-democracia-en-crisis-es-un-estado-fallido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Bolivia no es una democracia en crisis, es un Estado fallido"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde","name":"Hugo Marcelo Balderrama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","caption":"Hugo Marcelo Balderrama"},"description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hugobalderrama"],"url":"https:\/\/informatepy.com\/2024\/author\/hbalderrama\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1371,"user_id":31,"is_guest":0,"slug":"hbalderrama","display_name":"Hugo Marcelo Balderrama","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg"},"author_category":"1","first_name":"Hugo Marcelo","last_name":"Balderrama","user_url":"","job_title":"","description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad."}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=9229"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/4871"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=9229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=9229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=9229"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=9229"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=9229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}