{"id":9207,"date":"2022-12-02T11:00:00","date_gmt":"2022-12-02T10:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/"},"modified":"2022-12-02T11:00:00","modified_gmt":"2022-12-02T10:00:00","slug":"fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/","title":{"rendered":"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">En la ma\u00f1ana del jueves, en el palacio Benigno L\u00f3pez, sede de la Canciller\u00eda Nacional, se llev\u00f3 a cabo la firma del acta de recepci\u00f3n del segundo desembolso, para el financiamiento del proyecto <strong>\u201cImplementaci\u00f3n y equipamiento de Bibliotecas P\u00fablicas en territorios con mayor \u00edndice de pobreza a nivel nacional, para el fortalecimiento de la Red Nacional de Bibliotecas P\u00fablicas\u201d<\/strong>, que lleva adelante la <strong>Secretar\u00eda Nacional de Cultura (SNC)<\/strong>, con la cooperaci\u00f3n de la <strong>Rep\u00fablica de China (Taiw\u00e1n).<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">El acta fue firmada por el ministro de Cultura, Rub\u00e9n Capdevila; el embajador de Taiw\u00e1n en nuestro pa\u00eds, Jos\u00e9 Chih-Cheng Han y, en car\u00e1cter de testigo de honor, el canciller nacional, Julio C\u00e9sar Arriola.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Por su parte, el embajador de la Rep\u00fablica de China (Taiw\u00e1n), Jos\u00e9 HAN, valor\u00f3 el avance del proyecto, que tiene prevista la inauguraci\u00f3n de 20 bibliotecas p\u00fablicas en total, con miras a fomentar el libro y promover la lectura: <strong><em>\u00abformalizamos el segundo desembolso para el Proyecto de Implementaci\u00f3n y Equipamiento de Bibliotecas P\u00fablicas en Territorios con Mayor \u00cdndice de Pobreza a Nivel Nacional, cooperaci\u00f3n conjunta que contempla el fortalecimiento de la Red Nacional de Bibliotecas P\u00fablicas, para el fomento del libro y la lectura, especialmente en zonas con mayores indicadores de vulnerabilidad social a nivel nacional, fomentando el conocimiento y la difusi\u00f3n de la cultura, con 20 bibliotecas que brindar\u00e1n acceso a todos los ciudadanos a la informaci\u00f3n y desarrollo cultural\u00bb<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana del jueves, en el palacio Benigno L\u00f3pez, sede de la Canciller\u00eda Nacional, se llev\u00f3 a cabo la firma del acta de recepci\u00f3n del segundo desembolso, para el financiamiento del proyecto \u201cImplementaci\u00f3n y equipamiento de Bibliotecas P\u00fablicas en territorios con mayor \u00edndice de pobreza a nivel nacional, para el fortalecimiento de la Red [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9208,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[43],"tags":[831,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-9207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-destacada","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En la ma\u00f1ana del jueves, en el palacio Benigno L\u00f3pez, sede de la Canciller\u00eda Nacional, se llev\u00f3 a cabo la firma del acta de recepci\u00f3n del segundo desembolso, para el financiamiento del proyecto \u201cImplementaci\u00f3n y equipamiento de Bibliotecas P\u00fablicas en territorios con mayor \u00edndice de pobreza a nivel nacional, para el fortalecimiento de la Red [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-02T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"871\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso\",\"datePublished\":\"2022-12-02T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/\"},\"wordCount\":280,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1\",\"keywords\":[\"destacada\",\"taiwan\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/\",\"name\":\"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1\",\"datePublished\":\"2022-12-02T10:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1\",\"width\":1280,\"height\":871},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/12\\\/02\\\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/","og_locale":"es_ES","og_type":"article","og_title":"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En la ma\u00f1ana del jueves, en el palacio Benigno L\u00f3pez, sede de la Canciller\u00eda Nacional, se llev\u00f3 a cabo la firma del acta de recepci\u00f3n del segundo desembolso, para el financiamiento del proyecto \u201cImplementaci\u00f3n y equipamiento de Bibliotecas P\u00fablicas en territorios con mayor \u00edndice de pobreza a nivel nacional, para el fortalecimiento de la Red [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-12-02T10:00:00+00:00","og_image":[{"width":1280,"height":871,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso","datePublished":"2022-12-02T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/"},"wordCount":280,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1","keywords":["destacada","taiwan"],"articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/","url":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/","name":"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1","datePublished":"2022-12-02T10:00:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1","width":1280,"height":871},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/12\/02\/fortalecimiento-de-la-red-de-bibliotecas-publicas-el-gobierno-de-la-republica-de-china-taiwan-hizo-entrega-del-segundo-desembolso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Fortalecimiento de la Red de Bibliotecas P\u00fablicas: el gobierno de la Rep\u00fablica de China (Taiw\u00e1n) hizo entrega del segundo desembolso"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/12\/Firma-desembolso-Taiwan-bibliotecas.jpeg?fit=1280%2C871&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=9207"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/9207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/9208"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=9207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=9207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=9207"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=9207"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=9207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}