{"id":8983,"date":"2022-11-09T13:22:47","date_gmt":"2022-11-09T12:22:47","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/"},"modified":"2022-11-09T13:22:47","modified_gmt":"2022-11-09T12:22:47","slug":"concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/","title":{"rendered":"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \u00abChe\u00bb Guevara"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Entrevistado por radio 1000, el concejal Jos\u00e9 Alvarenga convers\u00f3 sobre la existencia de una calle con el nombre de Ernesto \u201cChe\u201d Guevara en la ciudad de Asunci\u00f3n. Record\u00f3 que \u00e9l ya propuso cambiar dicha denominaci\u00f3n y reemplazarla por el nombre del suboficial boliviano que abati\u00f3 al guerrillero luego de ser atrapado a finales de los a\u00f1os 60 en Bolivia.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Alvarenga afirm\u00f3 que el guerrillero fallecido no es una figura que haya servido al pa\u00eds en ning\u00fan momento, por el contrario de otras figuras j\u00f3venes nacionales que se merecer\u00edan m\u00e1s una calle, y coment\u00f3 que socializar\u00e1 su proyecto con los vecinos del barrio Ita Enramada para que el tr\u00e1mite permita el cambio de nombre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevistado por radio 1000, el concejal Jos\u00e9 Alvarenga convers\u00f3 sobre la existencia de una calle con el nombre de Ernesto \u201cChe\u201d Guevara en la ciudad de Asunci\u00f3n. Record\u00f3 que \u00e9l ya propuso cambiar dicha denominaci\u00f3n y reemplazarla por el nombre del suboficial boliviano que abati\u00f3 al guerrillero luego de ser atrapado a finales de los [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6376,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[40],"tags":[425,831,1509,802],"jnews-series":[],"ppma_author":[830],"class_list":["post-8983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales","tag-asuncion","tag-destacada","tag-jose-alvarenga","tag-municipalidad-de-asuncion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto &quot;Che&quot; Guevara - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto &quot;Che&quot; Guevara - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Entrevistado por radio 1000, el concejal Jos\u00e9 Alvarenga convers\u00f3 sobre la existencia de una calle con el nombre de Ernesto \u201cChe\u201d Guevara en la ciudad de Asunci\u00f3n. Record\u00f3 que \u00e9l ya propuso cambiar dicha denominaci\u00f3n y reemplazarla por el nombre del suboficial boliviano que abati\u00f3 al guerrillero luego de ser atrapado a finales de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-09T12:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/03\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \u00abChe\u00bb Guevara\",\"datePublished\":\"2022-11-09T12:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/\"},\"wordCount\":140,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1\",\"keywords\":[\"asuncion\",\"destacada\",\"jose alvarenga\",\"municipalidad de asuncion\"],\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/\",\"name\":\"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \\\"Che\\\" Guevara - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1\",\"datePublished\":\"2022-11-09T12:22:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1\",\"width\":1000,\"height\":631},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/11\\\/09\\\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \u00abChe\u00bb Guevara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \"Che\" Guevara - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/","og_locale":"es_ES","og_type":"article","og_title":"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \"Che\" Guevara - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Entrevistado por radio 1000, el concejal Jos\u00e9 Alvarenga convers\u00f3 sobre la existencia de una calle con el nombre de Ernesto \u201cChe\u201d Guevara en la ciudad de Asunci\u00f3n. Record\u00f3 que \u00e9l ya propuso cambiar dicha denominaci\u00f3n y reemplazarla por el nombre del suboficial boliviano que abati\u00f3 al guerrillero luego de ser atrapado a finales de los [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-11-09T12:22:47+00:00","og_image":[{"width":1000,"height":631,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/03\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \u00abChe\u00bb Guevara","datePublished":"2022-11-09T12:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/"},"wordCount":140,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/03\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1","keywords":["asuncion","destacada","jose alvarenga","municipalidad de asuncion"],"articleSection":["Municipales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/","url":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/","name":"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \"Che\" Guevara - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/03\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1","datePublished":"2022-11-09T12:22:47+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/03\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/03\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1","width":1000,"height":631},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/11\/09\/concejal-alvarenga-insiste-en-su-pedido-para-cambiar-el-nombre-de-la-calle-identificada-con-el-asesino-ernesto-che-guevara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Concejal Alvarenga insiste en su pedido para cambiar el nombre de la calle identificada con el asesino Ernesto \u00abChe\u00bb Guevara"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/03\/El-Che-disparando.jpg?fit=1000%2C631&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/8983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=8983"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/8983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/6376"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=8983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=8983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=8983"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=8983"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=8983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}