{"id":8242,"date":"2022-09-15T11:22:57","date_gmt":"2022-09-15T09:22:57","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/"},"modified":"2022-09-15T11:22:57","modified_gmt":"2022-09-15T09:22:57","slug":"si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/","title":{"rendered":"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Los camioneros movilizados desde el lunes pasado exigiendo la reducci\u00f3n de los precios del combustible, <strong>amenazan con sitiar Asunci\u00f3n<\/strong> si el gobierno no les da una respuesta esta ma\u00f1ana.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Basilio Duarte<\/strong>, uno de los voceros del grupo, dijo que una vez m\u00e1s fueron enga\u00f1ados por el gobierno. El ministro del Interior, <strong>Federico Gonz\u00e1lez<\/strong>, se comprometi\u00f3 que a las 09.00 de ayer mi\u00e9rcoles dar\u00edan una respuesta oficial. Sin embargo, pas\u00f3 el d\u00eda y el referente del Ejecutivo volvi\u00f3 a pedir tiempo hasta este jueves.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong><em>\u201cEsperaremos hasta ma\u00f1ana solamente y si la respuesta del gobierno no es favorable a nuestro reclamo, vamos a sitiar Asunci\u00f3n. Ya estamos de acuerdo con todos los gremios, camioneros, grueros, volqueteros, est\u00e1n los conductores de plataformas, taxistas, la ciudadan\u00eda toda\u201d<\/em><\/strong>, dijo Duarte.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Por otro lado, el dirigente rechaz\u00f3 las declaraciones del ministro del Interior, quien dijo que la manifestaci\u00f3n tiene tinte pol\u00edtico. <strong><em>\u201cA ellos les digo que ac\u00e1 estamos gente trabajadora y gente que ya est\u00e1 pasando necesidad en sus casas\u201d<\/em><\/strong>, manifest\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Respecto a sitiar Asunci\u00f3n, remarc\u00f3 que ser\u00e1 en bloques, <em><strong>\u201cas\u00ed como todas las decisiones que estamos tomando los m\u00e1s de 20 gremios que estamos involucrados en esta movilizaci\u00f3n\u201d.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los camioneros movilizados desde el lunes pasado exigiendo la reducci\u00f3n de los precios del combustible, amenazan con sitiar Asunci\u00f3n si el gobierno no les da una respuesta esta ma\u00f1ana. Basilio Duarte, uno de los voceros del grupo, dijo que una vez m\u00e1s fueron enga\u00f1ados por el gobierno. El ministro del Interior, Federico Gonz\u00e1lez, se comprometi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6848,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[1409,1448,831,1529,1131],"jnews-series":[],"ppma_author":[830],"class_list":["post-8242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-combustible","tag-combustibles","tag-destacada","tag-federico-gonzalez","tag-gremio-de-camioneros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Los camioneros movilizados desde el lunes pasado exigiendo la reducci\u00f3n de los precios del combustible, amenazan con sitiar Asunci\u00f3n si el gobierno no les da una respuesta esta ma\u00f1ana. Basilio Duarte, uno de los voceros del grupo, dijo que una vez m\u00e1s fueron enga\u00f1ados por el gobierno. El ministro del Interior, Federico Gonz\u00e1lez, se comprometi\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T09:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n\",\"datePublished\":\"2022-09-15T09:22:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/\"},\"wordCount\":221,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1\",\"keywords\":[\"combustible\",\"combustibles\",\"destacada\",\"federico gonzalez\",\"gremio de camioneros\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/\",\"name\":\"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1\",\"datePublished\":\"2022-09-15T09:22:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/09\\\/15\\\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/","og_locale":"es_ES","og_type":"article","og_title":"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Los camioneros movilizados desde el lunes pasado exigiendo la reducci\u00f3n de los precios del combustible, amenazan con sitiar Asunci\u00f3n si el gobierno no les da una respuesta esta ma\u00f1ana. Basilio Duarte, uno de los voceros del grupo, dijo que una vez m\u00e1s fueron enga\u00f1ados por el gobierno. El ministro del Interior, Federico Gonz\u00e1lez, se comprometi\u00f3 [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-09-15T09:22:57+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n","datePublished":"2022-09-15T09:22:57+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/"},"wordCount":221,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1","keywords":["combustible","combustibles","destacada","federico gonzalez","gremio de camioneros"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/","url":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/","name":"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1","datePublished":"2022-09-15T09:22:57+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/09\/15\/si-no-reciben-una-respuesta-favorable-hoy-camioneros-sitiaran-asuncion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Si no reciben una respuesta favorable hoy, camioneros sitiar\u00e1n Asunci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1920%2C1080&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/8242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=8242"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/8242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/6848"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=8242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=8242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=8242"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=8242"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=8242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}