{"id":8044,"date":"2022-08-23T21:46:34","date_gmt":"2022-08-23T19:46:34","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/"},"modified":"2022-08-23T21:46:34","modified_gmt":"2022-08-23T19:46:34","slug":"lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/","title":{"rendered":"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">En un evento de campa\u00f1a realizado el pasado s\u00e1bado 20, en Vale do Anhangaba\u00fa, S\u00e3o Paulo, el ex presidente&nbsp;<strong>Lula da Silva hizo una declaraci\u00f3n extremadamente pol\u00e9mica en favor de la violencia dom\u00e9stica<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Al hablar de la violencia contra la mujer, uno de los puntos m\u00e1s importantes de su nueva agenda progresista, en un momento se le escap\u00f3 una frase que le vali\u00f3 el repudio hasta de sus simpatizantes: \u201c<strong>Si quieres pegarle a una mujer, ve a pegarle a otro lugar, pero no dentro de tu casa<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Seg\u00fan su equipo de campa\u00f1a,\u00a0<strong>el candidato cometi\u00f3 un \u201cerror\u201d y en vez de \u201ccasa\u201d quiso decir \u201cBrasil\u201d<\/strong>, una explicaci\u00f3n que no dej\u00f3 satisfecho a nadie, ya que tampoco explica por qu\u00e9 dijo \u201c<strong>ve a pegarle a otro lugar<\/strong>\u201d en vez de pedir que no haya violencia contra la mujer, como\u00a0<strong>Bolsonaro quien hace campa\u00f1a en favor de que las mujeres se armen y puedan defenderse de la violencia con m\u00f3tivo de g\u00e9nero<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/silvionavarro\/status\/1561328893524688897\n<\/div><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:300\">Con informaci\u00f3n de La Derecha Diario<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En un evento de campa\u00f1a realizado el pasado s\u00e1bado 20, en Vale do Anhangaba\u00fa, S\u00e3o Paulo, el ex presidente&nbsp;Lula da Silva hizo una declaraci\u00f3n extremadamente pol\u00e9mica en favor de la violencia dom\u00e9stica. Al hablar de la violencia contra la mujer, uno de los puntos m\u00e1s importantes de su nueva agenda progresista, en un momento se [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4772,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[33],"tags":[353,831,1319],"jnews-series":[],"ppma_author":[830],"class_list":["post-8044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-brasil","tag-destacada","tag-lula"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En un evento de campa\u00f1a realizado el pasado s\u00e1bado 20, en Vale do Anhangaba\u00fa, S\u00e3o Paulo, el ex presidente&nbsp;Lula da Silva hizo una declaraci\u00f3n extremadamente pol\u00e9mica en favor de la violencia dom\u00e9stica. Al hablar de la violencia contra la mujer, uno de los puntos m\u00e1s importantes de su nueva agenda progresista, en un momento se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-23T19:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d\",\"datePublished\":\"2022-08-23T19:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/\"},\"wordCount\":205,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1\",\"keywords\":[\"brasil\",\"destacada\",\"lula\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/\",\"name\":\"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1\",\"datePublished\":\"2022-08-23T19:46:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1\",\"width\":1024,\"height\":749},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/23\\\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/","og_locale":"es_ES","og_type":"article","og_title":"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En un evento de campa\u00f1a realizado el pasado s\u00e1bado 20, en Vale do Anhangaba\u00fa, S\u00e3o Paulo, el ex presidente&nbsp;Lula da Silva hizo una declaraci\u00f3n extremadamente pol\u00e9mica en favor de la violencia dom\u00e9stica. Al hablar de la violencia contra la mujer, uno de los puntos m\u00e1s importantes de su nueva agenda progresista, en un momento se [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-23T19:46:34+00:00","og_image":[{"width":1024,"height":749,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d","datePublished":"2022-08-23T19:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/"},"wordCount":205,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1","keywords":["brasil","destacada","lula"],"articleSection":["Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/","url":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/","name":"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1","datePublished":"2022-08-23T19:46:34+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1","width":1024,"height":749},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/23\/lula-recomienda-a-sus-seguidores-si-queres-pegarle-a-una-mujer-pegale-en-otro-lado-no-en-tu-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Lula recomienda a sus seguidores: \u201cSi quer\u00e9s pegarle a una mujer,\u00a0pegale en otro lado, no en tu casa\u201d"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/lula-puno-en-alto.jpg?fit=1024%2C749&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/8044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=8044"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/8044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/4772"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=8044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=8044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=8044"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=8044"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=8044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}