{"id":7856,"date":"2022-08-07T20:30:00","date_gmt":"2022-08-07T18:30:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/"},"modified":"2022-08-07T20:30:00","modified_gmt":"2022-08-07T18:30:00","slug":"embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/","title":{"rendered":"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Paraguay expres\u00f3 su apoyo y solidaridad a la Rep\u00fablica de China (Taiw\u00e1n), gesto que agradeci\u00f3 el embajador taiwan\u00e9s en Paraguay, <strong>Jos\u00e9 Chih-Cheng Han<\/strong>, tras los ejercicios militares que inici\u00f3 Beijing luego de la visita a Taip\u00e9i de la presidente de la C\u00e1mara de Representantes estadounidense, Nancy Pelosi.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Respecto a la reacci\u00f3n de China, reconoci\u00f3 que los ejercicios militares generan cierta tensi\u00f3n tanto en Taiw\u00e1n como en la zona del Pacifico. Sobre el punto, indic\u00f3 que es la reacci\u00f3n de un pa\u00eds totalitario, <strong><em>\u201cque est\u00e1 en contra de los valores y principios, as\u00ed como de un mundo civilizado y abierto\u201d<\/em><\/strong>, expres\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong><em>\u201cSe tuvo incursiones de naves de guerra y tambi\u00e9n aviones de combate, cruzando la l\u00ednea media del estrecho de Taiw\u00e1n, todo esto est\u00e1 bajo control y monitoreo constante por parte de nuestro sistema de defensa\u201d<\/em><\/strong>, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Si bien todo lo mencionado provoc\u00f3 cierto temor en la poblaci\u00f3n, se\u00f1al\u00f3 que todas las actividades econ\u00f3micas siguen y que no hubo un caos en la cotidianeidad. <em><strong>\u201cHasta el momento los estudiantes y los dem\u00e1s paraguayos en Taiw\u00e1n est\u00e1n muy bien\u201d<\/strong><\/em>, expres\u00f3.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:300\">Con informaci\u00f3n de 1000 AM<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Paraguay expres\u00f3 su apoyo y solidaridad a la Rep\u00fablica de China (Taiw\u00e1n), gesto que agradeci\u00f3 el embajador taiwan\u00e9s en Paraguay, Jos\u00e9 Chih-Cheng Han, tras los ejercicios militares que inici\u00f3 Beijing luego de la visita a Taip\u00e9i de la presidente de la C\u00e1mara de Representantes estadounidense, Nancy Pelosi. Respecto a la reacci\u00f3n de China, reconoci\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7857,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[831,1402,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-7856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-jose-han","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Paraguay expres\u00f3 su apoyo y solidaridad a la Rep\u00fablica de China (Taiw\u00e1n), gesto que agradeci\u00f3 el embajador taiwan\u00e9s en Paraguay, Jos\u00e9 Chih-Cheng Han, tras los ejercicios militares que inici\u00f3 Beijing luego de la visita a Taip\u00e9i de la presidente de la C\u00e1mara de Representantes estadounidense, Nancy Pelosi. Respecto a la reacci\u00f3n de China, reconoci\u00f3 que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-07T18:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/08\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla\",\"datePublished\":\"2022-08-07T18:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1\",\"keywords\":[\"destacada\",\"jose han\",\"taiwan\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/\",\"name\":\"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1\",\"datePublished\":\"2022-08-07T18:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1\",\"width\":1281,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/08\\\/07\\\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/","og_locale":"es_ES","og_type":"article","og_title":"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Paraguay expres\u00f3 su apoyo y solidaridad a la Rep\u00fablica de China (Taiw\u00e1n), gesto que agradeci\u00f3 el embajador taiwan\u00e9s en Paraguay, Jos\u00e9 Chih-Cheng Han, tras los ejercicios militares que inici\u00f3 Beijing luego de la visita a Taip\u00e9i de la presidente de la C\u00e1mara de Representantes estadounidense, Nancy Pelosi. Respecto a la reacci\u00f3n de China, reconoci\u00f3 que [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-07T18:30:00+00:00","og_image":[{"width":1281,"height":675,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/08\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla","datePublished":"2022-08-07T18:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/"},"wordCount":225,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/08\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1","keywords":["destacada","jose han","taiwan"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/","url":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/","name":"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/08\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1","datePublished":"2022-08-07T18:30:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/08\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/08\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1","width":1281,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/08\/07\/embajador-de-la-republica-de-china-taiwan-acerca-tranquilidad-a-las-familias-de-los-paraguayos-que-viven-en-la-isla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Embajador de la Rep\u00fablica de China (Taiw\u00e1n) acerca tranquilidad a las familias de los paraguayos que viven en la isla"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/08\/Jose-Chih-Cheng-Han.jpg?fit=1281%2C675&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/7856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=7856"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/7856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/7857"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=7856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=7856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=7856"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=7856"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=7856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}