{"id":7537,"date":"2022-07-06T11:41:00","date_gmt":"2022-07-06T09:41:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/"},"modified":"2022-07-06T11:41:00","modified_gmt":"2022-07-06T09:41:00","slug":"el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/","title":{"rendered":"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Con los adheridos en el mes de junio de este a\u00f1o, ya suman 62 establecimientos incorporados durante el 2022, y un total de <strong>127 establecimientos de salud conectados en las 18 regiones sanitarias<\/strong>, desde el inicio de la implementaci\u00f3n del HIS.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Durante el <strong>2021<\/strong>, los establecimientos con HIS registraron<strong> un total de 1.933.471 consultas<\/strong>, en tanto que, en lo que va de este a\u00f1o, con los que se sumaron, <strong>esa cifra ya fue superada por 145.619 consultas, llegando en lo que va del 2022 a 2.079.090 consultas<\/strong> registradas a trav\u00e9s del HIS.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Entre otros beneficios para los pacientes, se destacan menor tiempo de espera para la consulta y m\u00e1s tiempo de calidad en la consulta con el m\u00e9dico, entre otros.<\/strong> As\u00ed tambi\u00e9n, <strong>presenta beneficios para los m\u00e9dicos, ya que posibilita una atenci\u00f3n m\u00e1s fluida a trav\u00e9s del sistema automatizado, la disponibilidad de la historia cl\u00ednica<\/strong>, que ayuda al diagn\u00f3stico y tratamiento, <strong>y la disponibilidad de stock en la farmacia<\/strong>, al momento de expedir la receta al paciente. En cuanto a las ventajas que ofrece al establecimiento de salud, se resaltan la estandarizaci\u00f3n del flujo de trabajo, la recolecci\u00f3n de datos en tiempo real, el fortalecimiento del control de gesti\u00f3n, lo que permite mejorar la productividad y la calidad del servicio.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Este proceso de transformaci\u00f3n digital es encarado en forma conjunta entre el <strong>Ministerio de Salud P\u00fablica y Bienestar Social (MSPyBS) y el gobierno de la Rep\u00fablica de China (Taiw\u00e1n), a trav\u00e9s del Proyecto para la \u201cMejora de la Eficiencia en la Gesti\u00f3n de la Inform\u00e1tica en Salud\u201d y cuenta con el apoyo del Ministerio de Tecnolog\u00edas de la Informaci\u00f3n y Comunicaci\u00f3n (MITIC), KOICA, Itaip\u00fa y el BID.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con los adheridos en el mes de junio de este a\u00f1o, ya suman 62 establecimientos incorporados durante el 2022, y un total de 127 establecimientos de salud conectados en las 18 regiones sanitarias, desde el inicio de la implementaci\u00f3n del HIS. Durante el 2021, los establecimientos con HIS registraron un total de 1.933.471 consultas, en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2915,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[36],"tags":[831,178,619,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-7537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-destacada","tag-ministerio-de-salud","tag-mitic","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022 - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022 - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Con los adheridos en el mes de junio de este a\u00f1o, ya suman 62 establecimientos incorporados durante el 2022, y un total de 127 establecimientos de salud conectados en las 18 regiones sanitarias, desde el inicio de la implementaci\u00f3n del HIS. Durante el 2021, los establecimientos con HIS registraron un total de 1.933.471 consultas, en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T09:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022\",\"datePublished\":\"2022-07-06T09:41:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/\"},\"wordCount\":310,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"keywords\":[\"destacada\",\"ministerio de salud\",\"mitic\",\"taiwan\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/\",\"name\":\"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022 - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"datePublished\":\"2022-07-06T09:41:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1\",\"width\":1201,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/07\\\/06\\\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022 - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/","og_locale":"es_ES","og_type":"article","og_title":"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022 - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Con los adheridos en el mes de junio de este a\u00f1o, ya suman 62 establecimientos incorporados durante el 2022, y un total de 127 establecimientos de salud conectados en las 18 regiones sanitarias, desde el inicio de la implementaci\u00f3n del HIS. Durante el 2021, los establecimientos con HIS registraron un total de 1.933.471 consultas, en [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-07-06T09:41:00+00:00","og_image":[{"width":1201,"height":676,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022","datePublished":"2022-07-06T09:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/"},"wordCount":310,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","keywords":["destacada","ministerio de salud","mitic","taiwan"],"articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/","url":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/","name":"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022 - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","datePublished":"2022-07-06T09:41:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","width":1201,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/07\/06\/el-sistema-his-ya-registra-mas-de-2-millones-de-consulta-en-lo-que-va-del-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"El sistema HIS ya registra m\u00e1s de 2 millones de consultas en lo que va del 2022"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/05\/sistema-HIS-salud-publica-taiwan.jpg?fit=1201%2C676&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/7537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=7537"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/7537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/2915"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=7537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=7537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=7537"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=7537"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=7537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}