{"id":650,"date":"2019-04-06T23:19:00","date_gmt":"2019-04-06T21:19:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto\/"},"modified":"2024-02-20T00:28:48","modified_gmt":"2024-02-19T23:28:48","slug":"la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/","title":{"rendered":"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto"},"content":{"rendered":"\n<p>En mayo pasado un anciano fue ingresado en la sucursal de Brooklyn del Hospital Monte Sina\u00ed para una cirug\u00eda abdominal.&nbsp;<strong>Un an\u00e1lisis de sangre revel\u00f3 que estaba infectado con un germen reci\u00e9n descubierto tan mortal como misterioso<\/strong>. Los m\u00e9dicos lo aislaron r\u00e1pidamente en la unidad de cuidados intensivos.<\/p>\n\n\n\n<p><strong>El germen, un hongo llamado Candida Auris, se alimenta de personas con sistemas inmunitarios debilitados<\/strong>&nbsp;y se propaga silenciosamente por todo el mundo. En los \u00faltimos cinco a\u00f1os, ha golpeado una unidad neonatal en Venezuela, ha pasado por un hospital en Espa\u00f1a, ha obligado a un prestigioso centro m\u00e9dico brit\u00e1nico a cerrar su unidad de cuidados intensivos y ha echado ra\u00edces en India, Pakist\u00e1n y Sud\u00e1frica.<\/p>\n\n\n\n<p>Recientemente,<strong>&nbsp;Candida Auris lleg\u00f3 a Nueva York, Nueva Jersey e Illinois<\/strong>, y los Centros Federales para el Control y la Prevenci\u00f3n de Enfermedades lo agregaron a una lista de g\u00e9rmenes considerados como \u00abamenazas urgentes\u00bb.<\/p>\n\n\n\n<p>El hombre en el Monte Sina\u00ed muri\u00f3 despu\u00e9s de 90 d\u00edas en el hospital, pero Candida Auris no lo hizo.&nbsp;<strong>Las pruebas mostraron que este virus estaba en todas partes de su habitaci\u00f3n<\/strong>, tan invasiva que el hospital necesitaba equipos de limpieza especiales y tuvo que arrancar algunos de los techos y baldosas para erradicarlo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/twitter.com\/intent\/tweet?text=La%20infecci%C3%B3n%20misteriosa%20que%20se%20propaga%20por%20el%20mundo%20en%20un%20clima%20de%20secreto&amp;url=https:\/\/www.infobae.com\/america\/the-new-york-times\/2019\/04\/06\/la-infeccion-misteriosa-que-abarca-el-mundo-en-un-clima-de-secreto\/%23BZAC6IIYMBFZTMMBX4YHIRDKLA\" target=\"_blank\" rel=\"noreferrer noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/INFECCION-2.png?ssl=1\" alt=\"(Foto: New York Times)\"\/><\/a><figcaption>(Foto: New York Times)<\/figcaption><\/figure>\n\n\n\n<p>\u00abTodo fue positivo: las paredes, la cama, las puertas, las cortinas, los tel\u00e9fonos, el fregadero, la pizarra, los postes, la bomba\u00bb, dijo el doctor Scott Lorin, presidente del hospital. \u00abEl colch\u00f3n, los rieles de la cama, los orificios de los recipientes, las persianas, el techo, todo en la habitaci\u00f3n fue positivo\u00bb.<\/p>\n\n\n\n<p><strong>C. Auris es tan tenaz, en parte, porque es impermeable a los principales medicamentos antimic\u00f3ticos<\/strong>, por lo que es un nuevo ejemplo de una de las amenazas para la salud m\u00e1s dif\u00edciles del mundo: el aumento de las infecciones resistentes a los medicamentos.<\/p>\n\n\n\n<p>Durante d\u00e9cadas, los expertos en salud p\u00fablica han advertido que el uso excesivo de antibi\u00f3ticos estaba reduciendo la efectividad de los medicamentos que han prolongado la vida \u00fatil al curar infecciones bacterianas que alguna vez suelen ser fatales.&nbsp;<strong>Pero \u00faltimamente, tambi\u00e9n ha habido una explosi\u00f3n de hongos resistentes, agregando una dimensi\u00f3n nueva y aterradora a un fen\u00f3meno que est\u00e1 socavando un pilar de la medicina moderna<\/strong>.<\/p>\n\n\n\n<p>\u00ab<strong>Es un problema enorme<\/strong>\u00ab, dijo Matthew Fisher, profesor de epidemiolog\u00eda de hongos en el Imperial College de Londres, quien fue coautor de una reciente revisi\u00f3n cient\u00edfica sobre el aumento de hongos resistentes. \u00abDependemos de ser capaces de tratar a esos pacientes con antif\u00fangicos\u00bb.<\/p>\n\n\n\n<p>En pocas palabras, los hongos, al igual que las bacterias, est\u00e1n desarrollando defensas para sobrevivir a las medicinas modernas.<\/p>\n\n\n\n<p>Sin embargo, incluso cuando los l\u00edderes mundiales de la salud han pedido m\u00e1s moderaci\u00f3n en la prescripci\u00f3n de medicamentos antimicrobianos para combatir las bacterias y los hongos, se convoc\u00f3 a&nbsp;<strong>la Asamblea General de las Naciones Unidas en 2016 para gestionar una crisis emergente: el uso excesivo de ellos en hospitales, cl\u00ednicas y la agricultura ha continuado<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/twitter.com\/intent\/tweet?text=La%20infecci%C3%B3n%20misteriosa%20que%20se%20propaga%20por%20el%20mundo%20en%20un%20clima%20de%20secreto&amp;url=https:\/\/www.infobae.com\/america\/the-new-york-times\/2019\/04\/06\/la-infeccion-misteriosa-que-abarca-el-mundo-en-un-clima-de-secreto\/%233WCPVRSYQNCEDGMA25N5GQJTQQ\" target=\"_blank\" rel=\"noreferrer noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/INFECCION-3.png?ssl=1\" alt=\"(Foto: New York Times)\"\/><\/a><figcaption>(Foto: New York Times)<\/figcaption><\/figure>\n\n\n\n<p>Los g\u00e9rmenes resistentes a menudo se llaman \u00absuperbacterias\u00bb, pero esto es simplista porque generalmente no matan a todos.&nbsp;<strong>En cambio, son m\u00e1s letales para las personas con sistemas inmaduros o sistemas inmunes comprometidos, incluidos los reci\u00e9n nacidos y los ancianos, los fumadores, los diab\u00e9ticos y las personas con desordenes autoinmunes<\/strong>&nbsp;que toman esteroides y suprimen las defensas del cuerpo.<\/p>\n\n\n\n<p><strong>Los cient\u00edficos dicen que a menos que se desarrollen nuevos medicamentos m\u00e1s efectivos y que se reduzca dr\u00e1sticamente el uso innecesario de medicamentos antimicrobianos, el riesgo se extender\u00e1 a poblaciones m\u00e1s saludables<\/strong>. Un estudio del gobierno brit\u00e1nico financi\u00f3 proyectos que, si no se implementan pol\u00edticas para frenar el aumento de la resistencia a los medicamentos, 10 millones de personas podr\u00edan morir en el mundo por todas estas infecciones en 2050, eclipsando a los ocho millones que se espera que mueran de c\u00e1ncer ese a\u00f1o.<\/p>\n\n\n\n<p><strong>En los Estados Unidos, dos millones de personas contraen infecciones resistentes anualmente, y 23 mil mueren a causa de ellas, seg\u00fan la C.D.C. estimar<\/strong>. Ese n\u00famero se bas\u00f3 en las cifras de 2010; estimaciones m\u00e1s recientes de investigadores de la Escuela de Medicina de la Universidad de Washington estimaron la cifra de muertos en 162 mil. Las muertes en todo el mundo por infecciones resistentes se estiman en 700 mil.<\/p>\n\n\n\n<p>Tanto los antibi\u00f3ticos como los antif\u00fangicos son esenciales para combatir las infecciones en las personas, pero los antibi\u00f3ticos tambi\u00e9n se usan ampliamente para prevenir enfermedades en los animales de granja, y los antimic\u00f3ticos tambi\u00e9n se aplican para evitar que las plantas agr\u00edcolas se pudran.<strong>&nbsp;Algunos cient\u00edficos citan evidencia de que el uso rampante de fungicidas en cultivos est\u00e1 contribuyendo al aumento de hongos resistentes a los medicamentos que infectan a los humanos<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/twitter.com\/intent\/tweet?text=La%20infecci%C3%B3n%20misteriosa%20que%20se%20propaga%20por%20el%20mundo%20en%20un%20clima%20de%20secreto&amp;url=https:\/\/www.infobae.com\/america\/the-new-york-times\/2019\/04\/06\/la-infeccion-misteriosa-que-abarca-el-mundo-en-un-clima-de-secreto\/%23BHUOQ7LLJBHKRPVKR5H72OU75I\" target=\"_blank\" rel=\"noreferrer noopener\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/INFECCION-4.png?ssl=1\" alt=\"(Foto: New York Times)\"\/><\/a><figcaption>(Foto: New York Times)<\/figcaption><\/figure>\n\n\n\n<p>Sin embargo, a medida que el problema crece, el p\u00fablico lo entiende poco, en parte porque la existencia misma de infecciones resistentes a menudo est\u00e1 oculta en secreto.<\/p>\n\n\n\n<p><strong>Con bacterias y hongos por igual, los hospitales y los gobiernos locales se muestran reacios a divulgar los brotes por temor a ser vistos como centros de infecci\u00f3n<\/strong>. Incluso la C.D.C., en virtud de su acuerdo con los estados, no est\u00e1 autorizado a hacer p\u00fablica la ubicaci\u00f3n o el nombre de los hospitales involucrados en brotes. En muchos casos, los gobiernos estatales se han negado a compartir informaci\u00f3n p\u00fablicamente m\u00e1s all\u00e1 de reconocer que han tenido casos.<\/p>\n\n\n\n<p>Al mismo tiempo,&nbsp;<strong>los g\u00e9rmenes se propagan f\u00e1cilmente: se llevan en las manos y el equipo dentro de los hospitales; transportado en carne y hortalizas fertilizadas con esti\u00e9rcol de las granjas<\/strong>; transportados a trav\u00e9s de las fronteras por los viajeros y en las exportaciones e importaciones; y transferidos por pacientes desde el hogar de ancianos al hospital y de regreso.<\/p>\n\n\n\n<p><strong>C. Auris, que infect\u00f3 al hombre en el Monte Sina\u00ed, es una de las docenas de bacterias y hongos peligrosos que han desarrollado resistencia<\/strong>. Sin embargo, como la mayor\u00eda de ellos, es una amenaza que es pr\u00e1cticamente desconocida para el p\u00fablico.<\/p>\n\n\n\n<p>Otras cepas prominentes del hongo Candida, una de las causas m\u00e1s comunes de infecciones del torrente sangu\u00edneo en los hospitales, no han desarrollado una resistencia significativa a los medicamentos, pero&nbsp;<strong>m\u00e1s del 90% de las infecciones por C. Auris son resistentes a al menos un f\u00e1rmaco, y el 30% son resistente a dos o m\u00e1s medicamentos<\/strong>.<\/p>\n\n\n\n<p>La Dra. Lynn Sosa, epidemi\u00f3loga estatal adjunta de Connecticut, dijo que ahora ve a C. Auris como la amenaza \u00abprincipal\u00bb entre las infecciones resistentes. \u00ab<strong>Es bastante imbatible y dif\u00edcil de identificar<\/strong>\u00ab, dijo.<\/p>\n\n\n\n<p>Casi la mitad de los pacientes que contraen C. Auris mueren dentro de los 90 d\u00edas, seg\u00fan el C.D.C. Sin embargo, los expertos del mundo no han determinado de d\u00f3nde viene en primer lugar.<\/p>\n\n\n\n<p>\u00abEs una criatura de la laguna negra\u00bb, dijo el Dr. Tom Chiller, quien encabeza la rama de hongos en el C.D.C., que encabeza un esfuerzo de detecci\u00f3n global para encontrar tratamientos y detener la propagaci\u00f3n. \u00abBurbujeaba y ahora est\u00e1 en todas partes\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mayo pasado un anciano fue ingresado en la sucursal de Brooklyn del Hospital Monte Sina\u00ed para una cirug\u00eda abdominal.&nbsp;Un an\u00e1lisis de sangre revel\u00f3 que estaba infectado con un germen reci\u00e9n descubierto tan mortal como misterioso. Los m\u00e9dicos lo aislaron r\u00e1pidamente en la unidad de cuidados intensivos. El germen, un hongo llamado Candida Auris, se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":651,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[36],"tags":[380,381],"jnews-series":[],"ppma_author":[47],"class_list":["post-650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-candida-auris","tag-epidemia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En mayo pasado un anciano fue ingresado en la sucursal de Brooklyn del Hospital Monte Sina\u00ed para una cirug\u00eda abdominal.&nbsp;Un an\u00e1lisis de sangre revel\u00f3 que estaba infectado con un germen reci\u00e9n descubierto tan mortal como misterioso. Los m\u00e9dicos lo aislaron r\u00e1pidamente en la unidad de cuidados intensivos. El germen, un hongo llamado Candida Auris, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-06T21:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T23:28:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/candidad-auris.jpg?fit=700%2C414&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicoCPT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicoCPT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/\"},\"author\":{\"name\":\"NicoCPT\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\"},\"headline\":\"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto\",\"datePublished\":\"2019-04-06T21:19:00+00:00\",\"dateModified\":\"2024-02-19T23:28:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/\"},\"wordCount\":1262,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/candidad-auris.jpg?fit=700%2C414&ssl=1\",\"keywords\":[\"candida auris\",\"epidemia\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/\",\"name\":\"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/candidad-auris.jpg?fit=700%2C414&ssl=1\",\"datePublished\":\"2019-04-06T21:19:00+00:00\",\"dateModified\":\"2024-02-19T23:28:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/candidad-auris.jpg?fit=700%2C414&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/candidad-auris.jpg?fit=700%2C414&ssl=1\",\"width\":700,\"height\":414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/06\\\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\",\"name\":\"NicoCPT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"NicoCPT\"},\"sameAs\":[\"https:\\\/\\\/informatepy.com\\\/2024\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/nicocpt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/","og_locale":"es_ES","og_type":"article","og_title":"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En mayo pasado un anciano fue ingresado en la sucursal de Brooklyn del Hospital Monte Sina\u00ed para una cirug\u00eda abdominal.&nbsp;Un an\u00e1lisis de sangre revel\u00f3 que estaba infectado con un germen reci\u00e9n descubierto tan mortal como misterioso. Los m\u00e9dicos lo aislaron r\u00e1pidamente en la unidad de cuidados intensivos. El germen, un hongo llamado Candida Auris, se [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2019-04-06T21:19:00+00:00","article_modified_time":"2024-02-19T23:28:48+00:00","og_image":[{"width":700,"height":414,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/candidad-auris.jpg?fit=700%2C414&ssl=1","type":"image\/jpeg"}],"author":"NicoCPT","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"NicoCPT","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/"},"author":{"name":"NicoCPT","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e"},"headline":"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto","datePublished":"2019-04-06T21:19:00+00:00","dateModified":"2024-02-19T23:28:48+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/"},"wordCount":1262,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/candidad-auris.jpg?fit=700%2C414&ssl=1","keywords":["candida auris","epidemia"],"articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/","url":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/","name":"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/candidad-auris.jpg?fit=700%2C414&ssl=1","datePublished":"2019-04-06T21:19:00+00:00","dateModified":"2024-02-19T23:28:48+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/candidad-auris.jpg?fit=700%2C414&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/candidad-auris.jpg?fit=700%2C414&ssl=1","width":700,"height":414},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/06\/la-infeccion-misteriosa-que-se-propaga-por-el-mundo-en-un-clima-de-secreto-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"La infecci\u00f3n misteriosa que se propaga por el mundo en un clima de secreto"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e","name":"NicoCPT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"NicoCPT"},"sameAs":["https:\/\/informatepy.com\/2024"],"url":"https:\/\/informatepy.com\/2024\/author\/nicocpt\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/candidad-auris.jpg?fit=700%2C414&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":47,"user_id":1,"is_guest":0,"slug":"nicocpt","display_name":"NicoCPT","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"https:\/\/informatepy.com\/2024","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=650"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/650\/revisions"}],"predecessor-version":[{"id":8535,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/650\/revisions\/8535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/651"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=650"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=650"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}