{"id":624,"date":"2019-04-01T20:19:00","date_gmt":"2019-04-01T18:19:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/"},"modified":"2019-04-01T20:19:00","modified_gmt":"2019-04-01T18:19:00","slug":"alliana-y-un-aviso-de-cara-a-las-proximas-elecciones","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/","title":{"rendered":"Alliana y un aviso de cara a las pr\u00f3ximas elecciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente de la Asamblea Nacional Republicana, diputado Pedro Alliana, fue entrevistado hace unos d\u00edas en el programa \u00abEl Repasador\u00bb por la RPC. En varios pasajes, Alliana envi\u00f3 un mensaje al ejecutivo nacional, al afirmar que va a ser muy dif\u00edcil pedirle a los dirigentes de Honor Colorado que apoyen al presidente, luego de que el mismo ignorara el apoyo brindado en las \u00faltimas elecciones, y se lanzara una caza de brujas en todos los organismos del estado en contra de los dirigentes de ese movimiento partidario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro pasaje de la entrevista, habl\u00f3 del precio que est\u00e1 pagando y que va a tener el pa\u00eds, detr\u00e1s de la alianza de Maro Abdo con la izquierda: \u00abMarito tiene un pacto con la izquierda a un costo elevado para el partido y el pa\u00eds\u00bb, y lo hizo traicionando a un importante sector del partido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Asamblea Nacional Republicana, diputado Pedro Alliana, fue entrevistado hace unos d\u00edas en el programa \u00abEl Repasador\u00bb por la RPC. En varios pasajes, Alliana envi\u00f3 un mensaje al ejecutivo nacional, al afirmar que va a ser muy dif\u00edcil pedirle a los dirigentes de Honor Colorado que apoyen al presidente, luego de que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":625,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[138,197,286,369],"jnews-series":[],"ppma_author":[47],"class_list":["post-624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-anr","tag-mario-abdo","tag-partido-colorado","tag-pedro-alliana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alliana y un aviso de cara a las pr\u00f3ximas elecciones - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alliana y un aviso de cara a las pr\u00f3ximas elecciones - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El presidente de la Asamblea Nacional Republicana, diputado Pedro Alliana, fue entrevistado hace unos d\u00edas en el programa \u00abEl Repasador\u00bb por la RPC. En varios pasajes, Alliana envi\u00f3 un mensaje al ejecutivo nacional, al afirmar que va a ser muy dif\u00edcil pedirle a los dirigentes de Honor Colorado que apoyen al presidente, luego de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-01T18:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/alliana-repasador.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicoCPT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicoCPT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/\"},\"author\":{\"name\":\"NicoCPT\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\"},\"headline\":\"Alliana y un aviso de cara a las pr\u00f3ximas elecciones\",\"datePublished\":\"2019-04-01T18:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alliana-repasador.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"anr\",\"mario abdo\",\"partido colorado\",\"Pedro Alliana\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/\",\"name\":\"Alliana y un aviso de cara a las pr\u00f3ximas elecciones - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alliana-repasador.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2019-04-01T18:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alliana-repasador.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/alliana-repasador.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/04\\\/01\\\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alliana y un aviso de cara a las pr\u00f3ximas elecciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\",\"name\":\"NicoCPT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"NicoCPT\"},\"sameAs\":[\"https:\\\/\\\/informatepy.com\\\/2024\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/nicocpt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alliana y un aviso de cara a las pr\u00f3ximas elecciones - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/","og_locale":"es_ES","og_type":"article","og_title":"Alliana y un aviso de cara a las pr\u00f3ximas elecciones - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El presidente de la Asamblea Nacional Republicana, diputado Pedro Alliana, fue entrevistado hace unos d\u00edas en el programa \u00abEl Repasador\u00bb por la RPC. En varios pasajes, Alliana envi\u00f3 un mensaje al ejecutivo nacional, al afirmar que va a ser muy dif\u00edcil pedirle a los dirigentes de Honor Colorado que apoyen al presidente, luego de que [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2019-04-01T18:19:00+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/alliana-repasador.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"NicoCPT","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"NicoCPT","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/"},"author":{"name":"NicoCPT","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e"},"headline":"Alliana y un aviso de cara a las pr\u00f3ximas elecciones","datePublished":"2019-04-01T18:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/"},"wordCount":159,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/alliana-repasador.jpg?fit=760%2C420&ssl=1","keywords":["anr","mario abdo","partido colorado","Pedro Alliana"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/","url":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/","name":"Alliana y un aviso de cara a las pr\u00f3ximas elecciones - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/alliana-repasador.jpg?fit=760%2C420&ssl=1","datePublished":"2019-04-01T18:19:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/alliana-repasador.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/alliana-repasador.jpg?fit=760%2C420&ssl=1","width":760,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2019\/04\/01\/alliana-y-un-aviso-de-cara-a-las-proximas-elecciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Alliana y un aviso de cara a las pr\u00f3ximas elecciones"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e","name":"NicoCPT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"NicoCPT"},"sameAs":["https:\/\/informatepy.com\/2024"],"url":"https:\/\/informatepy.com\/2024\/author\/nicocpt\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/alliana-repasador.jpg?fit=760%2C420&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":47,"user_id":1,"is_guest":0,"slug":"nicocpt","display_name":"NicoCPT","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"https:\/\/informatepy.com\/2024","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=624"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/625"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=624"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=624"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}