{"id":5354,"date":"2022-01-11T09:15:00","date_gmt":"2022-01-11T08:15:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/"},"modified":"2022-01-11T09:15:00","modified_gmt":"2022-01-11T08:15:00","slug":"a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/","title":{"rendered":"A tener en cuenta antes de salir de casa (11-01-22)"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Te dejamos algunos de los aspectos que debes tener en cuenta antes de salir de casa porque pueden llegar a modificar tu d\u00eda:<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em><strong>CLIMA:<\/strong><\/em>\u00a0Se prev\u00e9 una jornada de c\u00e1lida a calurosa (M\u00e1x. 37\u00ba), con un cielo de parcialmente nublado a nublado y vientos variables que luego ser\u00e1n del sureste.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>COTIZACION DE MONEDAS EXTRANJERAS:<\/strong>\u00a0<em>D\u00f3lar\u00a0<\/em>6.830 \/ 6.910,\u00a0<em>Euro<\/em>: 7.200 \/ 7.770,\u00a0<em>Real<\/em>: 1.200 \/ 1.300,\u00a0<em>Peso Argentino<\/em>: 30 \/ 40.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te dejamos algunos de los aspectos que debes tener en cuenta antes de salir de casa porque pueden llegar a modificar tu d\u00eda: CLIMA:\u00a0Se prev\u00e9 una jornada de c\u00e1lida a calurosa (M\u00e1x. 37\u00ba), con un cielo de parcialmente nublado a nublado y vientos variables que luego ser\u00e1n del sureste. COTIZACION DE MONEDAS EXTRANJERAS:\u00a0D\u00f3lar\u00a06.830 \/ 6.910,\u00a0Euro: [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5219,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[34],"tags":[1415,1417,1416,831],"jnews-series":[],"ppma_author":[830],"class_list":["post-5354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-clima","tag-clima-en-paraguay","tag-cotizacion","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A tener en cuenta antes de salir de casa (11-01-22) - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A tener en cuenta antes de salir de casa (11-01-22) - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Te dejamos algunos de los aspectos que debes tener en cuenta antes de salir de casa porque pueden llegar a modificar tu d\u00eda: CLIMA:\u00a0Se prev\u00e9 una jornada de c\u00e1lida a calurosa (M\u00e1x. 37\u00ba), con un cielo de parcialmente nublado a nublado y vientos variables que luego ser\u00e1n del sureste. COTIZACION DE MONEDAS EXTRANJERAS:\u00a0D\u00f3lar\u00a06.830 \/ 6.910,\u00a0Euro: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T08:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"A tener en cuenta antes de salir de casa (11-01-22)\",\"datePublished\":\"2022-01-11T08:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/\"},\"wordCount\":74,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1\",\"keywords\":[\"clima\",\"clima en paraguay\",\"cotizacion\",\"destacada\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/\",\"name\":\"A tener en cuenta antes de salir de casa (11-01-22) - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1\",\"datePublished\":\"2022-01-11T08:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1\",\"width\":612,\"height\":408,\"caption\":\"Reading newspaper on desk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/11\\\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A tener en cuenta antes de salir de casa (11-01-22)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A tener en cuenta antes de salir de casa (11-01-22) - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/","og_locale":"es_ES","og_type":"article","og_title":"A tener en cuenta antes de salir de casa (11-01-22) - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Te dejamos algunos de los aspectos que debes tener en cuenta antes de salir de casa porque pueden llegar a modificar tu d\u00eda: CLIMA:\u00a0Se prev\u00e9 una jornada de c\u00e1lida a calurosa (M\u00e1x. 37\u00ba), con un cielo de parcialmente nublado a nublado y vientos variables que luego ser\u00e1n del sureste. COTIZACION DE MONEDAS EXTRANJERAS:\u00a0D\u00f3lar\u00a06.830 \/ 6.910,\u00a0Euro: [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-01-11T08:15:00+00:00","og_image":[{"width":612,"height":408,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"A tener en cuenta antes de salir de casa (11-01-22)","datePublished":"2022-01-11T08:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/"},"wordCount":74,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1","keywords":["clima","clima en paraguay","cotizacion","destacada"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/","url":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/","name":"A tener en cuenta antes de salir de casa (11-01-22) - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1","datePublished":"2022-01-11T08:15:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1","width":612,"height":408,"caption":"Reading newspaper on desk"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/11\/a-tener-en-cuenta-antes-de-salir-de-casa-11-01-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"A tener en cuenta antes de salir de casa (11-01-22)"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/noticias-en-el-desayuno.jpg?fit=612%2C408&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/5354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=5354"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/5354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/5219"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=5354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=5354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=5354"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=5354"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=5354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}