{"id":5208,"date":"2022-01-01T19:24:28","date_gmt":"2022-01-01T18:24:28","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/"},"modified":"2022-01-01T19:24:28","modified_gmt":"2022-01-01T18:24:28","slug":"el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/","title":{"rendered":"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">La ministra de Transporte del Gobierno del Reino Unido, Trudy Harrison, habl\u00f3 recientemente en una conferencia sobre movilidad, abordando el futuro de la movilidad personal.\u00a0En sus comentarios, dijo que era necesario deshacerse del <em><strong>\u00abpensamiento del siglo XX centrado en la propiedad de veh\u00edculos privados y hacia una mayor flexibilidad, con elecci\u00f3n personal y transporte compartido bajo en carbono\u00bb<\/strong><\/em>.\u00a0As\u00ed es, dijo en voz alta la parte tranquila y mostr\u00f3 la mano de un n\u00famero creciente de funcionarios del gobierno.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Harrison continu\u00f3 elogiando no solo el transporte p\u00fablico, sino tambi\u00e9n los servicios de bicicletas compartidas, los e-scooters y las plataformas para compartir viajes.\u00a0Se supone que todos ellos reducen la cantidad de carbono que el Reino Unido emite a la atm\u00f3sfera.\u00a0Como ocurre con todas las opciones, esto tiene un costo, especialmente para quienes viven en \u00e1reas rurales.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Adem\u00e1s, 300 residentes de Coventry expresaron recientemente su inter\u00e9s en renunciar a sus autom\u00f3viles personales.&nbsp;Seg\u00fan se informa, la compensaci\u00f3n del gobierno ser\u00eda un cr\u00e9dito de movilidad por valor de hasta \u00a3 3.000.&nbsp;Este programa de cr\u00e9dito de movilidad ha estado en marcha desde marzo de este a\u00f1o, con 73 coches entregados y aplastados.&nbsp;No, esto no es una broma, pero desear\u00eda que lo fuera.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Es comprensible que muchos brit\u00e1nicos est\u00e9n molestos por esto.\u00a0Algunos han preguntado si deber\u00edan empezar a montar a caballo en su lugar, todo ello en nombre del \u00abprogreso\u00bb.\u00a0Otros est\u00e1n vinculando esta declaraci\u00f3n de Harrison con la inminente prohibici\u00f3n gubernamental de los motores de combusti\u00f3n interna para autom\u00f3viles para 2030. Despu\u00e9s de todo, los veh\u00edculos el\u00e9ctricos no son exactamente baratos, as\u00ed que,<strong> \u00bfQu\u00e9 mejor manera de obligar a las personas a subir al transporte p\u00fablico que poni\u00e9ndoles un precio para sacarlos del mercado de veh\u00edculos?<\/strong> <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Por m\u00e1s desagradable que sea la pol\u00edtica, si los entusiastas de los autom\u00f3viles y realmente todos los que disfrutan de ir a donde quieran cuando les plazca en su veh\u00edculo privado no comienzan a tomar una posici\u00f3n, nuestras libertades podr\u00edan verse severamente restringidas de formas que muchos han pensado que no eran posibles. .\u00a0No hacer algo para detener este impulso terminar\u00e1 mal para casi todos.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Yahoo Autos<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Pronto, los brit\u00e1nicos no poseer\u00e1n nada y estar\u00e1n m\u00e1s felices por ello<\/p>\n","protected":false},"author":3,"featured_media":5209,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33],"tags":[835,831,1299,1089],"jnews-series":[],"ppma_author":[830],"class_list":["post-5208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-agenda-2030","tag-destacada","tag-inglaterra","tag-reino-unido"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Pronto, los brit\u00e1nicos no poseer\u00e1n nada y estar\u00e1n m\u00e1s felices por ello\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-01T18:24:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/bus-londres-1.jpg?fit=804%2C453&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"804\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados\",\"datePublished\":\"2022-01-01T18:24:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/bus-londres-1.jpg?fit=804%2C453&ssl=1\",\"keywords\":[\"agenda 2030\",\"destacada\",\"inglaterra\",\"reino unido\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/\",\"name\":\"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/bus-londres-1.jpg?fit=804%2C453&ssl=1\",\"datePublished\":\"2022-01-01T18:24:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/bus-londres-1.jpg?fit=804%2C453&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/bus-londres-1.jpg?fit=804%2C453&ssl=1\",\"width\":804,\"height\":453},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2022\\\/01\\\/01\\\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/","og_locale":"es_ES","og_type":"article","og_title":"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Pronto, los brit\u00e1nicos no poseer\u00e1n nada y estar\u00e1n m\u00e1s felices por ello","og_url":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-01-01T18:24:28+00:00","og_image":[{"width":804,"height":453,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/bus-londres-1.jpg?fit=804%2C453&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados","datePublished":"2022-01-01T18:24:28+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/"},"wordCount":404,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/bus-londres-1.jpg?fit=804%2C453&ssl=1","keywords":["agenda 2030","destacada","inglaterra","reino unido"],"articleSection":["Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/","url":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/","name":"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/bus-londres-1.jpg?fit=804%2C453&ssl=1","datePublished":"2022-01-01T18:24:28+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/bus-londres-1.jpg?fit=804%2C453&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/bus-londres-1.jpg?fit=804%2C453&ssl=1","width":804,"height":453},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2022\/01\/01\/el-reino-unido-esta-mas-cerca-de-eliminar-la-propiedad-de-automoviles-privados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"El Reino Unido est\u00e1 m\u00e1s cerca de eliminar la propiedad de autom\u00f3viles privados"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2022\/01\/bus-londres-1.jpg?fit=804%2C453&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/5208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=5208"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/5208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/5209"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=5208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=5208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=5208"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=5208"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=5208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}