{"id":4975,"date":"2021-12-10T10:24:25","date_gmt":"2021-12-10T09:24:25","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/"},"modified":"2021-12-10T10:24:25","modified_gmt":"2021-12-10T09:24:25","slug":"serpaj-vuelve-a-las-andanzas","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/","title":{"rendered":"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El 7 de diciembre pasado SERPAJ, Servicio de Paz y Justicia, anunci\u00f3 el relanzamiento de su Gu\u00eda para docentes y familias sobre Educaci\u00f3n Sexual Integral. S\u00ed, pretenden relanzar el pol\u00e9mico material que en el 2018 fue denunciado por los padres y prohibido por el MEC seg\u00fan resoluci\u00f3n 1761\/2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que estar atentos al contenido de esta nueva versi\u00f3n de la Gu\u00eda. El 7 de Diciembre en un art\u00edculo de ABC se le\u00eda \u00a8Este jueves 8 de diciembre a las 8 y 30 en el Granel, Serpaj Paraguay realizar\u00e1 el relanzamiento de la gu\u00eda para docentes y familias sobre educaci\u00f3n integral de la sexualidad \u2026 Servicio Paz y Justicia Paraguay cuenta con un trabajo sostenido y comprometido en materia de Educaci\u00f3n Integral de la Sexualidad, que incluye esfuerzos comunicacionales para llegar a madres, padres, cuidadores, educadores y educadoras \u2026 <strong><u>En el encuentro explicar\u00e1n el contenido e importancia de estas gu\u00edas y atender\u00e1n las preguntas que surjan<\/u>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo llamativo es que hubo padres que asistimos al evento anunciado, pero no nos dejaron participar del encuentro argumentando que la cita era solo para la prensa. Mencion\u00e9 el art\u00edculo de ABC y ya que estaba en el lugar y hab\u00eda pedido permiso en el trabajo para asistir a la hora y en el lugar indicado por la Serpaj, insist\u00ed en participar. La negativa se reiter\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La persona que me atendi\u00f3 me manifest\u00f3 que el viernes 10 se transmitir\u00eda el relanzamiento por redes y que desde ah\u00ed me pod\u00eda enterar de los detalles. Que la publicaci\u00f3n en ABC hab\u00eda sido un error. Amablemente me invito a llenar una planilla y dejar mi mail, se comprometi\u00f3 a hacerme llegar las novedades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya nada me sorprende de las ONGs. Aunque disfrazadas de buenas maneras y de correcci\u00f3n pol\u00edtica son realmente ladinas, tramposas, ma\u00f1eras. Avanzan bajo enga\u00f1o en sus agendas, sin rubor alguno y sin importar los medios para llegar al fin. Es que reciben muy buenos fondos desde el extranjero y de nuestros propios impuestos, todo se justifica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como no me dejaron entrar, me sent\u00e9 a esperar que terminen y ver quienes estaban en la reuni\u00f3n en vez de los padres. Hab\u00edan periodistas del Surtidor, de Ciencias del Sur, de ABC y de UH. De Ciencias del Sur estaba Eduardo Quintana. Por la ONG CDIA, Diana Serafini y por la SERPAJ, Ram\u00f3n Corval\u00e1n. Prep\u00e1rense para el bombardeo medi\u00e1tico a favor de la EIS, odas a la Gu\u00eda recargada de Serpaj. <strong>Los trovadores ser\u00e1n los vende patrias de siempre. Esos que entregan a nuestros hijos por el vil metal.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ram\u00f3n Corval\u00e1n, cabe mencionar que termin\u00f3 siendo el marido de la Dra. Stela Ben\u00edtez, la que fraudulentamente quiso hacer creer, en un estudio, que los plaguicidas utilizados en el campo da\u00f1an el ADN de los ni\u00f1os. El mismo Corval\u00e1n figuraba en el equipo de investigadores que lideraba su esposa, deplorable, todo financiado por la CONACYT con dinero p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Diana Serafini la conoc\u00eda, ya que ella represent\u00f3 a CDIA en la mesa del Ministerio de la Ni\u00f1ez y Adolescencia donde se debati\u00f3 sobre el Plan Ni\u00f1ez objetado el a\u00f1o pasado. Est\u00e1n en todas como se ve y nunca para algo constructivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ram\u00f3n Corval\u00e1n, adem\u00e1s de ser el esposo de la Dra. Ben\u00edtez, es un gran defensor de la Gu\u00eda para docentes sobre educaci\u00f3n integral de la sexualidad, quien qued\u00f3 muy frustrado cuando la gu\u00eda fue dada de baja en el 2019 por resoluci\u00f3n ministerial y a instancias de la presi\u00f3n de los padres que enseguida advirtieron la perversi\u00f3n de la misma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La famosa Educaci\u00f3n Integral de la sexualidad se vende como la panacea para solucionar los abusos sexuales en ni\u00f1os y la prevenci\u00f3n de transmisi\u00f3n de enfermedades ven\u00e9reas, entre otras disque bondades que argumentan los que cobran en d\u00f3lares para imponerla. Cuando en realidad una vez implementada tiene el efecto inverso de lo que dicen que pretende solucionar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Educaci\u00f3n Integral de la Sexualidad como est\u00e1 planteada en todas partes del mundo, ya que es una agenda global, impuesta desde organismos internacionales, es una herramienta de adoctrinamiento de los ni\u00f1os y adolescentes, adoctrinamiento para imponer y normalizar en la mente de los chicos dos cuestiones, 1) El Enfoque o Ideolog\u00eda de G\u00e9nero, teor\u00eda a contramano de la ciencia y de la realidad, que niega la naturaleza humana, niega la realidad biol\u00f3gica del ser humano, suplant\u00e1ndola por la idea de la identidad de g\u00e9nero que prescinde del hecho biol\u00f3gico, es decir, no importa haber nacido mujer o var\u00f3n, este enfoque fomenta la posibilidad de adoptar, sexualmente hablando, lo que uno sienta que quiere ser, la autopercepci\u00f3n prima sobre el sexo biol\u00f3gico con el que se ha nacido y 2) La normalizaci\u00f3n del aborto, que es presentado como un derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El verdadero objetivo de la EIS es una revoluci\u00f3n cultural, no la prevenci\u00f3n de abusos sexuales en ni\u00f1os o la prevenci\u00f3n de enfermedades ven\u00e9reas. Lejos de esto, la EIS no ofrece educaci\u00f3n sexual acorde a la edad ni basada en ciencias, si no que se trata de una ense\u00f1anza en la pr\u00e1ctica genita, que termina predisponiendo al ni\u00f1o a ser abusado. (Cuando me refiero al ni\u00f1o, uso correctamente la gram\u00e1tica espa\u00f1ola que incluye al g\u00e9nero femenino en una sola palabra).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La implementaci\u00f3n de estos programas, no previenen las enfermedades ven\u00e9reas, las dispara, ya que la EIS toma el sexo como algo fortuito, un derecho que debe ser ejercido sin ning\u00fan tipo de limitaciones, ni de responsabilidad, que desemboca en embarazos no deseados y en miles de abortos, que es exactamente lo que se desea normalizar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La EIS provoca la hipersexualizaci\u00f3n de los chicos y priva a los ni\u00f1os de su infancia, violando gravemente su derecho a la indemnidad, es decir, el derecho a su desarrollo arm\u00f3nico, acorde a su edad f\u00edsica y psicol\u00f3gica. Tres efectos de la perdida de la infancia son peor alfabetizaci\u00f3n, peor educaci\u00f3n y peor sentido del pudor. Un ni\u00f1o sin pudor no aprende a ser due\u00f1o de sus impulsos, queda preso de los instintos. Los impulsos o instintos de agresi\u00f3n y la gratificaci\u00f3n inmediata se disparan y no aprenden a ser due\u00f1os de s\u00ed mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La liberaci\u00f3n sexual que propone este tipo de educaci\u00f3n, lleva a la decadencia cultural, a la ruptura de la familia, a la reducci\u00f3n de logros acad\u00e9micos, a la generaci\u00f3n de trastornos psicol\u00f3gicos. Una sociedad en declive, ya que se naturalizan pr\u00e1cticas sexuales depravadas, bajo el lema de la diversidad sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sexualizaci\u00f3n de los ni\u00f1os atenta contra la autoridad de la familia y la autoridad paterna. Hoy cuando nos hablan de derechos de los ni\u00f1os o enfoque de derechos, incluyen a todos los derechos que los adultos tenemos, pero en favor de la ni\u00f1ez. Al no haber criterio de oportunidad para otorgar estos derechos, incluido el derecho a la sexualidad plena para los chicos, les estamos haciendo un da\u00f1o enorme, ya que no est\u00e1n preparados para manejar estos derechos y lo hacen inadecuadamente. Cuando los padres intervienen para guiar o poner l\u00edmites al hijo, el Estado interpreta que se est\u00e1n vulnerando sus derechos y los progenitores quedan sujetos incluso a la p\u00e9rdida de la patria potestad. Ya hay casos en Paraguay y ni que decir en otros pa\u00edses donde la agenda est\u00e1 m\u00e1s avanzada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hiper sexualizar a los ni\u00f1os va contra su desarrollo hormonal natural, la madurez sexual f\u00edsica es un proceso largo y paulatino y la madurez sexual psicol\u00f3gica es un proceso mucho m\u00e1s largo, pero con la educaci\u00f3n sexual infantil se viola el ritmo biol\u00f3gico natural de estos procesos, creando en los chicos deseos y curiosidad que no corresponden a su edad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La masturbaci\u00f3n frecuente, va ligada a m\u00e1s riesgo de una sexualidad narcisista, en estos cursos de educaci\u00f3n integral de la sexualidad, como se ha constatado en todos los pa\u00edses donde se ha impuesto, a los ni\u00f1os se les anima a experimentar una y otra vez con la masturbaci\u00f3n, sin tener en cuenta que este mal habito lleva f\u00e1cilmente a la adicci\u00f3n y los empuja a la pornograf\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La incertidumbre del g\u00e9nero puede llevar a trastornos de la personalidad, como de hecho ya ocurre en otros pa\u00edses de Europa o en EEUU. Decirles a los ni\u00f1os que pueden optar por el g\u00e9nero con el que se auto perciban, independientemente del sexo con el que nacieron, o que incluso pueden cambiar de sexo, es sembrar incertidumbre en la identidad sexual y eso genera personalidades d\u00e9biles y manipulables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hablar de la homosexualidad a los chicos, sin explicar sus riesgos, los pone en peligro. La conducta homosexual va ligada a mayores tasas de depresi\u00f3n, trastornos de ansiedad, consumo de sustancias, adicciones, riesgo de suicidio y enfermedades de trasmisi\u00f3n sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Proponer a adolescentes, que se afirmen en un g\u00e9nero diferente al biol\u00f3gico atenta contra su desarrollo normal. Los chicos en la adolescencia est\u00e1n formando su identidad, hay estudios que demuestran que el 60% de los adolescentes que a los 17 a\u00f1os sent\u00edan alg\u00fan tipo de atracci\u00f3n hacia personas de su mismo sexo, a los 25 a\u00f1os terminaron identific\u00e1ndose correctamente con su sexo biol\u00f3gico y formando pareja heterosexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La EIS promueve la pedofilia, ya que vuelve m\u00e1s vulnerable a los ni\u00f1os. La EIS supuestamente educa para prevenir el abuso, pero nunca ofrece una soluci\u00f3n a la explotaci\u00f3n sexual. Se dice que la mayor\u00eda de los abusos ocurren en el \u00e1mbito familiar, pues bien, si se quiere proteger al ni\u00f1o, esto no se logra por medio de una educaci\u00f3n sexual ensen\u00e1ndole a perder el pudor. Se deber\u00eda m\u00e1s bien formar a los profesores a reconocer se\u00f1ales de abuso. Ya la Serpaj tiene una denuncia por la promoci\u00f3n de la pedofilia en su anterior Gu\u00eda para docentes sobre educaci\u00f3n integral. (ver p\u00e1g. 162 del citado material).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La EIS es parte del problema de la explotaci\u00f3n sexual, ya que no apunta a educar al ni\u00f1o a reconocer la diferencia entre el amor verdadero y la explotaci\u00f3n sexual, al chico solo se le ense\u00f1a que todo es el derecho de ejercer la propia sexualidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomiendo a los padres leer o seguir a Agust\u00edn Laje, a Pablo Mu\u00f1oz Iturrieta, a la Magister Judith Iturriaga o a otros referentes formados en el tema. Esto no se me ocurre a m\u00ed, lo he le\u00eddo, he asistido a charlas, conferencias, cursos y por sobre todo se condice con la educaci\u00f3n que siempre hemos recibido. Es de sentido com\u00fan, \u00bfo desde cuando la sexualidad temprana, sin compromiso, promiscua o con el mismo sexo hace que las personas sean sanas, maduras, competentes, capaces de compromiso? Para nuestros hijos, exijamos programas basados en ciencias y valores, que respetan la naturaleza del ser humano, no en ideolog\u00edas que buscan amoldar la realidad a sus ideas, sin importar el da\u00f1o y enorme perjuicio que causan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 7 de diciembre pasado SERPAJ, Servicio de Paz y Justicia, anunci\u00f3 el relanzamiento de su Gu\u00eda para docentes y familias sobre Educaci\u00f3n Sexual Integral. S\u00ed, pretenden relanzar el pol\u00e9mico material que en el 2018 fue denunciado por los padres y prohibido por el MEC seg\u00fan resoluci\u00f3n 1761\/2019. Hay que estar atentos al contenido de [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":4976,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[39],"tags":[150,831,1168,341],"jnews-series":[],"ppma_author":[1204],"class_list":["post-4975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-abuso-infantil","tag-destacada","tag-educacion","tag-ministerio-de-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El 7 de diciembre pasado SERPAJ, Servicio de Paz y Justicia, anunci\u00f3 el relanzamiento de su Gu\u00eda para docentes y familias sobre Educaci\u00f3n Sexual Integral. S\u00ed, pretenden relanzar el pol\u00e9mico material que en el 2018 fue denunciado por los padres y prohibido por el MEC seg\u00fan resoluci\u00f3n 1761\/2019. Hay que estar atentos al contenido de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-10T09:24:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/12\/serpaj-esi.png?fit=1280%2C801&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Valeria Insfran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valeria Insfran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/\"},\"author\":{\"name\":\"Valeria Insfran\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/5b8089500d230a38edf670ecc256483e\"},\"headline\":\"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas\",\"datePublished\":\"2021-12-10T09:24:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/\"},\"wordCount\":1936,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/serpaj-esi.png?fit=1280%2C801&ssl=1\",\"keywords\":[\"abuso infantil\",\"destacada\",\"educacion\",\"ministerio de educaci\u00f3n\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/\",\"name\":\"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/serpaj-esi.png?fit=1280%2C801&ssl=1\",\"datePublished\":\"2021-12-10T09:24:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/serpaj-esi.png?fit=1280%2C801&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/serpaj-esi.png?fit=1280%2C801&ssl=1\",\"width\":1280,\"height\":801},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/12\\\/10\\\/serpaj-vuelve-a-las-andanzas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/5b8089500d230a38edf670ecc256483e\",\"name\":\"Valeria Insfran\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Valeria-insfran.jpg54a869e00ca2a1338509f90a0b5bce7f\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Valeria-insfran.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Valeria-insfran.jpg\",\"caption\":\"Valeria Insfran\"},\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/vinsfran\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/","og_locale":"es_ES","og_type":"article","og_title":"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El 7 de diciembre pasado SERPAJ, Servicio de Paz y Justicia, anunci\u00f3 el relanzamiento de su Gu\u00eda para docentes y familias sobre Educaci\u00f3n Sexual Integral. S\u00ed, pretenden relanzar el pol\u00e9mico material que en el 2018 fue denunciado por los padres y prohibido por el MEC seg\u00fan resoluci\u00f3n 1761\/2019. Hay que estar atentos al contenido de [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2021-12-10T09:24:25+00:00","og_image":[{"width":1280,"height":801,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/12\/serpaj-esi.png?fit=1280%2C801&ssl=1","type":"image\/png"}],"author":"Valeria Insfran","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valeria Insfran","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/"},"author":{"name":"Valeria Insfran","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/5b8089500d230a38edf670ecc256483e"},"headline":"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas","datePublished":"2021-12-10T09:24:25+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/"},"wordCount":1936,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/12\/serpaj-esi.png?fit=1280%2C801&ssl=1","keywords":["abuso infantil","destacada","educacion","ministerio de educaci\u00f3n"],"articleSection":["Analisis"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/","url":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/","name":"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/12\/serpaj-esi.png?fit=1280%2C801&ssl=1","datePublished":"2021-12-10T09:24:25+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/12\/serpaj-esi.png?fit=1280%2C801&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/12\/serpaj-esi.png?fit=1280%2C801&ssl=1","width":1280,"height":801},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2021\/12\/10\/serpaj-vuelve-a-las-andanzas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"TRINCHERA PATRIOTA: SERPAJ vuelve a las andanzas"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/5b8089500d230a38edf670ecc256483e","name":"Valeria Insfran","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/Valeria-insfran.jpg54a869e00ca2a1338509f90a0b5bce7f","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/Valeria-insfran.jpg","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/Valeria-insfran.jpg","caption":"Valeria Insfran"},"url":"https:\/\/informatepy.com\/2024\/author\/vinsfran\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/12\/serpaj-esi.png?fit=1280%2C801&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1204,"user_id":20,"is_guest":0,"slug":"vinsfran","display_name":"Valeria Insfran","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/Valeria-insfran.jpg","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/Valeria-insfran.jpg"},"author_category":"1","first_name":"Valeria","last_name":"Insfran","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/4975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=4975"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/4975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/4976"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=4975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=4975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=4975"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=4975"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=4975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}