{"id":458,"date":"2019-03-02T00:19:00","date_gmt":"2019-03-01T23:19:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/"},"modified":"2019-03-02T00:19:00","modified_gmt":"2019-03-01T23:19:00","slug":"gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/","title":{"rendered":"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Agentes policiales intervinieron en el complejo cerrado Costa del Lago Country Club del Este, de la ciudad de Hernandarias, donde constataron destrozos en la lujosa vivienda del gobernador&nbsp;Roberto Gonz\u00e1lez Vaesken, y una grave acusaci\u00f3n en la pared que reza: \u201cNo m\u00e1s org\u00edas con menores\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de escuchar fuertes ruidos, el encargado de seguridad del complejo encontr\u00f3 la puerta violentada y alert\u00f3 a los uniformados. La sospechosa es la esposa del jefe departamental, Darsy Sirley Gonz\u00e1lez de Gonz\u00e1lez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ra\u00edz de la situaci\u00f3n, Gonz\u00e1lez Vaesken se pronunci\u00f3 y en comunicaci\u00f3n conMonumental 1080 AM aleg\u00f3 que el suceso registrado tiene que ver con un problema de pareja. Adem\u00e1s, sostuvo que la divulgaci\u00f3n del caso se tratar\u00eda de una especie de campa\u00f1a manipuladora para da\u00f1ar su imagen<strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9l es l\u00edder del movimiento Colorado A\u00f1etete en el Este del pa\u00eds, y ven\u00eda realizando una campa\u00f1a con miras a las elecciones municipales en Ciudad del Este, luego de la destituci\u00f3n de Sandra McLeod, del clan Zacar\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero se retir\u00f3 de la campa\u00f1a, porque, seg\u00fan percibi\u00f3, a su alrededor existen personas que tienen intereses personales y que podr\u00edan motivar que sigan sucediendo situaciones como esta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cResulta que en esta campa\u00f1a mucha gente va con este tipo de reacciones, pero esto fue algo a nivel de pareja (&#8230;) Alguien le llam\u00f3 a mi esposa y le dijo que yo ando con mujeres de 20 a 25 a\u00f1os\u201d, refiri\u00f3, aunque la pintata en su propiedad menciona a menores de edad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la Ley 1160 del C\u00f3digo Penal, se considera como&nbsp;abuso sexualen ni\u00f1os cuando el acto afecta a menores de hasta 14 a\u00f1os y estupro cuando un hombre persuade a relaci\u00f3n sexual a una adolescente de entre 14 y 16 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consultado sobre la veracidad y la gravedad de la acusaci\u00f3n, el gobernador dijo que la Fiscal\u00eda es la que deber\u00eda encargarse de determinar la situaci\u00f3n e indagar. \u201cYo no tengo nada que esconder\u201d, asegur\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario p\u00fablico manifest\u00f3 que le afecta mucho la situaci\u00f3n, pero insisti\u00f3 en que se trat\u00f3 de una disputa marital.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfAtaque de celos?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la esposa del gobernador tambi\u00e9n convers\u00f3 seguidamente con la misma emisora radial, aprovechando que se encontraba en compa\u00f1\u00eda del gobernador al momento de la entrevista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Darsy Gonz\u00e1lez, quien se desempe\u00f1a como titular de la Secretar\u00eda de Acci\u00f3n Social de la Gobernaci\u00f3n de Alto Paran\u00e1, aclar\u00f3 que fue un ataque de celos lo que la motiv\u00f3 a amedrentar la vivienda de su esposo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo toda mujer casada con alguien que est\u00e1 en campa\u00f1a, estoy rodeada de gente mala que est\u00e1 difamando. Fue una cuesti\u00f3n emotiva y estaba muy nerviosa\u201d, justific\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consultada sobre la inscripci\u00f3n que dej\u00f3 en la pared, Gonz\u00e1lez evit\u00f3 dar declaraciones sobre ello diciendo \u00absin comentarios\u00bb, y argument\u00f3 que se trata de su casa, por lo que puede escribir lo que quiera en ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, indic\u00f3 que no teme a que la Fiscal\u00eda intervenga en el caso y que responder\u00e1 en el tiempo que sea necesario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes policiales intervinieron en el complejo cerrado Costa del Lago Country Club del Este, de la ciudad de Hernandarias, donde constataron destrozos en la lujosa vivienda del gobernador&nbsp;Roberto Gonz\u00e1lez Vaesken, y una grave acusaci\u00f3n en la pared que reza: \u201cNo m\u00e1s org\u00edas con menores\u201d. Luego de escuchar fuertes ruidos, el encargado de seguridad del complejo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":459,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[279,280,299],"jnews-series":[],"ppma_author":[47],"class_list":["post-458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-alto-parana","tag-colorado-anetete","tag-roberto-gonzalez-vaesken"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Agentes policiales intervinieron en el complejo cerrado Costa del Lago Country Club del Este, de la ciudad de Hernandarias, donde constataron destrozos en la lujosa vivienda del gobernador&nbsp;Roberto Gonz\u00e1lez Vaesken, y una grave acusaci\u00f3n en la pared que reza: \u201cNo m\u00e1s org\u00edas con menores\u201d. Luego de escuchar fuertes ruidos, el encargado de seguridad del complejo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-01T23:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/03\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicoCPT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicoCPT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/\"},\"author\":{\"name\":\"NicoCPT\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\"},\"headline\":\"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja\",\"datePublished\":\"2019-03-01T23:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1\",\"keywords\":[\"alto paran\u00e1\",\"colorado a\u00f1etete\",\"Roberto Gonz\u00e1lez Vaesken\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/\",\"name\":\"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1\",\"datePublished\":\"2019-03-01T23:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1\",\"width\":730,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/03\\\/02\\\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\",\"name\":\"NicoCPT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"NicoCPT\"},\"sameAs\":[\"https:\\\/\\\/informatepy.com\\\/2024\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/nicocpt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/","og_locale":"es_ES","og_type":"article","og_title":"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Agentes policiales intervinieron en el complejo cerrado Costa del Lago Country Club del Este, de la ciudad de Hernandarias, donde constataron destrozos en la lujosa vivienda del gobernador&nbsp;Roberto Gonz\u00e1lez Vaesken, y una grave acusaci\u00f3n en la pared que reza: \u201cNo m\u00e1s org\u00edas con menores\u201d. Luego de escuchar fuertes ruidos, el encargado de seguridad del complejo [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2019-03-01T23:19:00+00:00","og_image":[{"width":730,"height":484,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/03\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1","type":"image\/jpeg"}],"author":"NicoCPT","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"NicoCPT","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/"},"author":{"name":"NicoCPT","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e"},"headline":"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja","datePublished":"2019-03-01T23:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/"},"wordCount":551,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/03\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1","keywords":["alto paran\u00e1","colorado a\u00f1etete","Roberto Gonz\u00e1lez Vaesken"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/","url":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/","name":"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/03\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1","datePublished":"2019-03-01T23:19:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/03\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/03\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1","width":730,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2019\/03\/02\/gobernador-de-alto-parana-niega-orgia-con-menores-y-alega-conflicto-de-pareja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Gobernador de Alto Paran\u00e1 niega org\u00eda con menores y alega conflicto de pareja"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e","name":"NicoCPT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"NicoCPT"},"sameAs":["https:\/\/informatepy.com\/2024"],"url":"https:\/\/informatepy.com\/2024\/author\/nicocpt\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/03\/Roberto-GonzC3A1lez-Vaesken.jpg?fit=730%2C484&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":47,"user_id":1,"is_guest":0,"slug":"nicocpt","display_name":"NicoCPT","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"https:\/\/informatepy.com\/2024","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=458"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/459"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=458"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=458"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}