{"id":39345,"date":"2026-06-10T00:00:00","date_gmt":"2026-06-10T03:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=39345"},"modified":"2026-06-10T06:36:57","modified_gmt":"2026-06-10T09:36:57","slug":"el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/","title":{"rendered":"El MEC apuesta por fortalecer la lectura y los valores desde la familia"},"content":{"rendered":"<p class=\"isSelectedEnd\">Con el objetivo de llevar materiales de lectura a m\u00e1s de 1.200.000 estudiantes de la Educaci\u00f3n B\u00e1sica de instituciones oficiales y privadas subvencionadas, el Ministerio de Educaci\u00f3n y Ciencias (MEC) puso en marcha la distribuci\u00f3n de los nuevos Portafolios de Lectura, una iniciativa que busca fortalecer la comprensi\u00f3n lectora, el pensamiento cr\u00edtico y el v\u00ednculo de los ni\u00f1os con la cultura paraguaya.<\/p>\n<p class=\"isSelectedEnd\">El lanzamiento oficial se realiz\u00f3 en el Puerto de Asunci\u00f3n, en el marco del Programa de Lectura, Escritura y Oralidad \u00d1e\u2019\u1ebdry, y cont\u00f3 con la presencia del presidente de la Rep\u00fablica, Santiago Pe\u00f1a; la Primera Dama, Leticia Ocampos; el ministro de Educaci\u00f3n y Ciencias, Luis Fernando Ram\u00edrez; el director de la Organizaci\u00f3n de Estados Iberoamericanos (OEI) en Paraguay, Germ\u00e1n Garc\u00eda da Rosa, adem\u00e1s de autoridades educativas y representantes de diversos sectores.<\/p>\n<p class=\"isSelectedEnd\">La iniciativa contempla la entrega de cuentos y cuadernillos destinados a estudiantes desde el nivel Inicial hasta el noveno grado. Los materiales fueron concebidos como un complemento de los kits escolares distribuidos al inicio del a\u00f1o lectivo y buscan extender la experiencia educativa m\u00e1s all\u00e1 de las aulas.<\/p>\n<p class=\"isSelectedEnd\">Durante el acto, el presidente Santiago Pe\u00f1a destac\u00f3 el papel de la familia en la formaci\u00f3n de los ni\u00f1os y j\u00f3venes, se\u00f1alando que la lectura debe convertirse en una herramienta de encuentro dentro del hogar.<\/p>\n<p class=\"isSelectedEnd\">\u201cEl prop\u00f3sito de estos portafolios va m\u00e1s all\u00e1 del aula, de la escuela. Queremos que estos libros lleguen a los hogares y generen conversaciones con la familia, que despierten la curiosidad y se conviertan en compa\u00f1eros de viaje de nuestros ni\u00f1os y j\u00f3venes, porque la educaci\u00f3n comienza en el hogar, en los cuentos que escuchamos, en conversaciones familiares y en los valores que aprendemos en la casa\u201d, expres\u00f3.<\/p>\n<p class=\"isSelectedEnd\">La propuesta educativa apunta no solo a mejorar los niveles de lectura, sino tambi\u00e9n a fortalecer contenidos vinculados a la identidad nacional, la historia y las tradiciones paraguayas, promoviendo una mayor participaci\u00f3n de las familias en los procesos de aprendizaje.<\/p>\n<p class=\"isSelectedEnd\">En ese sentido, el ministro Luis Fernando Ram\u00edrez explic\u00f3 que el proyecto busca que los libros formen parte de la vida cotidiana de los estudiantes y de sus hogares.<\/p>\n<p class=\"isSelectedEnd\">\u201cLas escuelas ya tienen libros y ahora queremos que las casas tambi\u00e9n. Necesitamos que nuestros ni\u00f1os interact\u00faen en casa con mam\u00e1, con pap\u00e1, por eso les damos cuentos con historias educativas, libros para los m\u00e1s peque\u00f1itos y que podamos contar historias paraguayas, que tienen que ver con nuestra cultura y con nuestra idiosincrasia\u201d, manifest\u00f3.<\/p>\n<p class=\"isSelectedEnd\">Ram\u00edrez sostuvo adem\u00e1s que la educaci\u00f3n constituye una de las inversiones m\u00e1s trascendentes que puede realizar una sociedad, al tratarse de una construcci\u00f3n que impacta directamente en las futuras generaciones.<\/p>\n<p class=\"isSelectedEnd\">\u201cA veces ponderamos los puentes y los edificios, pero el edificio que estamos construyendo hoy es uno que nunca desaparece: la construcci\u00f3n de ciudadanos, de personas, de un ser humano que va a poder trascender, conectarse con el mundo, consigo mismo, llevar al Paraguay a eso que tanto anhelamos, que es entender que somos un gigante que est\u00e1 dormido. Con los libros, Paraguay se pone de pie y el gigante va a resurgir con todo\u201d, concluy\u00f3.<\/p>\n<p>Con esta iniciativa, el MEC busca consolidar una pol\u00edtica educativa que promueva el h\u00e1bito de la lectura desde edades tempranas y que convierta a los hogares en protagonistas del proceso de formaci\u00f3n de los estudiantes, fortaleciendo al mismo tiempo los valores, la cultura y la identidad nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de llevar materiales de lectura a m\u00e1s de 1.200.000 estudiantes de la Educaci\u00f3n B\u00e1sica de instituciones oficiales y privadas subvencionadas, el Ministerio de Educaci\u00f3n y Ciencias (MEC) puso en marcha la distribuci\u00f3n de los nuevos Portafolios de Lectura, una iniciativa que busca fortalecer la comprensi\u00f3n lectora, el pensamiento cr\u00edtico y el v\u00ednculo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":1,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","jnews_video_option_group":[[]],"override":[{"template":"2","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":""},"jnews_primary_category":[],"jnews_override_bookmark_settings":{"override_bookmark_button":"0","override_show_bookmark_button":"0"},"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":{"paragraph_limit":"2","enable_premium_post":"0","enable_free_post":"0","override_paragraph_limit":"0","enable_preview_post":"0","enable_preview_video":"0"},"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[831,1772,667,341,374,2449],"jnews-series":[],"ppma_author":[830],"class_list":["post-39345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-luis-ramirez","tag-mec","tag-ministerio-de-educacion","tag-santiago-pena","tag-santiago-pena-palacios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El MEC apuesta por fortalecer la lectura y los valores desde la familia - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El MEC apuesta por fortalecer la lectura y los valores desde la familia - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Con el objetivo de llevar materiales de lectura a m\u00e1s de 1.200.000 estudiantes de la Educaci\u00f3n B\u00e1sica de instituciones oficiales y privadas subvencionadas, el Ministerio de Educaci\u00f3n y Ciencias (MEC) puso en marcha la distribuci\u00f3n de los nuevos Portafolios de Lectura, una iniciativa que busca fortalecer la comprensi\u00f3n lectora, el pensamiento cr\u00edtico y el v\u00ednculo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-10T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T09:36:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/06\/entrega-de-libros-mec1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"El MEC apuesta por fortalecer la lectura y los valores desde la familia\",\"datePublished\":\"2026-06-10T03:00:00+00:00\",\"dateModified\":\"2026-06-10T09:36:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/\"},\"wordCount\":621,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1\",\"keywords\":[\"destacada\",\"luis ramirez\",\"mec\",\"ministerio de educaci\u00f3n\",\"santiago pe\u00f1a\",\"Santiago Pe\u00f1a Palacios\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/\",\"name\":\"El MEC apuesta por fortalecer la lectura y los valores desde la familia - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1\",\"datePublished\":\"2026-06-10T03:00:00+00:00\",\"dateModified\":\"2026-06-10T09:36:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1\",\"width\":1200,\"height\":654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/06\\\/10\\\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El MEC apuesta por fortalecer la lectura y los valores desde la familia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El MEC apuesta por fortalecer la lectura y los valores desde la familia - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/","og_locale":"es_ES","og_type":"article","og_title":"El MEC apuesta por fortalecer la lectura y los valores desde la familia - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Con el objetivo de llevar materiales de lectura a m\u00e1s de 1.200.000 estudiantes de la Educaci\u00f3n B\u00e1sica de instituciones oficiales y privadas subvencionadas, el Ministerio de Educaci\u00f3n y Ciencias (MEC) puso en marcha la distribuci\u00f3n de los nuevos Portafolios de Lectura, una iniciativa que busca fortalecer la comprensi\u00f3n lectora, el pensamiento cr\u00edtico y el v\u00ednculo [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2026-06-10T03:00:00+00:00","article_modified_time":"2026-06-10T09:36:57+00:00","og_image":[{"width":1200,"height":654,"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/06\/entrega-de-libros-mec1.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"El MEC apuesta por fortalecer la lectura y los valores desde la familia","datePublished":"2026-06-10T03:00:00+00:00","dateModified":"2026-06-10T09:36:57+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/"},"wordCount":621,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/06\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1","keywords":["destacada","luis ramirez","mec","ministerio de educaci\u00f3n","santiago pe\u00f1a","Santiago Pe\u00f1a Palacios"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/","url":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/","name":"El MEC apuesta por fortalecer la lectura y los valores desde la familia - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/06\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1","datePublished":"2026-06-10T03:00:00+00:00","dateModified":"2026-06-10T09:36:57+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/06\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/06\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1","width":1200,"height":654},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2026\/06\/10\/el-mec-apuesta-por-fortalecer-la-lectura-y-los-valores-desde-la-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"El MEC apuesta por fortalecer la lectura y los valores desde la familia"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/06\/entrega-de-libros-mec1.jpg?fit=1200%2C654&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/39345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=39345"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/39345\/revisions"}],"predecessor-version":[{"id":39347,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/39345\/revisions\/39347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/39346"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=39345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=39345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=39345"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=39345"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=39345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}