{"id":38751,"date":"2026-05-10T00:00:00","date_gmt":"2026-05-10T03:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=38751"},"modified":"2026-05-09T19:38:02","modified_gmt":"2026-05-09T22:38:02","slug":"jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/","title":{"rendered":"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En Villarrica se llev\u00f3 a cabo la<strong> quinta asamblea del Comit\u00e9 de J\u00f3venes Cooperativistas de la Confederaci\u00f3n de Cooperativas Rurales del Paraguay<\/strong> <strong>(CONCOPAR Ltda.)<\/strong>, con sede en la <strong>Cerecoop Ltda<\/strong>., donde se desarroll\u00f3 un encuentro orientado a fortalecer el liderazgo juvenil dentro del movimiento cooperativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la jornada, se realiz\u00f3 la incorporaci\u00f3n de los nuevos representantes titulares y suplentes de las entidades socias, quienes formar\u00e1n parte del <strong>comit\u00e9 en el periodo 2026-2027. <\/strong>Para este nuevo ciclo, la conducci\u00f3n estar\u00e1 a cargo de <strong>CECOI<\/strong>, <strong>Cenconori Ltda<\/strong>. y <strong>Unicoop<\/strong> <strong>Ltda<\/strong>., que asumir\u00e1n el desaf\u00edo de liderar las iniciativas del sector joven.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde <strong>CONCOPAR <\/strong>destacaron la importancia de <strong>seguir impulsando la participaci\u00f3n de las nuevas generaciones en el cooperativismo, promoviendo proyectos que reflejen el potencial del modelo como motor de desarrollo econ\u00f3mico y social en Paraguay.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro reafirm\u00f3 el compromiso del sector juvenil con el fortalecimiento institucional y la generaci\u00f3n de propuestas innovadoras que contribuyan al crecimiento sostenible del cooperativismo en el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Villarrica se llev\u00f3 a cabo la quinta asamblea del Comit\u00e9 de J\u00f3venes Cooperativistas de la Confederaci\u00f3n de Cooperativas Rurales del Paraguay (CONCOPAR Ltda.), con sede en la Cerecoop Ltda., donde se desarroll\u00f3 un encuentro orientado a fortalecer el liderazgo juvenil dentro del movimiento cooperativo. Durante la jornada, se realiz\u00f3 la incorporaci\u00f3n de los nuevos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":5,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[2634,2633,1854,1761,2026,831,2435,2359,2262],"jnews-series":[],"ppma_author":[830],"class_list":["post-38751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-cecoi","tag-cenconori","tag-concopar","tag-cooperativas","tag-cooperativismo","tag-destacada","tag-noticias-de-cooperativismo","tag-noticias-de-paraguay","tag-unicoop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En Villarrica se llev\u00f3 a cabo la quinta asamblea del Comit\u00e9 de J\u00f3venes Cooperativistas de la Confederaci\u00f3n de Cooperativas Rurales del Paraguay (CONCOPAR Ltda.), con sede en la Cerecoop Ltda., donde se desarroll\u00f3 un encuentro orientado a fortalecer el liderazgo juvenil dentro del movimiento cooperativo. Durante la jornada, se realiz\u00f3 la incorporaci\u00f3n de los nuevos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-10T03:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar\",\"datePublished\":\"2026-05-10T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/\"},\"wordCount\":181,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1\",\"keywords\":[\"cecoi\",\"cenconori\",\"concopar\",\"cooperativas\",\"cooperativismo\",\"destacada\",\"noticias de cooperativismo\",\"noticias de paraguay\",\"unicoop\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/\",\"name\":\"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1\",\"datePublished\":\"2026-05-10T03:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1\",\"width\":1200,\"height\":672},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/05\\\/10\\\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/","og_locale":"es_ES","og_type":"article","og_title":"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En Villarrica se llev\u00f3 a cabo la quinta asamblea del Comit\u00e9 de J\u00f3venes Cooperativistas de la Confederaci\u00f3n de Cooperativas Rurales del Paraguay (CONCOPAR Ltda.), con sede en la Cerecoop Ltda., donde se desarroll\u00f3 un encuentro orientado a fortalecer el liderazgo juvenil dentro del movimiento cooperativo. Durante la jornada, se realiz\u00f3 la incorporaci\u00f3n de los nuevos [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2026-05-10T03:00:00+00:00","og_image":[{"width":1200,"height":672,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar","datePublished":"2026-05-10T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/"},"wordCount":181,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1","keywords":["cecoi","cenconori","concopar","cooperativas","cooperativismo","destacada","noticias de cooperativismo","noticias de paraguay","unicoop"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/","url":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/","name":"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1","datePublished":"2026-05-10T03:00:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1","width":1200,"height":672},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2026\/05\/10\/jovenes-cooperativistas-renovaron-autoridades-en-asamblea-de-concopar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"J\u00f3venes cooperativistas renovaron autoridades en asamblea de Concopar"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/05\/elecciones-jovenes-concopar-2026.jpg?fit=1200%2C672&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/38751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=38751"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/38751\/revisions"}],"predecessor-version":[{"id":38752,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/38751\/revisions\/38752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/38763"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=38751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=38751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=38751"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=38751"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=38751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}