{"id":36669,"date":"2026-01-20T10:23:32","date_gmt":"2026-01-20T13:23:32","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=36669"},"modified":"2026-01-20T10:23:37","modified_gmt":"2026-01-20T13:23:37","slug":"cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/","title":{"rendered":"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El <strong>Ministerio de Salud P\u00fablica y Bienestar Social <\/strong>sum\u00f3 cinco simuladores de reanimaci\u00f3n cardiopulmonar (RCP) al <strong>Instituto Nacional de Salud (INS)<\/strong>, como resultado de una cooperaci\u00f3n con la <strong>Embajada del Estado de Israel en Paraguay<\/strong>, destinada a fortalecer la formaci\u00f3n del personal sanitario en la atenci\u00f3n de emergencias vitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entrega se realiz\u00f3 en un acto que cont\u00f3 con la participaci\u00f3n de la ministra de Salud P\u00fablica y Bienestar Social, <strong>Dra. Mar\u00eda Teresa Bar\u00e1n Wasilchuk<\/strong>, y del embajador extraordinario y plenipotenciario del Estado de Israel en Paraguay, <strong>Amit Mekel<\/strong>, junto a autoridades del nivel central de la instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los nuevos equipos permitir\u00e1n la realizaci\u00f3n de capacitaciones y talleres pr\u00e1cticos de RCP para profesionales de todas las regiones sanitarias, a trav\u00e9s de la simulaci\u00f3n realista de situaciones de paro cardiorrespiratorio. Estos simuladores ofrecen retroalimentaci\u00f3n objetiva sobre aspectos fundamentales como la profundidad y el ritmo de las compresiones, as\u00ed como la ventilaci\u00f3n, promoviendo un aprendizaje seguro, estandarizado y basado en competencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el acto, la ministra <strong>Bar\u00e1n <\/strong>resalt\u00f3 el valor de esta cooperaci\u00f3n para mejorar la calidad de la formaci\u00f3n del talento humano en salud. S<strong>e\u00f1al\u00f3 que, para el Gobierno del Paraguay, la entrega representa un aporte significativo y un honor, en el marco de un a\u00f1o de estrecha colaboraci\u00f3n en materia de salud entre Paraguay e Israel,<\/strong> que permitir\u00e1 reforzar las capacidades ya existentes en el Instituto Nacional de Salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fortalecimiento de la capacitaci\u00f3n en reanimaci\u00f3n cardiopulmonar tiene un impacto directo en la atenci\u00f3n de emergencias, optimiza la capacidad de respuesta del sistema sanitario y contribuye a la reducci\u00f3n de muertes evitables. El INS cumple un rol clave como centro de referencia nacional para la formaci\u00f3n continua del personal de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su turno, el embajador <strong>Amit Mekel <\/strong>destac\u00f3 la relevancia de la cooperaci\u00f3n bilateral en el \u00e1mbito de la salud y <strong>manifest\u00f3 el inter\u00e9s de seguir profundizando el trabajo conjunto entre ambos pa\u00edses en este sector estrat\u00e9gico.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n participaron del acto el <strong>Dr. Sa\u00fal Recalde<\/strong>, viceministro de Atenci\u00f3n Integral a la Salud; la <strong>Dra. Adriana Amarilla<\/strong>, directora general de Relaciones Internacionales; y la <strong>Dra. Cristina Caballero<\/strong>, directora general del Instituto Nacional de Salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Salud P\u00fablica y Bienestar Social sum\u00f3 cinco simuladores de reanimaci\u00f3n cardiopulmonar (RCP) al Instituto Nacional de Salud (INS), como resultado de una cooperaci\u00f3n con la Embajada del Estado de Israel en Paraguay, destinada a fortalecer la formaci\u00f3n del personal sanitario en la atenci\u00f3n de emergencias vitales. La entrega se realiz\u00f3 en un [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":36670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[2344,831,250,1855,178,2357,2359,2414,92],"jnews-series":[],"ppma_author":[830],"class_list":["post-36669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-amit-mekel","tag-destacada","tag-israel","tag-maria-teresa-baran","tag-ministerio-de-salud","tag-noticias-de-israel","tag-noticias-de-paraguay","tag-noticias-de-salud","tag-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Salud P\u00fablica y Bienestar Social sum\u00f3 cinco simuladores de reanimaci\u00f3n cardiopulmonar (RCP) al Instituto Nacional de Salud (INS), como resultado de una cooperaci\u00f3n con la Embajada del Estado de Israel en Paraguay, destinada a fortalecer la formaci\u00f3n del personal sanitario en la atenci\u00f3n de emergencias vitales. La entrega se realiz\u00f3 en un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T13:23:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T13:23:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/01\/baran-mekel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud\",\"datePublished\":\"2026-01-20T13:23:32+00:00\",\"dateModified\":\"2026-01-20T13:23:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/\"},\"wordCount\":405,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/baran-mekel.jpg?fit=870%2C522&ssl=1\",\"keywords\":[\"amit mekel\",\"destacada\",\"israel\",\"maria teresa baran\",\"ministerio de salud\",\"noticias de israel\",\"noticias de paraguay\",\"noticias de salud\",\"salud\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/\",\"name\":\"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/baran-mekel.jpg?fit=870%2C522&ssl=1\",\"datePublished\":\"2026-01-20T13:23:32+00:00\",\"dateModified\":\"2026-01-20T13:23:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/baran-mekel.jpg?fit=870%2C522&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/baran-mekel.jpg?fit=870%2C522&ssl=1\",\"width\":870,\"height\":522},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2026\\\/01\\\/20\\\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/","og_locale":"es_ES","og_type":"article","og_title":"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El Ministerio de Salud P\u00fablica y Bienestar Social sum\u00f3 cinco simuladores de reanimaci\u00f3n cardiopulmonar (RCP) al Instituto Nacional de Salud (INS), como resultado de una cooperaci\u00f3n con la Embajada del Estado de Israel en Paraguay, destinada a fortalecer la formaci\u00f3n del personal sanitario en la atenci\u00f3n de emergencias vitales. La entrega se realiz\u00f3 en un [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2026-01-20T13:23:32+00:00","article_modified_time":"2026-01-20T13:23:37+00:00","og_image":[{"width":870,"height":522,"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/01\/baran-mekel.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud","datePublished":"2026-01-20T13:23:32+00:00","dateModified":"2026-01-20T13:23:37+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/"},"wordCount":405,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/01\/baran-mekel.jpg?fit=870%2C522&ssl=1","keywords":["amit mekel","destacada","israel","maria teresa baran","ministerio de salud","noticias de israel","noticias de paraguay","noticias de salud","salud"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/","url":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/","name":"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/01\/baran-mekel.jpg?fit=870%2C522&ssl=1","datePublished":"2026-01-20T13:23:32+00:00","dateModified":"2026-01-20T13:23:37+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/01\/baran-mekel.jpg?fit=870%2C522&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/01\/baran-mekel.jpg?fit=870%2C522&ssl=1","width":870,"height":522},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2026\/01\/20\/cooperacion-paraguay-israel-impulsa-la-capacitacion-en-rcp-en-el-instituto-nacional-de-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Cooperaci\u00f3n Paraguay\u2013Israel impulsa la capacitaci\u00f3n en RCP en el Instituto Nacional de Salud"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2026\/01\/baran-mekel.jpg?fit=870%2C522&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/36669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=36669"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/36669\/revisions"}],"predecessor-version":[{"id":36671,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/36669\/revisions\/36671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/36670"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=36669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=36669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=36669"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=36669"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=36669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}