{"id":34623,"date":"2025-09-27T10:06:00","date_gmt":"2025-09-27T13:06:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=34623"},"modified":"2025-09-27T11:11:41","modified_gmt":"2025-09-27T14:11:41","slug":"la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/","title":{"rendered":"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La <strong>Embajada de la Rep\u00fablica de China (Taiw\u00e1n)<\/strong> invita cordialmente al p\u00fablico a participar de la <strong>Expo Orqu\u00eddeas<\/strong>, que se realizar\u00e1 en el <strong>Olmi Hall Events<\/strong> de <strong>Encarnaci\u00f3n<\/strong>, en un horario de <strong>9:00 a 21:00<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La exposici\u00f3n ofrece una oportunidad \u00fanica para celebrar la <strong>primavera<\/strong> rodeado de la belleza y diversidad de estas delicadas flores. La actividad estar\u00e1 abierta hasta el <strong>29 de septiembre<\/strong>, permitiendo a visitantes de todas las edades disfrutar de un ambiente colorido y lleno de naturaleza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Embajada de la Rep\u00fablica de China (Taiw\u00e1n) invita cordialmente al p\u00fablico a participar de la Expo Orqu\u00eddeas, que se realizar\u00e1 en el Olmi Hall Events de Encarnaci\u00f3n, en un horario de 9:00 a 21:00. La exposici\u00f3n ofrece una oportunidad \u00fanica para celebrar la primavera rodeado de la belleza y diversidad de estas delicadas flores. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":1,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43],"tags":[831,839,2359,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-34623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-destacada","tag-encarnacion","tag-noticias-de-paraguay","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"La Embajada de la Rep\u00fablica de China (Taiw\u00e1n) invita cordialmente al p\u00fablico a participar de la Expo Orqu\u00eddeas, que se realizar\u00e1 en el Olmi Hall Events de Encarnaci\u00f3n, en un horario de 9:00 a 21:00. La exposici\u00f3n ofrece una oportunidad \u00fanica para celebrar la primavera rodeado de la belleza y diversidad de estas delicadas flores. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-27T13:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-27T14:11:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2025\/09\/orquideas-taiwan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n\",\"datePublished\":\"2025-09-27T13:06:00+00:00\",\"dateModified\":\"2025-09-27T14:11:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/\"},\"wordCount\":97,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1\",\"keywords\":[\"destacada\",\"encarnacion\",\"noticias de paraguay\",\"taiwan\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/\",\"name\":\"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1\",\"datePublished\":\"2025-09-27T13:06:00+00:00\",\"dateModified\":\"2025-09-27T14:11:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1\",\"width\":1200,\"height\":668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/09\\\/27\\\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/","og_locale":"es_ES","og_type":"article","og_title":"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"La Embajada de la Rep\u00fablica de China (Taiw\u00e1n) invita cordialmente al p\u00fablico a participar de la Expo Orqu\u00eddeas, que se realizar\u00e1 en el Olmi Hall Events de Encarnaci\u00f3n, en un horario de 9:00 a 21:00. La exposici\u00f3n ofrece una oportunidad \u00fanica para celebrar la primavera rodeado de la belleza y diversidad de estas delicadas flores. [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2025-09-27T13:06:00+00:00","article_modified_time":"2025-09-27T14:11:41+00:00","og_image":[{"width":1200,"height":668,"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2025\/09\/orquideas-taiwan.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n","datePublished":"2025-09-27T13:06:00+00:00","dateModified":"2025-09-27T14:11:41+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/"},"wordCount":97,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/09\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1","keywords":["destacada","encarnacion","noticias de paraguay","taiwan"],"articleSection":["Cultura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/","url":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/","name":"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/09\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1","datePublished":"2025-09-27T13:06:00+00:00","dateModified":"2025-09-27T14:11:41+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/09\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/09\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1","width":1200,"height":668},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2025\/09\/27\/la-embajada-de-taiwan-invita-a-la-expo-orquideas-en-encarnacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"La Embajada de Taiw\u00e1n invita a la Expo Orqu\u00eddeas en Encarnaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/09\/orquideas-taiwan.jpg?fit=1200%2C668&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/34623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=34623"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/34623\/revisions"}],"predecessor-version":[{"id":34625,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/34623\/revisions\/34625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/34624"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=34623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=34623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=34623"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=34623"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=34623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}