{"id":32271,"date":"2025-06-09T00:00:00","date_gmt":"2025-06-09T03:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=32271"},"modified":"2025-06-09T08:16:02","modified_gmt":"2025-06-09T11:16:02","slug":"fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/","title":{"rendered":"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En un acto cargado de emoci\u00f3n y sentido de pertenencia, la <strong>Federaci\u00f3n de Cooperativas de Producci\u00f3n (Fecoprod Ltda.)<\/strong> y la <strong>Cooperativa La Holanda<\/strong> rindieron homenaje al trabajo incansable de los productores lecheros, destacando su rol clave en el desarrollo econ\u00f3mico y social del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el evento, <strong>Alfred Fast<\/strong>, presidente de Fecoprod Ltda., resalt\u00f3 la magnitud del impacto que tiene el sector:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">\u201cLa cadena l\u00e1ctea genera un mill\u00f3n de d\u00f3lares diarios solo en producci\u00f3n primaria\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fast tambi\u00e9n dedic\u00f3 palabras de reconocimiento a la dedicaci\u00f3n de los trabajadores del campo:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">\u201cLos tamberos trabajan sin descanso, sin importar lluvia, fr\u00edo o calor. Esa constancia es la base del crecimiento del sector.\u201d<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, valor\u00f3 el rol esencial de las cooperativas en el equilibrio del sistema:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cLas cooperativas permiten que el productor reciba un precio justo y el consumidor acceda a calidad. Este modelo es una de nuestras mayores fortalezas.\u201d<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el coraz\u00f3n de la producci\u00f3n, la tambera <strong>Eva Gim\u00e9nez<\/strong> comparti\u00f3 su experiencia cotidiana:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">\u201cLa leche es un alimento noble, directo del orde\u00f1e, pero con gran responsabilidad en higiene y sanidad. Cumplir con los est\u00e1ndares nos permite sostener relaciones comerciales justas y estables.\u201d<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El acto culmin\u00f3 con un <strong>brindis simb\u00f3lico con leche<\/strong>, un recorrido por el tambo que permiti\u00f3 a los presentes conocer de cerca la realidad productiva, y un almuerzo de confraternidad que reafirm\u00f3 los lazos entre productores, cooperativistas y referentes del sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada no solo fue un reconocimiento al esfuerzo, sino tambi\u00e9n un llamado a proyectar el futuro con la solidez del cooperativismo como pilar fundamental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un acto cargado de emoci\u00f3n y sentido de pertenencia, la Federaci\u00f3n de Cooperativas de Producci\u00f3n (Fecoprod Ltda.) y la Cooperativa La Holanda rindieron homenaje al trabajo incansable de los productores lecheros, destacando su rol clave en el desarrollo econ\u00f3mico y social del pa\u00eds. Durante el evento, Alfred Fast, presidente de Fecoprod Ltda., resalt\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":2,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"2","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"0","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[46],"tags":[1757,1761,2026,831,1750],"jnews-series":[],"ppma_author":[830],"class_list":["post-32271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-alfred-fast","tag-cooperativas","tag-cooperativismo","tag-destacada","tag-fecoprod"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En un acto cargado de emoci\u00f3n y sentido de pertenencia, la Federaci\u00f3n de Cooperativas de Producci\u00f3n (Fecoprod Ltda.) y la Cooperativa La Holanda rindieron homenaje al trabajo incansable de los productores lecheros, destacando su rol clave en el desarrollo econ\u00f3mico y social del pa\u00eds. Durante el evento, Alfred Fast, presidente de Fecoprod Ltda., resalt\u00f3 la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T03:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T11:16:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2025\/06\/alfred-fast-la-holando.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"698\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros\",\"datePublished\":\"2025-06-09T03:00:00+00:00\",\"dateModified\":\"2025-06-09T11:16:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1\",\"keywords\":[\"Alfred Fast\",\"cooperativas\",\"cooperativismo\",\"destacada\",\"fecoprod\"],\"articleSection\":[\"Negocios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/\",\"name\":\"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1\",\"datePublished\":\"2025-06-09T03:00:00+00:00\",\"dateModified\":\"2025-06-09T11:16:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1\",\"width\":1200,\"height\":698},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/06\\\/09\\\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/","og_locale":"es_ES","og_type":"article","og_title":"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En un acto cargado de emoci\u00f3n y sentido de pertenencia, la Federaci\u00f3n de Cooperativas de Producci\u00f3n (Fecoprod Ltda.) y la Cooperativa La Holanda rindieron homenaje al trabajo incansable de los productores lecheros, destacando su rol clave en el desarrollo econ\u00f3mico y social del pa\u00eds. Durante el evento, Alfred Fast, presidente de Fecoprod Ltda., resalt\u00f3 la [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2025-06-09T03:00:00+00:00","article_modified_time":"2025-06-09T11:16:02+00:00","og_image":[{"width":1200,"height":698,"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2025\/06\/alfred-fast-la-holando.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros","datePublished":"2025-06-09T03:00:00+00:00","dateModified":"2025-06-09T11:16:02+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/06\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1","keywords":["Alfred Fast","cooperativas","cooperativismo","destacada","fecoprod"],"articleSection":["Negocios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/","url":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/","name":"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/06\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1","datePublished":"2025-06-09T03:00:00+00:00","dateModified":"2025-06-09T11:16:02+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/06\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/06\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1","width":1200,"height":698},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2025\/06\/09\/fecoprod-y-la-holanda-rindieron-homenaje-al-esfuerzo-diario-de-los-productores-lecheros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Fecoprod y La Holanda rindieron homenaje al esfuerzo diario de los productores lecheros"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2025\/06\/alfred-fast-la-holando.jpg?fit=1200%2C698&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/32271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=32271"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/32271\/revisions"}],"predecessor-version":[{"id":32273,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/32271\/revisions\/32273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/32272"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=32271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=32271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=32271"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=32271"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=32271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}