{"id":3191,"date":"2021-06-25T23:26:24","date_gmt":"2021-06-25T21:26:24","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/"},"modified":"2021-06-25T23:26:24","modified_gmt":"2021-06-25T21:26:24","slug":"atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/","title":{"rendered":"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo"},"content":{"rendered":"\n<p>El helic\u00f3ptero del presidente colombiano, Iv\u00e1n Duque, fue atacado esta tarde en pleno vuelo. El presidente, quien iba con su comitiva, aseguraron que no hubo heridos. <\/p>\n\n\n\n<p>El hecho se produjo una semana despu\u00e9s de que una Brigada del Ej\u00e9rcito fuera atacada y dejara al menos 36 heridos. <\/p>\n\n\n\n<p>A bordo de la aeronave, que recibi\u00f3 cinco impactos, estaban los ministros de Defensa y del Interior. <\/p>\n\n\n\n<p>El presidente Iv\u00e1n Duque se\u00f1al\u00f3 que <em><strong>\u201cQuiero informar al pa\u00eds que luego de cumplir compromiso en Sardinata el helic\u00f3ptero fue victima de un atentado. Tanto el dispositivo a\u00e9reo como la capacidad de la aeronave evitaron que ocurriera algo letal. Lo cierto es que es un hecho cobarde. Como gobierno no vamos a desfallecer en la lucha contra el narcotr\u00e1fico, terrorismo y criminalidad organizada que operan en el pa\u00eds. No nos amedrentan con violencia. Nuestro estado es fuerte para enfrentar estas amenazas. Seguiremos demostrando que el estado hace presencia en todo el territorio. He dado instrucciones de ir en contra de quienes pusieron en riesgo la vida de otras personas. Colombia sigue siempre fuerte enfrentando la criminalidad\u201d.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El helic\u00f3ptero del presidente colombiano, Iv\u00e1n Duque, fue atacado esta tarde en pleno vuelo. El presidente, quien iba con su comitiva, aseguraron que no hubo heridos. El hecho se produjo una semana despu\u00e9s de que una Brigada del Ej\u00e9rcito fuera atacada y dejara al menos 36 heridos. A bordo de la aeronave, que recibi\u00f3 cinco [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[41,33],"tags":[1088,831,591],"jnews-series":[],"ppma_author":[830],"class_list":["post-3191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-mundo","tag-colombia","tag-destacada","tag-terrorismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El helic\u00f3ptero del presidente colombiano, Iv\u00e1n Duque, fue atacado esta tarde en pleno vuelo. El presidente, quien iba con su comitiva, aseguraron que no hubo heridos. El hecho se produjo una semana despu\u00e9s de que una Brigada del Ej\u00e9rcito fuera atacada y dejara al menos 36 heridos. A bordo de la aeronave, que recibi\u00f3 cinco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-25T21:26:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo\",\"datePublished\":\"2021-06-25T21:26:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1\",\"keywords\":[\"colombia\",\"destacada\",\"terrorismo\"],\"articleSection\":[\"Destacados\",\"Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/\",\"name\":\"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1\",\"datePublished\":\"2021-06-25T21:26:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1\",\"width\":770,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/25\\\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/","og_locale":"es_ES","og_type":"article","og_title":"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El helic\u00f3ptero del presidente colombiano, Iv\u00e1n Duque, fue atacado esta tarde en pleno vuelo. El presidente, quien iba con su comitiva, aseguraron que no hubo heridos. El hecho se produjo una semana despu\u00e9s de que una Brigada del Ej\u00e9rcito fuera atacada y dejara al menos 36 heridos. A bordo de la aeronave, que recibi\u00f3 cinco [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-06-25T21:26:24+00:00","og_image":[{"width":770,"height":512,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo","datePublished":"2021-06-25T21:26:24+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/"},"wordCount":202,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1","keywords":["colombia","destacada","terrorismo"],"articleSection":["Destacados","Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/","url":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/","name":"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1","datePublished":"2021-06-25T21:26:24+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1","width":770,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/25\/atentan-contra-el-helicoptero-del-presidente-de-colombia-en-pleno-vuelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Atentan contra el helic\u00f3ptero del presidente de Colombia en pleno vuelo"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/helicoptero-presidente-de-colombia.jpeg?fit=770%2C512&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/3191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=3191"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/3191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/3192"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=3191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=3191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=3191"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=3191"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=3191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}