{"id":3121,"date":"2021-06-15T11:46:12","date_gmt":"2021-06-15T09:46:12","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/"},"modified":"2021-06-15T11:46:12","modified_gmt":"2021-06-15T09:46:12","slug":"traicionarse-para-salvarse-paraguay-revive","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/","title":{"rendered":"Traicionarse para salvarse: Paraguay Revive"},"content":{"rendered":"\n<p><strong>TRAICIONARSE NO SIEMPRE ES MALO.<\/strong><\/p>\n\n\n\n<p>Todo entrenador tiene un momento en el que est\u00e1 a punto de traicionarse a s\u00ed mismo en sus convicciones futbol\u00edsticas m\u00e1s profundas. A Eduardo Berizzo la traici\u00f3n le corri\u00f3 por las venas y asalt\u00f3 su punto neur\u00e1lgico, el mediocampo: Gast\u00f3n Gim\u00e9nez fuera de la convocatoria. &nbsp;<\/p>\n\n\n\n<p>El dibujo del medio compart\u00eda por primera vez la presencia de un volante central en Robert Piris Da Motta. El <em>Toto<\/em> pens\u00f3 en defender con 3, el citado Piris m\u00e1s Gustavo G\u00f3mez y Junior Alonso en la lectura de que Bolivia no se animar\u00eda a atacar sostenidamente, y en la necesidad de iniciar limpio con los pases del de Mineiro.<\/p>\n\n\n\n<p>La presencia del pivote potenci\u00f3 el desempe\u00f1o de Math\u00edas Villasanti por el interno derecho. Despliegue excepcional para apuntalar la presencia permanente de Paraguay en territorio boliviano: era el primero en saltar a la presi\u00f3n y a la recuperaci\u00f3n tras p\u00e9rdida. Completaba la trilog\u00eda del medio Miguel Almir\u00f3n que, puesto por el medio, es otra cosa, atacando directo a los centrales, a espaldas de los volantes rivales.<\/p>\n\n\n\n<p>Por momentos, el tri\u00e1ngulo del medio cambiaba de orientaci\u00f3n y se paraba en 2-1, teniendo a Almir\u00f3n como un enlace o segunda punta.<\/p>\n\n\n\n<p>Los laderos fueron elegidos por sus virtudes de pasar la l\u00ednea del medio en transiciones ofensivas. <em>Beto<\/em> Esp\u00ednola menos utilizado, y Santiago Arzamendia entraron con la misi\u00f3n de mantenerse a buena altura para sumar opciones de progresi\u00f3n.<\/p>\n\n\n\n<p>Una traici\u00f3n importante: Paraguay de Berizzo jug\u00f3 con un 9 cl\u00e1sico, Gabriel \u00c1valos fijando y fajando centrales bolivianos para que \u00c1ngel Romero por izquierda y Alejandro Kaku Romero fuesen m\u00e1s extremos que volantes; las funciones cambiaron.<\/p>\n\n\n\n<p><strong>PARA ATACAR BIEN HAY QUE DEFENDER BIEN<\/strong><\/p>\n\n\n\n<p>La lectura de Berizzo fue que una Bolivia diezmada no atacar\u00eda. Acert\u00f3: hizo el gol sin atacar, por infortunio de los nuestros; pero lo que se llaman atacar, los de Far\u00edas no lo hicieron.<\/p>\n\n\n\n<p>Paraguay no ejerci\u00f3 la defensa porque no necesit\u00f3 hacerlo: G\u00f3mez y Alonso ejercieron de iniciadores de ataque; se pararon en mitad de cancha durante 65\u00b4, 70\u00b4aproximadamente. Y los pases de Alonso sumaron mucho para romper con la primera l\u00ednea boliviana y conectar lo m\u00e1s r\u00e1pido posible con Almir\u00f3n y <em>Kaku<\/em>.<\/p>\n\n\n\n<p>El gol boliviano (21\u00b4) no hizo m\u00e1s que acelerar las piernas paraguayas: Paraguay se aboton\u00f3 en las cercan\u00edas del \u00e1rea verde. Gabriel \u00c1valos, se vio muy de cara al gol y no consigui\u00f3 marcar. Pero su tarea de desmarque permanente y lucha con los centrales benefici\u00f3 a los Romero, \u00c1ngel y Alejandro, para que empiecen a ir en el 1c1 permanentemente: el del Cicl\u00f3n argentino ganaba por afuera y estiraba a Bolivia sobre la l\u00ednea; <em>Kaku<\/em> propon\u00eda diagonales de derecha para adentro para soltar pases por ese callej\u00f3n y buscar el pivote de \u00c1valos.<\/p>\n\n\n\n<p>En segunda l\u00ednea, Almir\u00f3n y Villasanti apuntalaban la presencia. Varias veces, los nuestros estuvieron de cara al gol, pero no consegu\u00edamos vulnerar la \u00faltima instancia. Piris Da Motta, el equilibrio.<\/p>\n\n\n\n<p>En los papeles, Paraguay atacaba correctamente. Pero Bolivia termin\u00f3 ganando ese primer tiempo, y con un hombre menos por expulsi\u00f3n de Jaime Cuellar.<\/p>\n\n\n\n<p><strong>EL PLAN DEL SEGUNDO TIEMPO: INSISTIR, PERSISTIR, NUNCA DESISTIR<\/strong><\/p>\n\n\n\n<p>Berizzo redobl\u00f3 la apuesta y asedi\u00f3 los frontones bolivianos con el mismo plan: \u00c1ngel desbordando, \u00c1valos pivotando para la llegada de los dem\u00e1s. Sin embargo, los frontones bolivianos se iban cercando cada vez m\u00e1s. Desde arriba, desde la TV, se ve\u00eda que era necesario o romper l\u00edneas con una conducci\u00f3n, con un pase, u obligar a Bolivia a salir porque pegar\u00edamos de media distancia.<\/p>\n\n\n\n<p>Fue justamente <em>Kaku<\/em> qui\u00e9n empez\u00f3 a animarse a pegar a porter\u00eda; Almir\u00f3n tambi\u00e9n, \u00c1ngel\u2026 Empez\u00e1bamos a animarnos hasta que el cambio posicional de Romero Gamarra, tirado al medio, termin\u00f3 por decidir el rumbo definitivo: caz\u00f3 un rebote y probando fuego clav\u00f3 el zurdazo para equilibrar las cosas e indicar el camino. Bolivia ya era escombros.<\/p>\n\n\n\n<p>El cazador oli\u00f3 sangre y fue por m\u00e1s. Berizzo reforz\u00f3 el mensaje con los cambios: Carlos Gonz\u00e1lez por Piris Da Motta, Richard S\u00e1nchez por Villasanti. A jugar \u00a1con dos 9! Dif\u00edcil ya sostener para Bolivia que penaba en propia \u00e1rea. Bal\u00f3n cruzado a segundo palo, fant\u00e1stico desmarque de Gonz\u00e1lez que gana por arriba y fusila de cabeza al portero boliviano para que Angelito empuje el rebote para ya revertir definitivamente.<\/p>\n\n\n\n<p>El tercer gol ya lo agarra a Bolivia corriendo contra su arco por primera vez, y por ende fue el de ejecuci\u00f3n menos compleja.<\/p>\n\n\n\n<p>Paraguay exhala.<\/p>\n\n\n\n<p><strong>\u00bfCU\u00c1L ES LA VARA?<\/strong><\/p>\n\n\n\n<p>La tarea est\u00e1 cumplida. Pero, \u00bfcu\u00e1l es la vara para esta selecci\u00f3n? \u00bfC\u00f3mo medimos el rendimiento? \u00bfFue contra Brasil o es contra Bolivia?<\/p>\n\n\n\n<p>\u00bfRetornamos a lo b\u00e1sico como contra Uruguay?<\/p>\n\n\n\n<p>Berizzo se ha tenido que traicionar para encontrar una soluci\u00f3n (\u00bfparche?) que le permita respirar de cara a todo lo que viene. La traici\u00f3n solo vino con nombres propios, y desde ellos, con una propuesta futbol\u00edstica diferente. El volante central cl\u00e1sico potencia el desempe\u00f1o de los dem\u00e1s. Almir\u00f3n y <em>Kaku<\/em> atacando a los centrales genera entusiasmo. \u00c1ngel proponiendo desbordes es un show aparte.<\/p>\n\n\n\n<p>Pero, \u00bfestar\u00e1n todos en un <em>big match<\/em>? Se viene Argentina, y est\u00e1 por verse si Berrizo logra la calma mental como para no creer que la permanente traici\u00f3n es el camino.<\/p>\n\n\n\n<p>De vez en cuando, traicionarse est\u00e1 bien. No siempre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paraguay salv\u00f3 la tarea del d\u00eda y sum\u00f3 los puntos ante una debilitada Bolivia por la primera fecha de la Copa Am\u00e9rica. No sin antes sufrir (un d\u00eda en la oficina), Kaku Romero y doblete de \u00c1ngel Romero dieron vuelta el 0-1 inicial, y la sensaci\u00f3n final fue agradable. Berizzo recurri\u00f3 a contramarchas de sus propuestas anteriores, y por ahora puede preparar con tranquilidad el duelo contra Argentina. <\/p>\n","protected":false},"author":12,"featured_media":3122,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[35,41],"tags":[831],"jnews-series":[],"ppma_author":[1071],"class_list":["post-3121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-destacados","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traicionarse para salvarse: Paraguay Revive - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traicionarse para salvarse: Paraguay Revive - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Paraguay salv\u00f3 la tarea del d\u00eda y sum\u00f3 los puntos ante una debilitada Bolivia por la primera fecha de la Copa Am\u00e9rica. No sin antes sufrir (un d\u00eda en la oficina), Kaku Romero y doblete de \u00c1ngel Romero dieron vuelta el 0-1 inicial, y la sensaci\u00f3n final fue agradable. Berizzo recurri\u00f3 a contramarchas de sus propuestas anteriores, y por ahora puede preparar con tranquilidad el duelo contra Argentina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T09:46:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adan Amarilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Pinkfloydiano82\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adan Amarilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/\"},\"author\":{\"name\":\"Adan Amarilla\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/c21036c84cdec564f5e16356332b2f02\"},\"headline\":\"Traicionarse para salvarse: Paraguay Revive\",\"datePublished\":\"2021-06-15T09:46:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/\"},\"wordCount\":949,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1\",\"keywords\":[\"destacada\"],\"articleSection\":[\"Deportes\",\"Destacados\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/\",\"name\":\"Traicionarse para salvarse: Paraguay Revive - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1\",\"datePublished\":\"2021-06-15T09:46:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/15\\\/traicionarse-para-salvarse-paraguay-revive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traicionarse para salvarse: Paraguay Revive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/c21036c84cdec564f5e16356332b2f02\",\"name\":\"Adan Amarilla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/830fd80589c35eb39235e45fa5b562573bae604a0811beb82a380aa56daab4bc?s=96&d=mm&r=g4761c3ef8a45d10d3b0eab4f7672d367\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/830fd80589c35eb39235e45fa5b562573bae604a0811beb82a380aa56daab4bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/830fd80589c35eb39235e45fa5b562573bae604a0811beb82a380aa56daab4bc?s=96&d=mm&r=g\",\"caption\":\"Adan Amarilla\"},\"description\":\"Docente, entrenador, coordinador de proyectos.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Pinkfloydiano82\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/aamarilla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traicionarse para salvarse: Paraguay Revive - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/","og_locale":"es_ES","og_type":"article","og_title":"Traicionarse para salvarse: Paraguay Revive - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Paraguay salv\u00f3 la tarea del d\u00eda y sum\u00f3 los puntos ante una debilitada Bolivia por la primera fecha de la Copa Am\u00e9rica. No sin antes sufrir (un d\u00eda en la oficina), Kaku Romero y doblete de \u00c1ngel Romero dieron vuelta el 0-1 inicial, y la sensaci\u00f3n final fue agradable. Berizzo recurri\u00f3 a contramarchas de sus propuestas anteriores, y por ahora puede preparar con tranquilidad el duelo contra Argentina.","og_url":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2021-06-15T09:46:12+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1","type":"image\/jpeg"}],"author":"Adan Amarilla","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Pinkfloydiano82","twitter_misc":{"Escrito por":"Adan Amarilla","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/"},"author":{"name":"Adan Amarilla","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/c21036c84cdec564f5e16356332b2f02"},"headline":"Traicionarse para salvarse: Paraguay Revive","datePublished":"2021-06-15T09:46:12+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/"},"wordCount":949,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1","keywords":["destacada"],"articleSection":["Deportes","Destacados"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/","url":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/","name":"Traicionarse para salvarse: Paraguay Revive - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1","datePublished":"2021-06-15T09:46:12+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/15\/traicionarse-para-salvarse-paraguay-revive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Traicionarse para salvarse: Paraguay Revive"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/c21036c84cdec564f5e16356332b2f02","name":"Adan Amarilla","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/830fd80589c35eb39235e45fa5b562573bae604a0811beb82a380aa56daab4bc?s=96&d=mm&r=g4761c3ef8a45d10d3b0eab4f7672d367","url":"https:\/\/secure.gravatar.com\/avatar\/830fd80589c35eb39235e45fa5b562573bae604a0811beb82a380aa56daab4bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/830fd80589c35eb39235e45fa5b562573bae604a0811beb82a380aa56daab4bc?s=96&d=mm&r=g","caption":"Adan Amarilla"},"description":"Docente, entrenador, coordinador de proyectos.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Pinkfloydiano82"],"url":"https:\/\/informatepy.com\/2024\/author\/aamarilla\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/paraguay-bolivia.jpg?fit=1200%2C675&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1071,"user_id":12,"is_guest":0,"slug":"aamarilla","display_name":"Adan Amarilla","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/830fd80589c35eb39235e45fa5b562573bae604a0811beb82a380aa56daab4bc?s=96&d=mm&r=g","author_category":"","first_name":"Adan","last_name":"Amarilla","user_url":"","job_title":"","description":"Docente, entrenador, coordinador de proyectos."}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/3121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=3121"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/3121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/3122"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=3121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=3121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=3121"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=3121"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=3121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}