{"id":3119,"date":"2021-06-14T20:48:34","date_gmt":"2021-06-14T18:48:34","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/"},"modified":"2021-06-14T20:48:34","modified_gmt":"2021-06-14T18:48:34","slug":"yo-los-conozco-son-25-mil-los-monos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/","title":{"rendered":"Yo los conozco son&#8230; 25 mil los monos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un dicho del \u00e1mbito jur\u00eddico reza que \u201ca confesi\u00f3n de parte, relevo de pruebas\u201d. Es exac\u00adtamente esto lo que se puede aplicar a las palabras atri\u00adbuidas de Arnulfo Ram\u00f3n \u201cMonchi\u201d Fretes Sosa, pre\u00adsidente de la seccional colo\u00adrada N\u00b0 35 y funcionario de la Entidad Binacional Yacyret\u00e1 (EBY), quien durante el 2020 se embols\u00f3 nada menos que G. 614 millones en concepto de salarios, aguinaldo y boni\u00adficaciones, seg\u00fan publica&nbsp;La Naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un audio filtrado y que fue dado a conocer en redes sociales y grupos de men\u00adsajer\u00eda, el \u201coperador\u201d pol\u00ed\u00adtico de A\u00f1etete, muy cer\u00adcano a Nicanor Duarte Frutos, titular de la EBY, menciona la manera en la que, supuestamente, van a obtener los votos que nece\u00adsitan para lograr la victo\u00adria en las elecciones inter\u00adnas en varias localidades, espec\u00edficamente de la ciu\u00addad de Asunci\u00f3n y en otras del departamento Central.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El operador pol\u00edtico de A\u00f1etete tiene una p\u00e1gina en sus redes sociales con este eslogan: \u201cDenme la oportunidad de demostrar nuestro talento con el equipo pol\u00edtico que me acompa\u00f1a. VOTA A CONCIENCIA\u201d.FOTO:CAPTURA DE PANTALLA<br><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cSAB\u00c9S C\u00d3MO ES LA PLEBE\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMonchi\u201d habr\u00eda explicado la manera en que va a operar el \u201cD\u00eda D\u201d, como llama al d\u00eda de las elecciones. \u201cPara las 10 de la ma\u00f1ana ya va a venir un ej\u00e9rcito de 70 \u00f3mnibus desde Central y qui\u00e9n va a poder contra ellos, mientras que los perros golpean todav\u00eda (de puerta en puerta)\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n mencion\u00f3 que le dio consejos supues\u00adtamente a Daniel Centu\u00adri\u00f3n, precandidato de A\u00f1e\u00adtete para la Intendencia de Asunci\u00f3n. \u201cVos no gan\u00e1s con esto (publicidad), vos gan\u00e1s el D\u00eda D, con 25 mil monos de Central. Yo a todi\u00adtos (sic) les pago G. 100 mil, le dije. Se van a morir por ese 100 mil, vos sab\u00e9s c\u00f3mo es la plebe\u201d, reiter\u00f3 el fun\u00adcionario de la EBY.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201c\u00a1SABEN QUE YO SOY MA\u00d1ERO!\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin mencionar a qui\u00e9nes se refiere, Arnulfo \u201cMonchi\u201d Fretes contin\u00faa explicando: \u201cPor eso es que le piden a Dani por m\u00ed, porque saben que yo soy ma\u00f1ero, en la seccional (N\u00b0 35) donde siempre tuve m\u00e1s votos y yo siempre gan\u00e9, por eso les dije que no hagan campa\u00f1as largas\u201d, se jact\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El operador pol\u00edtico de A\u00f1e\u00adtete tiene una p\u00e1gina en sus redes sociales con este eslo\u00adgan: \u201cDenme la oportuni\u00addad de demostrar nuestro talento con el equipo pol\u00ed\u00adtico que me acompa\u00f1a. VOTA A CONCIENCIA\u201d, algo que a juzgar por sus pro\u00adpias expresiones est\u00e1 muy alejado de sus intenciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INVOLUCR\u00d3 A NATALICIO CHASE Y A MARIO ABDO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, seg\u00fan el audio atribuido al opera\u00addor, \u201cMonchi\u201d Fretes fue mucho m\u00e1s all\u00e1 de las sim\u00adples \u201crecomendaciones electorales\u201d e involucr\u00f3 al presidente de la Empresa de Servicios Sanitarios del Paraguay SA (Essap), Natalicio Chase, y al pro\u00adpio presidente de la Rep\u00fa\u00adblica, Mario Abdo Ben\u00edtez, en los hechos que men\u00adciona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNatalicio Chase va a dar m\u00e1s plata, ayer habl\u00e9 con Natalicio y me dijo que ya junt\u00f3 4.000 (millones de guaran\u00edes) y para el D\u00eda D, tres palos verdes (tres millones de d\u00f3lares). Marito quiere ganar y me dijo a m\u00ed \u2018le ganamos a estos con un palo verde\u2019\u201d, mientras expli\u00adcaba supuestamente al pre\u00adsidente de la Rep\u00fablica que comprar\u00edan toda la ribera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCompramos 70 mil perso\u00adnas a G. 100 mil y Marito se sorprendi\u00f3 cuando le dije que vamos a comprar toda la ribera (zona de los ba\u00f1a\u00addos)\u201d, coment\u00f3 a su interlo\u00adcutor sobre lo conversado supuestamente con el presi\u00addente de la Rep\u00fablica y con el titular de Essap.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Arnulfo Ram\u00f3n \u201cMonchi\u201d Fretes Sosa afirma que \u201cla plebe\u201d, la gente vulnerable, saldr\u00e1 ese d\u00eda a votar por \u201cG. 100 mil\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TAMBI\u00c9N NICANOR REQUIRI\u00d3 DE SUS \u201cSERVICIOS\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro momento de la con\u00adversaci\u00f3n filtrada, atri\u00adbuida a \u201cMonchi\u201d Fretes, este pide voto a conciencia en sus redes sociales, men\u00adciona que el director de la EBY, Nicanor Duarte Fru\u00adtos, le consult\u00f3 qu\u00e9 pod\u00edan hacer, sin mencionar el con\u00adtexto de la charla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLe dije que tiene que sacar ya un 50 mil antes, para que la gente no vea, y vos sab\u00e9s que en las zonas vulnerables los perros van a agarrar\u201d, a lo que Duarte Frutos res\u00adpondi\u00f3 en guaran\u00ed: \u201cEso es lo que me gusta de vos, tu estructura y yo le dije, 25 por ciento de participaci\u00f3n y luego a platazo y compra\u00admos toda la ribera\u201d, reiter\u00f3 el funcionario de la EBY.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro momento de su con\u00adversaci\u00f3n, mencion\u00f3 que tambi\u00e9n se pusieron en con\u00adtacto con \u00e9l, por la misma cuesti\u00f3n, Mauricio Esp\u00ed\u00adnola, secretario privado de la Presidencia de la Rep\u00fa\u00adblica, y David Miranda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cVAN A SALIR POR UN CIEN MIL\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa gente va a salir por un cien mil, para comer, para comprar algo, va a votar y va a entrar otra vez en su casa\u201d, concluye parte del \u201cenriquecedor\u201d di\u00e1logo que mantiene en varias con\u00adversaciones el presidente de la Seccional Colorada N\u00b0 35, operador pol\u00edtico del movimiento A\u00f1etete y bien pagado funcionario de la Entidad Binacional Yacyret\u00e1, quien en el mes de mayo pasado recibi\u00f3 poco m\u00e1s de G. 9 millones en con\u00adcepto de bonificaciones y horas extras, sin incluir su salario de cerca de G. 20 millones, seg\u00fan la catego\u00adr\u00eda H6 en la que figura en la n\u00f3mina de funcionarios de Yacyret\u00e1.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Diario Hoy<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Un dicho del \u00e1mbito jur\u00eddico reza que \u201ca confesi\u00f3n de parte, relevo de pruebas\u201d. Es exac\u00adtamente esto lo que se puede aplicar a las palabras atri\u00adbuidas de Arnulfo Ram\u00f3n \u201cMonchi\u201d Fretes Sosa, pre\u00adsidente de la seccional colo\u00adrada N\u00b0 35 y funcionario de la Entidad Binacional Yacyret\u00e1 (EBY), quien durante el 2020 se embols\u00f3 nada menos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3120,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":2,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[41,40],"tags":[635,831],"jnews-series":[],"ppma_author":[830],"class_list":["post-3119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-municipales","tag-daniel-centurion","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yo los conozco son... 25 mil los monos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yo los conozco son... 25 mil los monos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Un dicho del \u00e1mbito jur\u00eddico reza que \u201ca confesi\u00f3n de parte, relevo de pruebas\u201d. Es exac\u00adtamente esto lo que se puede aplicar a las palabras atri\u00adbuidas de Arnulfo Ram\u00f3n \u201cMonchi\u201d Fretes Sosa, pre\u00adsidente de la seccional colo\u00adrada N\u00b0 35 y funcionario de la Entidad Binacional Yacyret\u00e1 (EBY), quien durante el 2020 se embols\u00f3 nada menos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-14T18:48:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Yo los conozco son&#8230; 25 mil los monos\",\"datePublished\":\"2021-06-14T18:48:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/\"},\"wordCount\":963,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1\",\"keywords\":[\"daniel centurion\",\"destacada\"],\"articleSection\":[\"Destacados\",\"Municipales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/\",\"name\":\"Yo los conozco son... 25 mil los monos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1\",\"datePublished\":\"2021-06-14T18:48:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1\",\"width\":1200,\"height\":783},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/06\\\/14\\\/yo-los-conozco-son-25-mil-los-monos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yo los conozco son&#8230; 25 mil los monos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yo los conozco son... 25 mil los monos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/","og_locale":"es_ES","og_type":"article","og_title":"Yo los conozco son... 25 mil los monos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Un dicho del \u00e1mbito jur\u00eddico reza que \u201ca confesi\u00f3n de parte, relevo de pruebas\u201d. Es exac\u00adtamente esto lo que se puede aplicar a las palabras atri\u00adbuidas de Arnulfo Ram\u00f3n \u201cMonchi\u201d Fretes Sosa, pre\u00adsidente de la seccional colo\u00adrada N\u00b0 35 y funcionario de la Entidad Binacional Yacyret\u00e1 (EBY), quien durante el 2020 se embols\u00f3 nada menos [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-06-14T18:48:34+00:00","og_image":[{"width":1200,"height":783,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Yo los conozco son&#8230; 25 mil los monos","datePublished":"2021-06-14T18:48:34+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/"},"wordCount":963,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1","keywords":["daniel centurion","destacada"],"articleSection":["Destacados","Municipales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/","url":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/","name":"Yo los conozco son... 25 mil los monos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1","datePublished":"2021-06-14T18:48:34+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1","width":1200,"height":783},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Yo los conozco son&#8230; 25 mil los monos"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/3119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=3119"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/3119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/3120"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=3119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=3119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=3119"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=3119"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=3119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}