{"id":30748,"date":"2025-03-14T00:00:00","date_gmt":"2025-03-14T03:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=30748"},"modified":"2025-03-13T15:17:22","modified_gmt":"2025-03-13T18:17:22","slug":"eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/","title":{"rendered":"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>Departamento de Eficiencia Gubernamental (DOGE) de Estados Unidos<\/strong>&nbsp;cancel\u00f3 varias subvenciones de los<strong>&nbsp;Institutos Nacionales de Salud (NIH)<\/strong>, entre ellas la de m\u00e1s de medio mill\u00f3n de d\u00f3lares destinada a un \u00abprograma de prevenci\u00f3n de embarazos para chicos transexuales\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El DOGE, liderado por <strong>Elon Musk<\/strong>, revel\u00f3 en un post de X que el NIH puso fin al menos, a cinco programas con gastos millonarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los proyectos m\u00e1s extravagantes que han sido cancelados est\u00e1 una subvenci\u00f3n de 620.000 d\u00f3lares para <strong>\u00abun programa de prevenci\u00f3n del embarazo adolescente inclusivo LGB+ para chicos transexuales\u00bb<\/strong>, refiri\u00e9ndose a mujeres biol\u00f3gicas que se reconocen como hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El instituto, que forma parte del Departamento de Salud y Servicios Humanos (HHS), tambi\u00e9n gastaba unos <strong>700.000 d\u00f3lares<\/strong> para estudiar el consumo de cannabis en <em><strong>\u00abindividuos de minor\u00edas sexuales de g\u00e9nero diverso\u00bb<\/strong>, <\/em><strong>740.000 d\u00f3lares<\/strong> en el examen de las <strong><em>\u00abredes sociales\u00bb <\/em><\/strong>entre los <strong><em>\u00abhombres negros y latinos de minor\u00edas sexuales en Nueva Jersey\u00bb<\/em><\/strong>, y <strong>50.000 d\u00f3lares <\/strong>m\u00e1s en la evaluaci\u00f3n de la <strong><em>\u00absalud sexual\u00bb<\/em><\/strong> entre los <strong><em>\u00abj\u00f3venes LGTBQ + Latinx en una comunidad agr\u00edcola\u00bb.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;Departamento de Eficiencia Gubernamental (DOGE) de Estados Unidos&nbsp;cancel\u00f3 varias subvenciones de los&nbsp;Institutos Nacionales de Salud (NIH), entre ellas la de m\u00e1s de medio mill\u00f3n de d\u00f3lares destinada a un \u00abprograma de prevenci\u00f3n de embarazos para chicos transexuales\u00bb. El DOGE, liderado por Elon Musk, revel\u00f3 en un post de X que el NIH puso fin al [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":25321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"2","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"0","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33],"tags":[831,685],"jnews-series":[],"ppma_author":[830],"class_list":["post-30748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-destacada","tag-estados-unidos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El&nbsp;Departamento de Eficiencia Gubernamental (DOGE) de Estados Unidos&nbsp;cancel\u00f3 varias subvenciones de los&nbsp;Institutos Nacionales de Salud (NIH), entre ellas la de m\u00e1s de medio mill\u00f3n de d\u00f3lares destinada a un \u00abprograma de prevenci\u00f3n de embarazos para chicos transexuales\u00bb. El DOGE, liderado por Elon Musk, revel\u00f3 en un post de X que el NIH puso fin al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T03:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/05\/impuestos.jpg?fit=1280%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d\",\"datePublished\":\"2025-03-14T03:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/\"},\"wordCount\":205,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/impuestos.jpg?fit=1280%2C630&ssl=1\",\"keywords\":[\"destacada\",\"estados unidos\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/\",\"name\":\"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/impuestos.jpg?fit=1280%2C630&ssl=1\",\"datePublished\":\"2025-03-14T03:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/impuestos.jpg?fit=1280%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/impuestos.jpg?fit=1280%2C630&ssl=1\",\"width\":1280,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2025\\\/03\\\/14\\\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/","og_locale":"es_ES","og_type":"article","og_title":"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El&nbsp;Departamento de Eficiencia Gubernamental (DOGE) de Estados Unidos&nbsp;cancel\u00f3 varias subvenciones de los&nbsp;Institutos Nacionales de Salud (NIH), entre ellas la de m\u00e1s de medio mill\u00f3n de d\u00f3lares destinada a un \u00abprograma de prevenci\u00f3n de embarazos para chicos transexuales\u00bb. El DOGE, liderado por Elon Musk, revel\u00f3 en un post de X que el NIH puso fin al [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2025-03-14T03:00:00+00:00","og_image":[{"width":1280,"height":630,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/05\/impuestos.jpg?fit=1280%2C630&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d","datePublished":"2025-03-14T03:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/"},"wordCount":205,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/05\/impuestos.jpg?fit=1280%2C630&ssl=1","keywords":["destacada","estados unidos"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/","url":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/","name":"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/05\/impuestos.jpg?fit=1280%2C630&ssl=1","datePublished":"2025-03-14T03:00:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/05\/impuestos.jpg?fit=1280%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/05\/impuestos.jpg?fit=1280%2C630&ssl=1","width":1280,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2025\/03\/14\/eeuu-cancela-subvenciones-para-prevenir-el-embarazo-de-chicos-transexuales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"EEUU cancela subvenciones para prevenir el embarazo de \u201cchicos transexuales\u201d"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/05\/impuestos.jpg?fit=1280%2C630&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/30748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=30748"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/30748\/revisions"}],"predecessor-version":[{"id":30749,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/30748\/revisions\/30749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/25321"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=30748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=30748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=30748"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=30748"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=30748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}