{"id":28522,"date":"2024-11-23T00:01:00","date_gmt":"2024-11-23T03:01:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=28522"},"modified":"2024-11-22T16:41:44","modified_gmt":"2024-11-22T19:41:44","slug":"presentan-el-trazado-del-gasoducto-a-traves-del-chaco","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/","title":{"rendered":"Presentan el trazado del gasoducto a trav\u00e9s del Chaco"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El viceministro de Minas y Energ\u00eda, <strong>Mauricio Bejarano<\/strong>, expuso que el trazado propuesto por Paraguay para el gasoducto que conectar\u00e1 <strong>Argentina <\/strong>y <strong>Brasil<\/strong>, presentado en la cumbre del G20, ofrece ventajas significativas en aspectos t\u00e9cnicos, ambientales y econ\u00f3micos. Este proyecto busca enlazar la formaci\u00f3n de Vaca Muerta con los mercados del sur de Brasil y otros destinos regionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u201cEl ducto recorrer\u00eda 1.050 kil\u00f3metros desde Argentina hasta Mato Grosso del Sur, siguiendo la ruta bioce\u00e1nica. Esta trayectoria evita complicaciones topogr\u00e1ficas y ambientales, como monta\u00f1as, r\u00edos importantes y comunidades, salvo el r\u00edo Paraguay, donde ya se construye un puente que facilitar\u00e1 el cruce\u201d<\/em><\/strong>, indic\u00f3 Bejarano, refiri\u00e9ndose al puente Bioce\u00e1nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bejarano destac\u00f3 que Paraguay se presenta como una alternativa competitiva gracias a su estabilidad econ\u00f3mica y calificaci\u00f3n de grado de inversi\u00f3n, factores clave para atraer a inversores privados que financiar\u00e1n el proyecto. Adem\u00e1s, se enviaron memorandos de entendimiento a las embajadas de Argentina y Brasil, as\u00ed como a las provincias de Salta y Mato Grosso del Sur, para avanzar en el dise\u00f1o del gasoducto y alcanzar los consensos necesarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viceministro de Minas y Energ\u00eda, Mauricio Bejarano, expuso que el trazado propuesto por Paraguay para el gasoducto que conectar\u00e1 Argentina y Brasil, presentado en la cumbre del G20, ofrece ventajas significativas en aspectos t\u00e9cnicos, ambientales y econ\u00f3micos. Este proyecto busca enlazar la formaci\u00f3n de Vaca Muerta con los mercados del sur de Brasil y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":2,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"2","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"0","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[526,353,1813,831,2111],"jnews-series":[],"ppma_author":[830],"class_list":["post-28522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-argentina","tag-brasil","tag-chaco","tag-destacada","tag-gasoducto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentan el trazado del gasoducto a trav\u00e9s del Chaco - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentan el trazado del gasoducto a trav\u00e9s del Chaco - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El viceministro de Minas y Energ\u00eda, Mauricio Bejarano, expuso que el trazado propuesto por Paraguay para el gasoducto que conectar\u00e1 Argentina y Brasil, presentado en la cumbre del G20, ofrece ventajas significativas en aspectos t\u00e9cnicos, ambientales y econ\u00f3micos. Este proyecto busca enlazar la formaci\u00f3n de Vaca Muerta con los mercados del sur de Brasil y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-23T03:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/11\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Presentan el trazado del gasoducto a trav\u00e9s del Chaco\",\"datePublished\":\"2024-11-23T03:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/\"},\"wordCount\":204,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1\",\"keywords\":[\"argentina\",\"brasil\",\"chaco\",\"destacada\",\"gasoducto\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/\",\"name\":\"Presentan el trazado del gasoducto a trav\u00e9s del Chaco - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2024-11-23T03:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/11\\\/23\\\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentan el trazado del gasoducto a trav\u00e9s del Chaco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentan el trazado del gasoducto a trav\u00e9s del Chaco - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/","og_locale":"es_ES","og_type":"article","og_title":"Presentan el trazado del gasoducto a trav\u00e9s del Chaco - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El viceministro de Minas y Energ\u00eda, Mauricio Bejarano, expuso que el trazado propuesto por Paraguay para el gasoducto que conectar\u00e1 Argentina y Brasil, presentado en la cumbre del G20, ofrece ventajas significativas en aspectos t\u00e9cnicos, ambientales y econ\u00f3micos. Este proyecto busca enlazar la formaci\u00f3n de Vaca Muerta con los mercados del sur de Brasil y [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2024-11-23T03:01:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/11\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Presentan el trazado del gasoducto a trav\u00e9s del Chaco","datePublished":"2024-11-23T03:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/"},"wordCount":204,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/11\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1","keywords":["argentina","brasil","chaco","destacada","gasoducto"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/","url":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/","name":"Presentan el trazado del gasoducto a trav\u00e9s del Chaco - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/11\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1","datePublished":"2024-11-23T03:01:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/11\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/11\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2024\/11\/23\/presentan-el-trazado-del-gasoducto-a-traves-del-chaco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Presentan el trazado del gasoducto a trav\u00e9s del Chaco"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/11\/gasoducto-chaco.jpg?fit=1280%2C720&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/28522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=28522"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/28522\/revisions"}],"predecessor-version":[{"id":28524,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/28522\/revisions\/28524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/28523"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=28522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=28522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=28522"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=28522"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=28522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}