{"id":2706,"date":"2021-04-23T09:23:00","date_gmt":"2021-04-23T07:23:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/"},"modified":"2021-04-23T09:23:00","modified_gmt":"2021-04-23T07:23:00","slug":"australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/","title":{"rendered":"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobierno de Australia&nbsp;<strong>vet\u00f3 el mi\u00e9rcoles dos acuerdos entre China y la regi\u00f3n de Victoria en el marco de la Iniciativa de la Franja y la Ruta (BRI, en ingl\u00e9s)<\/strong>&nbsp;por \u201cinconsistencias\u201d con la pol\u00edtica exterior del pa\u00eds oce\u00e1nico, tras lo cual Beijing reclam\u00f3 este jueves que se de marcha atr\u00e1s y amenaz\u00f3 con responder \u201cde forma dura\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el portavoz del Ministerio de Asuntos Exteriores chino Wang Wenbin, citado por la prensa local, la decisi\u00f3n de Canberra es un \u201cpaso hacia atr\u00e1s\u201d que deteriorar\u00e1 todav\u00eda m\u00e1s los maltrechos lazos entre ambos pa\u00edses. \u201c<strong>Es una nueva confirmaci\u00f3n de que Australia no tiene sinceridad alguna a la hora de desarrollar las relaciones bilaterales (con China)\u201d<\/strong>, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno de Australia ejerci\u00f3 por primera vez los poderes para vetar acuerdos entre las jurisdicciones del pa\u00eds y naciones extranjeras, alegando que defiende el inter\u00e9s nacional y que <strong>la firma de esos acuerdos para crear una nueva \u00abruta de la seda\u00bb supon\u00eda \u00abinconsistencias\u00bb con la pol\u00edtica exterior marcada por Canberra.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los acuerdos en cuesti\u00f3n son<strong>&nbsp;memorandos de entendimiento suscritos en 2018 y 2019&nbsp;<\/strong>aunque, seg\u00fan la prensa australiana, no comprometen a las autoridades regionales de Victoria a llevar a cabo proyectos espec\u00edficos y no son legalmente vinculantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante,\u00a0<strong>China ha presentado \u201cquejas formales y firmes\u201d ante las autoridades australianas, a las que exigen que den marcha atr\u00e1s en su decisi\u00f3n al considerar que los acuerdos entre Beijing y la regi\u00f3n del pa\u00eds insular son beneficiosos para ambas partes.<\/strong><\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Con informaci\u00f3n de Infobae<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno australiano explic\u00f3 que vet\u00f3 los pactos porque no concuerdan con la pol\u00edtica exterior de la naci\u00f3n oce\u00e1nica, que aboga por una regi\u00f3n del Indo-Pac\u00edfico \u201clibre y abierta\u201d. El r\u00e9gimen chino respondi\u00f3 que la medida representa un da\u00f1o grave en la relaci\u00f3n bilateral<\/p>\n","protected":false},"author":3,"featured_media":2707,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33],"tags":[722,207,1029],"jnews-series":[],"ppma_author":[830],"class_list":["post-2706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-australia","tag-china","tag-ruta-de-la-seda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El Gobierno australiano explic\u00f3 que vet\u00f3 los pactos porque no concuerdan con la pol\u00edtica exterior de la naci\u00f3n oce\u00e1nica, que aboga por una regi\u00f3n del Indo-Pac\u00edfico \u201clibre y abierta\u201d. El r\u00e9gimen chino respondi\u00f3 que la medida representa un da\u00f1o grave en la relaci\u00f3n bilateral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-23T07:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing\",\"datePublished\":\"2021-04-23T07:23:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/\"},\"wordCount\":297,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1\",\"keywords\":[\"australia\",\"china\",\"ruta de la seda\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/\",\"name\":\"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1\",\"datePublished\":\"2021-04-23T07:23:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/23\\\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/","og_locale":"es_ES","og_type":"article","og_title":"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El Gobierno australiano explic\u00f3 que vet\u00f3 los pactos porque no concuerdan con la pol\u00edtica exterior de la naci\u00f3n oce\u00e1nica, que aboga por una regi\u00f3n del Indo-Pac\u00edfico \u201clibre y abierta\u201d. El r\u00e9gimen chino respondi\u00f3 que la medida representa un da\u00f1o grave en la relaci\u00f3n bilateral","og_url":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-04-23T07:23:00+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing","datePublished":"2021-04-23T07:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/"},"wordCount":297,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1","keywords":["australia","china","ruta de la seda"],"articleSection":["Mundo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/","url":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/","name":"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1","datePublished":"2021-04-23T07:23:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/23\/australia-se-retiro-de-la-nueva-ruta-de-la-seda-promovida-por-china-y-genero-la-ira-de-beijing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Australia se retir\u00f3 de la \u201cNueva Ruta de la Seda\u201d promovida por China y gener\u00f3 la ira de Beijing"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/scott-morrison-1-min-australia.jpg?fit=768%2C512&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/2706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=2706"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/2706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/2707"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=2706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=2706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=2706"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=2706"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=2706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}