{"id":2574,"date":"2021-04-09T11:27:50","date_gmt":"2021-04-09T09:27:50","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/"},"modified":"2021-04-09T11:27:50","modified_gmt":"2021-04-09T09:27:50","slug":"muneco-de-torta","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/","title":{"rendered":"Mu\u00f1eco de torta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este tipo, el turquito, parece un mu\u00f1eco de torta puesto de adorno sobre el merengue. Claro, a su lado la mu\u00f1equita, su parejita, quien otrora sol\u00eda cacarear al pedo cual gallina turuleca hasta que se fu\u00e9 a Miami para hacerse lavandera con toda su parentela. Mientras, aqu\u00ed, el <strong><em>prescindente <\/em><\/strong>propon\u00eda fundir la econom\u00eda paraguaya con el paquete de leyes anti-lavado como primera medida de su gobierno. All\u00e1 lavando y aqu\u00ed, al pueblo, con el mazo dando. Por eso, escupo sobre la hipocres\u00eda de este monigote dirigido a control remoto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando sale Marito y habla en p\u00fablico, parece un actor de una telenovela distinta a la nuestra. Su parlamento no encaja, no tiene sentido, parece estar actuando en el canal equivocado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es como si le pones a Danny Da Rosa de \u00abLa Chuchi\u00bb en el papel del \u00abPatr\u00f3n del Mal\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pel\u00edcula en la que <strong>el presidente amor<\/strong> har\u00eda un papel perfecto, con su asesor <strong>Danny Centuri\u00f3n<\/strong> si se quiere, se llama <strong>\u00abTonto y re-tonto\u00bb<\/strong>. El primero para el ex concejal de Asunci\u00f3n, obvio microbio. En\u00a0 realidad, aunque fue fantas\u00eda hollywoodense, protagonizaron el film nada m\u00e1s y nada menos que Jim Carey y Jeff Daniels. S\u00ed, de eso trataba, eso mismo; aventuras de un par de idiotas; tonto y re-tonto, Danny y Marito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hubo un tiempo, atr\u00e1s, en el que se dec\u00eda que el Rock &amp; Roll podr\u00eda salvar al mundo. Bu\u00e9&#8230;\u00bfQui\u00e9nes lo dec\u00edan? Seguramente los rockeros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez consult\u00e9 a Luis Zaran si cab\u00eda la comparaci\u00f3n de la m\u00fasica de Johan Sebastian Bach, para m\u00ed el mejor m\u00fasico de la Historia, con el jazz, ya que el m\u00fasico alem\u00e1n improvisaba bastante cuando interpretaba sus composiciones gracias a su genio. Sabemos que el jazz tiene mucha improvisaci\u00f3n, pero Luis Saran exhal\u00f3 una sonrisa y contest\u00f3: <strong>\u00abEso dicen los jazzistas\u00bb<\/strong>. Excelente respuesta, \u00bfNo ser\u00e1 pariente de nuestro l\u00edder Jair Bolsonaro?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hablando de, \u00bfNo escucharon la f\u00f3rmula que dio para acabar totalmente con la plandemia? Dijo que ser\u00eda muy sencillo, pagarles a todos los medios como lo hicieron los gobiernos anteriores al suyo, como el del herrero Lula y la terrorista Dilma, cabra loca esta. \u00bfQue tul? Epetacularrr, arr, arr!! Levanten la mano quienes quieren que Jair \u00abMes\u00edas\u00bb sea su presidente! Arrasa!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rock &amp; roll a lo mejor nunca morir\u00e1 pero al mundo no lo va a salvar, tampoco el jazz, ni Bach, menos a\u00fan el reggeton. El actor desubicado dijo que el amor salvar\u00e1 al Paraguay y al mundo. \u00bfEl amor a qu\u00e9? Por lo menos el que practica \u00e9l y su familia pol\u00edtica es el amor a lo ajeno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y si cree lo que dice, no creo ni que sepa de lo que habla, porque carajo f\u00edrma esos decretos que tratan de impedir a la gente, a la familia paraguaya, que se den el afecto necesario de la \u00fanica manera que pueden? Reuniendose!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hip\u00f3crita e idiota lo que sos Marito<\/strong>, badulaque que habla todo al pedo y juega con la gente, \u00abMarito de la Gente\u00bb, por Dios! Los que inventaron este slogan, el m\u00e1s bola de la historia paraguaya, deber\u00edan ser apedreados a muerte as\u00ed como los que fabricaron a este candidato para deshonrar la presidencia del Paraguay hasta las \u00faltimas consecuencias. Ya lo hab\u00eda hecho bastante el \u00abescarabajo\u00bb, as\u00ed apodado por tener el motor atr\u00e1s como dijeron algunos colorados de culo pelado , el mono manco como dir\u00edan los cubanos por los putos, ya que deben pelar la banana con el orto, Luis \u00c1ngel Gonz\u00e1lez Macchi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hitler tambi\u00e9n era puto! \u00bfSab\u00edan? M\u00e1s bien prostituto de putos, en su Austria natal, as\u00ed fue. Y si no me creen, preg\u00fantenme si me calienta. Qu\u00e9 grosero! Hablemos de amor hermano! Salv\u00e9monos! Salvemos al mundo! En verdad lo que debi\u00f3 decir el mu\u00f1eco de torta fue: <strong>\u00abS\u00e1lvense quien pueda!\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, es perentorio decirlo, hay un s\u00f3lo salvador del mundo; Jesucristo hombre, las feministas no se salvar\u00e1n entonces, el Nazareno era circunciso tambi\u00e9n, de hecho, Jes\u00fas quiere decir \u00abEl que salva\u00bb en hebreo. El fabuloso escritor liban\u00e9s dijo de \u00e9l: <em><strong>\u00abCristo cur\u00f3 a los ciegos, a los lisiados, a los paral\u00edticos y a los leprosos. Pero a los idiotas no pudo curarlos\u00bb<\/strong><\/em>. Puede ser que a Marito le salve su fe, pero no curar\u00e1 su idiotez.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este tipo, el turquito, parece un mu\u00f1eco de torta puesto de adorno sobre el merengue. Claro, a su lado la mu\u00f1equita, su parejita, quien otrora sol\u00eda cacarear al pedo cual gallina turuleca hasta que se fu\u00e9 a Miami para hacerse lavandera con toda su parentela. Mientras, aqu\u00ed, el prescindente propon\u00eda fundir la econom\u00eda paraguaya con [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2575,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[39,41],"tags":[635,831,197],"jnews-series":[],"ppma_author":[830],"class_list":["post-2574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","category-destacados","tag-daniel-centurion","tag-destacada","tag-mario-abdo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mu\u00f1eco de torta - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mu\u00f1eco de torta - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Este tipo, el turquito, parece un mu\u00f1eco de torta puesto de adorno sobre el merengue. Claro, a su lado la mu\u00f1equita, su parejita, quien otrora sol\u00eda cacarear al pedo cual gallina turuleca hasta que se fu\u00e9 a Miami para hacerse lavandera con toda su parentela. Mientras, aqu\u00ed, el prescindente propon\u00eda fundir la econom\u00eda paraguaya con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-09T09:27:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1201%2C626&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"626\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Mu\u00f1eco de torta\",\"datePublished\":\"2021-04-09T09:27:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/\"},\"wordCount\":759,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mborito.jpg?fit=1201%2C626&ssl=1\",\"keywords\":[\"daniel centurion\",\"destacada\",\"mario abdo\"],\"articleSection\":[\"Analisis\",\"Destacados\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/\",\"name\":\"Mu\u00f1eco de torta - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mborito.jpg?fit=1201%2C626&ssl=1\",\"datePublished\":\"2021-04-09T09:27:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mborito.jpg?fit=1201%2C626&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/mborito.jpg?fit=1201%2C626&ssl=1\",\"width\":1201,\"height\":626},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2021\\\/04\\\/09\\\/muneco-de-torta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mu\u00f1eco de torta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mu\u00f1eco de torta - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/","og_locale":"es_ES","og_type":"article","og_title":"Mu\u00f1eco de torta - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Este tipo, el turquito, parece un mu\u00f1eco de torta puesto de adorno sobre el merengue. Claro, a su lado la mu\u00f1equita, su parejita, quien otrora sol\u00eda cacarear al pedo cual gallina turuleca hasta que se fu\u00e9 a Miami para hacerse lavandera con toda su parentela. Mientras, aqu\u00ed, el prescindente propon\u00eda fundir la econom\u00eda paraguaya con [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-04-09T09:27:50+00:00","og_image":[{"width":1201,"height":626,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1201%2C626&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Mu\u00f1eco de torta","datePublished":"2021-04-09T09:27:50+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/"},"wordCount":759,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1201%2C626&ssl=1","keywords":["daniel centurion","destacada","mario abdo"],"articleSection":["Analisis","Destacados"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/","url":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/","name":"Mu\u00f1eco de torta - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1201%2C626&ssl=1","datePublished":"2021-04-09T09:27:50+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1201%2C626&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1201%2C626&ssl=1","width":1201,"height":626},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2021\/04\/09\/muneco-de-torta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Mu\u00f1eco de torta"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1201%2C626&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/2574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=2574"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/2574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/2575"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=2574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=2574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=2574"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=2574"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=2574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}