{"id":24093,"date":"2024-03-12T11:50:48","date_gmt":"2024-03-12T14:50:48","guid":{"rendered":"https:\/\/informatepy.com\/2024\/?p=24093"},"modified":"2024-03-12T11:52:40","modified_gmt":"2024-03-12T14:52:40","slug":"podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/","title":{"rendered":"PODCAST: Batalla de Cerro Cora parte 01 &#8211; \u00daltimas Palabras del Mariscal L\u00f3pez"},"content":{"rendered":"\n<p>\u00bfC\u00f3mo muri\u00f3 el Mariscal L\u00f3pez, seg\u00fan los propios brasile\u00f1os? El Prof. Emilio Urdapilleta te lo cuenta en este primer cap\u00edtulo de <em>\u00abReal Historia\u00bb.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"PODCAST: Real Historia - Batalla Cerro Cor\u00e1\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rfhaAHQL2WA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo muri\u00f3 el Mariscal L\u00f3pez, seg\u00fan los propios brasile\u00f1os? El Prof. Emilio Urdapilleta te lo cuenta en este primer cap\u00edtulo de \u00abReal Historia\u00bb.<\/p>\n","protected":false},"author":3,"featured_media":24095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"2","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"0","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"0","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[45,42],"tags":[],"jnews-series":[],"ppma_author":[830],"class_list":["post-24093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcasts","category-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PODCAST: Batalla de Cerro Cora parte 01 - \u00daltimas Palabras del Mariscal L\u00f3pez - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PODCAST: Batalla de Cerro Cora parte 01 - \u00daltimas Palabras del Mariscal L\u00f3pez - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo muri\u00f3 el Mariscal L\u00f3pez, seg\u00fan los propios brasile\u00f1os? El Prof. Emilio Urdapilleta te lo cuenta en este primer cap\u00edtulo de \u00abReal Historia\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T14:50:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T14:52:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/03\/real-historia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"PODCAST: Batalla de Cerro Cora parte 01 &#8211; \u00daltimas Palabras del Mariscal L\u00f3pez\",\"datePublished\":\"2024-03-12T14:50:48+00:00\",\"dateModified\":\"2024-03-12T14:52:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/\"},\"wordCount\":46,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/real-historia.jpg?fit=2560%2C1440&ssl=1\",\"articleSection\":[\"Podcasts\",\"Videos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/\",\"name\":\"PODCAST: Batalla de Cerro Cora parte 01 - \u00daltimas Palabras del Mariscal L\u00f3pez - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/real-historia.jpg?fit=2560%2C1440&ssl=1\",\"datePublished\":\"2024-03-12T14:50:48+00:00\",\"dateModified\":\"2024-03-12T14:52:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/real-historia.jpg?fit=2560%2C1440&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/real-historia.jpg?fit=2560%2C1440&ssl=1\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2024\\\/03\\\/12\\\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PODCAST: Batalla de Cerro Cora parte 01 &#8211; \u00daltimas Palabras del Mariscal L\u00f3pez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PODCAST: Batalla de Cerro Cora parte 01 - \u00daltimas Palabras del Mariscal L\u00f3pez - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/","og_locale":"es_ES","og_type":"article","og_title":"PODCAST: Batalla de Cerro Cora parte 01 - \u00daltimas Palabras del Mariscal L\u00f3pez - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"\u00bfC\u00f3mo muri\u00f3 el Mariscal L\u00f3pez, seg\u00fan los propios brasile\u00f1os? El Prof. Emilio Urdapilleta te lo cuenta en este primer cap\u00edtulo de \u00abReal Historia\u00bb.","og_url":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2024-03-12T14:50:48+00:00","article_modified_time":"2024-03-12T14:52:40+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/03\/real-historia.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"PODCAST: Batalla de Cerro Cora parte 01 &#8211; \u00daltimas Palabras del Mariscal L\u00f3pez","datePublished":"2024-03-12T14:50:48+00:00","dateModified":"2024-03-12T14:52:40+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/"},"wordCount":46,"commentCount":1,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/03\/real-historia.jpg?fit=2560%2C1440&ssl=1","articleSection":["Podcasts","Videos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/","url":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/","name":"PODCAST: Batalla de Cerro Cora parte 01 - \u00daltimas Palabras del Mariscal L\u00f3pez - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/03\/real-historia.jpg?fit=2560%2C1440&ssl=1","datePublished":"2024-03-12T14:50:48+00:00","dateModified":"2024-03-12T14:52:40+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/03\/real-historia.jpg?fit=2560%2C1440&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/03\/real-historia.jpg?fit=2560%2C1440&ssl=1","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2024\/03\/12\/podcast-batalla-de-cerro-cora-parte-01-ultimas-palabras-del-mariscal-lopez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"PODCAST: Batalla de Cerro Cora parte 01 &#8211; \u00daltimas Palabras del Mariscal L\u00f3pez"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/03\/real-historia.jpg?fit=2560%2C1440&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/24093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=24093"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/24093\/revisions"}],"predecessor-version":[{"id":24094,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/24093\/revisions\/24094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/24095"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=24093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=24093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=24093"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=24093"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=24093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}