{"id":186,"date":"2019-02-10T20:19:00","date_gmt":"2019-02-10T19:19:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/"},"modified":"2019-02-10T20:19:00","modified_gmt":"2019-02-10T19:19:00","slug":"cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/","title":{"rendered":"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca"},"content":{"rendered":"\n<p>En ingl\u00e9s hay un dicho que reza: \u00abBeer before wine and you&#8217;ll feel fine, wine before beer and you&#8217;ll feel queer\u00bb.<\/p>\n\n\n\n<p>La traducci\u00f3n vendr\u00eda a ser que, de cara a la m\u00e1s que previsible resaca que tendremos tras haber mezclado varias bebidas alcoh\u00f3licas, es mejor beber&nbsp;<strong>primero cerveza y despu\u00e9s vino<\/strong>.<\/p>\n\n\n\n<p>De lo contrario, parece que al d\u00eda siguiente nos sentiremos todav\u00eda peor.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La raz\u00f3n gen\u00e9tica por la que algunos no sufren resaca despu\u00e9s de una borrachera<\/li><li>\u00abEl alcohol era m\u00e1s importante para m\u00ed que mi matrimonio\u00bb: qu\u00e9 es el alcoholismo funcional y c\u00f3mo saber si lo padeces<\/li><\/ul>\n\n\n\n<p>La cultura popular anglosajona no es la \u00fanica que refleja la creencia de que, cuando se trata de tomar m\u00e1s de una bebida alcoh\u00f3lica, el orden de los factores s\u00ed altera el producto.<\/p>\n\n\n\n<p>Sin embargo, un nuevo estudio publicado en el &#8216;American Journal of Clinical Nutrition&#8217;&nbsp;<strong>refuta la idea<\/strong>&nbsp;de que el orden en que tomamos bebidas alcoh\u00f3licas afecte a la gravedad de la resaca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p>As\u00ed se hizo el estudio<\/p>\n\n\n\n<p>Sorprendentemente, no se sabe qu\u00e9 es exactamente lo que causa la resaca, y la ciencia no le encontr\u00f3 un remedio realmente efectivo.<\/p>\n\n\n\n<p>Para saber si el orden en que tomamos las bebidas alcoh\u00f3licas afecta a c\u00f3mo nos sentimos al d\u00eda siguiente, los cient\u00edficos eligieron a&nbsp;<strong>90 estudiantes de entre 19 y 40 a\u00f1os<\/strong>&nbsp;y los dividieron en tres grupos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El primer grupo bebi\u00f3 alrededor de un litro y medio de cerveza, y luego cuatro vasos grandes de vino blanco.<\/li><li>El segundo grupo bebi\u00f3 las mismas cantidades de alcohol pero en orden inverso.<\/li><li>El tercer grupo bebi\u00f3 solo cerveza o vino (era el grupo de control)<\/li><\/ul>\n\n\n\n<p>Una semana m\u00e1s tarde, los participantes del primer y el segundo grupo se intercambiaron, mientras que los del grupo de control cambiaron a la otra bebida alcoh\u00f3lica.<\/p>\n\n\n\n<p>Se les pidi\u00f3 que juzgaran cu\u00e1n borrachos estaban al final de cada d\u00eda de estudio y estuvieron&nbsp;<strong>bajo supervisi\u00f3n m\u00e9dica&nbsp;<\/strong>durante la noche.<\/p>\n\n\n\n<p>Las conclusiones del estudio fueron que&nbsp;<strong>cambiar el orden de las bebidas no se tradujo en una diferencia significativa<\/strong>&nbsp;a la hora de valorar la resaca, cosa que hicieron mediante un cuestionario.<\/p>\n\n\n\n<p>Seg\u00fan el estudio, la sensaci\u00f3n de ebriedad que ten\u00edan los participantes y el hecho de si vomitaban o no eran los mejores indicadores de c\u00f3mo se sentir\u00edan al d\u00eda siguiente.<\/p>\n\n\n\n<p>Los investigadores tampoco lograron predecir la intensidad de la resaca en funci\u00f3n de factores como la edad, el peso, los h\u00e1bitos de consumo y la frecuencia con la que ten\u00edan resaca.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Los meses y a\u00f1os que pierdes de vida si bebes alcohol a diario<\/li><\/ul>\n\n\n\n<p>Sin embargo, s\u00ed hubo una diferencia entre mujeres hombres: parece que&nbsp;<strong>ellas tend\u00edan a sufrir una resaca ligeramente peor<\/strong>&nbsp;que los hombres.<\/p>\n\n\n\n<p>J\u00f6ran K\u00f6chling, uno de los autores del art\u00edculo de la Universidad Witten\/Herdecke, explic\u00f3: \u00abLa \u00fanica forma segura de predecir lo mal que te sentir\u00e1s al d\u00eda siguiente es cu\u00e1n borracho te sientes y si est\u00e1s enfermo. Debemos tener en cuenta estos toques de atenci\u00f3n cuando bebemos\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las se\u00f1ales de alerta<\/h2>\n\n\n\n<p>Aunque la ciencia no acaba de descifrar el porqu\u00e9 de la resaca, se cree que las causas tienen que ver con la&nbsp;<strong>deshidrataci\u00f3n<\/strong>, con el sistema inmunol\u00f3gico y con trastornos del metabolismo y las hormonas.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qu\u00e9 son los sulfitos y por qu\u00e9 algunas personas no pueden tomarlos (y no tiene nada que ver con la resaca)<\/li><\/ul>\n\n\n\n<p>Los colorantes y los aromas tambi\u00e9n pueden empeorar la resaca, lo que podr\u00eda explicar por qu\u00e9 bebidas con la misma concentraci\u00f3n de alcohol pueden causar una resaca m\u00e1s severa.<\/p>\n\n\n\n<p>Uno de los hallazgos del estudio fue que los participantes que vomitaban ten\u00edan m\u00e1s probabilidades de tener una resaca peor.<\/p>\n\n\n\n<p>\u00bfSignifica eso que&nbsp;<strong>provocarse el v\u00f3mito<\/strong>&nbsp;para deshacerse de parte del alcohol consumido y disminuir as\u00ed la resaca tambi\u00e9n es un mito?<\/p>\n\n\n\n<p>Kai Hensel, uno de los autores del estudio de la Universidad de Cambridge, afirm\u00f3 que deshacerse de parte del alcohol significaba que el cuerpo absorber\u00eda menos, lo que podr\u00eda hacer que uno se sienta mejor al d\u00eda siguiente.<\/p>\n\n\n\n<p>Pero, aun as\u00ed, asegur\u00f3 que era una pr\u00e1ctica que \u00e9l<strong>&nbsp;no recomendar\u00eda<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Por qu\u00e9 algunas personas pierden completamente la memoria durante una borrachera (y qu\u00e9 nos dice esto de su salud)<\/li><li>\u00abNunca me imagin\u00e9 que a los 25 a\u00f1os ya ser\u00eda un alcoh\u00f3lico\u00bb<\/li><\/ul>\n\n\n\n<p>\u00abSi llegas a un punto en el que necesitas estar enfermo, probablemente has pasado el punto de no retorno\u00bb, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Y es que, por desagradables que sean, las resacas tienen un prop\u00f3sito: los expertos afirman que son el&nbsp;<strong>sistema de advertencia de la naturaleza<\/strong>&nbsp;para alentarnos a beber menos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consejos para evitar la resaca<\/h2>\n\n\n\n<p>No hay una cura m\u00e1gica para la resaca. De todas maneras, es posible aliviar el malestar rehidrat\u00e1ndose, con analg\u00e9sicos como el paracetamol y el ibuprofeno y tomando alimentos azucarados.<\/p>\n\n\n\n<p>Sin embargo, s\u00ed hay algunos trucos que pueden reducir la posibilidad de acabar con resaca, m\u00e1s all\u00e1 del m\u00e1s obvio:&nbsp;<strong>beber menos<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>No beber con el est\u00f3mago vac\u00edo.<\/li><li>No tomar bebidas de color oscuro si eres sensible a ellas (contienen sustancias qu\u00edmicas que irritan los vasos sangu\u00edneos y los tejidos del cerebro y pueden empeorar la resaca).<\/li><li>Beber agua o refrescos no gaseosos entre cada bebida alcoh\u00f3lica.<\/li><li>Beber medio litro de agua antes de ir a dormir.<\/li><\/ul>\n\n\n\n<p>(Fuente: sistema p\u00fablico de salud del Reino Unido)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En ingl\u00e9s hay un dicho que reza: \u00abBeer before wine and you&#8217;ll feel fine, wine before beer and you&#8217;ll feel queer\u00bb. La traducci\u00f3n vendr\u00eda a ser que, de cara a la m\u00e1s que previsible resaca que tendremos tras haber mezclado varias bebidas alcoh\u00f3licas, es mejor beber&nbsp;primero cerveza y despu\u00e9s vino. De lo contrario, parece que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[36],"tags":[131,132],"jnews-series":[],"ppma_author":[47],"class_list":["post-186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-bebidas-alcoholicas","tag-resaca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En ingl\u00e9s hay un dicho que reza: \u00abBeer before wine and you&#8217;ll feel fine, wine before beer and you&#8217;ll feel queer\u00bb. La traducci\u00f3n vendr\u00eda a ser que, de cara a la m\u00e1s que previsible resaca que tendremos tras haber mezclado varias bebidas alcoh\u00f3licas, es mejor beber&nbsp;primero cerveza y despu\u00e9s vino. De lo contrario, parece que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-10T19:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/resaca.jpg?fit=660%2C371&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicoCPT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicoCPT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/\"},\"author\":{\"name\":\"NicoCPT\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\"},\"headline\":\"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca\",\"datePublished\":\"2019-02-10T19:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/\"},\"wordCount\":999,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/resaca.jpg?fit=660%2C371&ssl=1\",\"keywords\":[\"bebidas alcoholicas\",\"resaca\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/\",\"name\":\"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/resaca.jpg?fit=660%2C371&ssl=1\",\"datePublished\":\"2019-02-10T19:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/resaca.jpg?fit=660%2C371&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/resaca.jpg?fit=660%2C371&ssl=1\",\"width\":660,\"height\":371},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/02\\\/10\\\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\",\"name\":\"NicoCPT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"NicoCPT\"},\"sameAs\":[\"https:\\\/\\\/informatepy.com\\\/2024\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/nicocpt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En ingl\u00e9s hay un dicho que reza: \u00abBeer before wine and you&#8217;ll feel fine, wine before beer and you&#8217;ll feel queer\u00bb. La traducci\u00f3n vendr\u00eda a ser que, de cara a la m\u00e1s que previsible resaca que tendremos tras haber mezclado varias bebidas alcoh\u00f3licas, es mejor beber&nbsp;primero cerveza y despu\u00e9s vino. De lo contrario, parece que [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2019-02-10T19:19:00+00:00","og_image":[{"width":660,"height":371,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/resaca.jpg?fit=660%2C371&ssl=1","type":"image\/jpeg"}],"author":"NicoCPT","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"NicoCPT","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/"},"author":{"name":"NicoCPT","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e"},"headline":"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca","datePublished":"2019-02-10T19:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/"},"wordCount":999,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/resaca.jpg?fit=660%2C371&ssl=1","keywords":["bebidas alcoholicas","resaca"],"articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/","url":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/","name":"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/resaca.jpg?fit=660%2C371&ssl=1","datePublished":"2019-02-10T19:19:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/resaca.jpg?fit=660%2C371&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/resaca.jpg?fit=660%2C371&ssl=1","width":660,"height":371},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2019\/02\/10\/cerveza-y-despues-vino-o-al-reves-el-experimento-que-analiza-si-el-orden-en-el-que-tomamos-bebidas-alcoholicas-afecta-a-la-resaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"\u00bfCerveza y despu\u00e9s vino o al rev\u00e9s? El experimento que analiza si el orden en el que tomamos bebidas alcoh\u00f3licas afecta a la resaca"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e","name":"NicoCPT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"NicoCPT"},"sameAs":["https:\/\/informatepy.com\/2024"],"url":"https:\/\/informatepy.com\/2024\/author\/nicocpt\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/02\/resaca.jpg?fit=660%2C371&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":47,"user_id":1,"is_guest":0,"slug":"nicocpt","display_name":"NicoCPT","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"https:\/\/informatepy.com\/2024","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/187"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=186"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=186"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}