{"id":1744,"date":"2020-08-15T20:20:00","date_gmt":"2020-08-15T18:20:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/"},"modified":"2020-08-15T20:20:00","modified_gmt":"2020-08-15T18:20:00","slug":"no-esperabamos-nada-aun-asi-logro-decepcionarnos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/","title":{"rendered":"No esper\u00e1bamos nada&#8230; a\u00fan as\u00ed logr\u00f3 decepcionarnos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Transcurrieron dos a\u00f1os de mandato del Presidente Mario Abdo; un presidente del que muchos no esper\u00e1bamos nada. A\u00fan as\u00ed, ni el m\u00e1s esc\u00e9ptico pod\u00eda vaticinar el nivel de decadencia en el que se ver\u00eda sumergido el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Independientemente de la pandemia, la cual sin dudas ha contribuido a este desastre, desde el gobierno mismo se han encargado de acentuar la crisis de la cual se har\u00e1 muy dif\u00edcil salir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una sucesi\u00f3n (constante) de malas de decisiones han puesto al gobierno de Mario Abdo en una espiral descendente. Acusaciones permanentes de corrupci\u00f3n en su gabinete, despilfarro del dinero p\u00fablico, obscenidad frente a un pueblo hambreado y hasta una acusaci\u00f3n de traici\u00f3n a la patria que nunca fue del todo aclarada, hacen de este gobierno uno de los peores de los \u00faltimos tiempos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quisiera seguir pero, como dice <strong>Prov. 10:19, <em>\u00abEn las muchas palabras no falta pecado\u00bb<\/em><\/strong>. Ojal\u00e1, por el bien del pa\u00eds, el Presidente Mario Abdo rectifique el rumbo, es ahora, est\u00e1 a tiempo de evitar pasar a la historia como un trago amargo, como un chiste de al gusto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transcurrieron dos a\u00f1os de mandato del Presidente Mario Abdo; un presidente del que muchos no esper\u00e1bamos nada. A\u00fan as\u00ed, ni el m\u00e1s esc\u00e9ptico pod\u00eda vaticinar el nivel de decadencia en el que se ver\u00eda sumergido el pa\u00eds. Independientemente de la pandemia, la cual sin dudas ha contribuido a este desastre, desde el gobierno mismo se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[39],"tags":[197],"jnews-series":[],"ppma_author":[47],"class_list":["post-1744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-mario-abdo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No esper\u00e1bamos nada... a\u00fan as\u00ed logr\u00f3 decepcionarnos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No esper\u00e1bamos nada... a\u00fan as\u00ed logr\u00f3 decepcionarnos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Transcurrieron dos a\u00f1os de mandato del Presidente Mario Abdo; un presidente del que muchos no esper\u00e1bamos nada. A\u00fan as\u00ed, ni el m\u00e1s esc\u00e9ptico pod\u00eda vaticinar el nivel de decadencia en el que se ver\u00eda sumergido el pa\u00eds. Independientemente de la pandemia, la cual sin dudas ha contribuido a este desastre, desde el gobierno mismo se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-15T18:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicoCPT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicoCPT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/\"},\"author\":{\"name\":\"NicoCPT\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\"},\"headline\":\"No esper\u00e1bamos nada&#8230; a\u00fan as\u00ed logr\u00f3 decepcionarnos\",\"datePublished\":\"2020-08-15T18:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1\",\"keywords\":[\"mario abdo\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/\",\"name\":\"No esper\u00e1bamos nada... a\u00fan as\u00ed logr\u00f3 decepcionarnos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1\",\"datePublished\":\"2020-08-15T18:20:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1\",\"width\":720,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2020\\\/08\\\/15\\\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No esper\u00e1bamos nada&#8230; a\u00fan as\u00ed logr\u00f3 decepcionarnos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\",\"name\":\"NicoCPT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"NicoCPT\"},\"sameAs\":[\"https:\\\/\\\/informatepy.com\\\/2024\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/nicocpt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No esper\u00e1bamos nada... a\u00fan as\u00ed logr\u00f3 decepcionarnos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/","og_locale":"es_ES","og_type":"article","og_title":"No esper\u00e1bamos nada... a\u00fan as\u00ed logr\u00f3 decepcionarnos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Transcurrieron dos a\u00f1os de mandato del Presidente Mario Abdo; un presidente del que muchos no esper\u00e1bamos nada. A\u00fan as\u00ed, ni el m\u00e1s esc\u00e9ptico pod\u00eda vaticinar el nivel de decadencia en el que se ver\u00eda sumergido el pa\u00eds. Independientemente de la pandemia, la cual sin dudas ha contribuido a este desastre, desde el gobierno mismo se [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2020-08-15T18:20:00+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1","type":"image\/jpeg"}],"author":"NicoCPT","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"NicoCPT","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/"},"author":{"name":"NicoCPT","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e"},"headline":"No esper\u00e1bamos nada&#8230; a\u00fan as\u00ed logr\u00f3 decepcionarnos","datePublished":"2020-08-15T18:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/"},"wordCount":202,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1","keywords":["mario abdo"],"articleSection":["Analisis"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/","url":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/","name":"No esper\u00e1bamos nada... a\u00fan as\u00ed logr\u00f3 decepcionarnos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1","datePublished":"2020-08-15T18:20:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1","width":720,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2020\/08\/15\/no-esperabamos-nada-aun-asi-logro-decepcionarnos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"No esper\u00e1bamos nada&#8230; a\u00fan as\u00ed logr\u00f3 decepcionarnos"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e","name":"NicoCPT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"NicoCPT"},"sameAs":["https:\/\/informatepy.com\/2024"],"url":"https:\/\/informatepy.com\/2024\/author\/nicocpt\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/abdo-asuncion-presidencial.jpg?fit=720%2C480&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":47,"user_id":1,"is_guest":0,"slug":"nicocpt","display_name":"NicoCPT","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"https:\/\/informatepy.com\/2024","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/1744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=1744"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/1744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/1745"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=1744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=1744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=1744"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=1744"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=1744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}