{"id":12095,"date":"2023-11-13T07:00:00","date_gmt":"2023-11-13T06:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/"},"modified":"2023-11-13T07:00:00","modified_gmt":"2023-11-13T06:00:00","slug":"sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/","title":{"rendered":"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">En el marco del Proyecto <strong><em>\u201cFortalecimiento institucional para la implementaci\u00f3n de experiencias basadas en modelos educativos flexibles\u201d<\/em><\/strong>, impulsado por la Comisi\u00f3n Ad Hoc de Ense\u00f1anza Media del Sector Educativo del MERCOSUR, se pone a conocimiento la convocatoria para contrataci\u00f3n de cuatro consultores (uno por cada pa\u00eds miembro) especialistas en las \u00e1reas de ciencias de la educaci\u00f3n y\/o ciencias sociales, con experiencia en investigaci\u00f3n en educaci\u00f3n media\/secundaria. Los interesados podr\u00e1n postularse hasta el 24 de noviembre del a\u00f1o en curso.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Al respecto, cada profesional contratado en car\u00e1cter de consultor deber\u00e1 desarrollar su trabajo sobre dos (2) experiencias educativas seleccionadas por el Ministerio de Educaci\u00f3n de cada pa\u00eds.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Las postulaciones deber\u00e1n ser remitidas al\u00a0<em>correo\u00a0<\/em><a href=\"mailto:dgpbcyp@mec.gov.py\" target=\"_blank\" rel=\"noreferrer noopener\"><em>dgpbcyp@mec.gov.py<\/em><\/a><em>.<\/em> Para m\u00e1s informaci\u00f3n, se adjuntan los\u00a0<a href=\"https:\/\/www.mec.gov.py\/cms_v2\/adjuntos\/20396?1699638712\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9rminos de Referencia -TDR.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del Proyecto \u201cFortalecimiento institucional para la implementaci\u00f3n de experiencias basadas en modelos educativos flexibles\u201d, impulsado por la Comisi\u00f3n Ad Hoc de Ense\u00f1anza Media del Sector Educativo del MERCOSUR, se pone a conocimiento la convocatoria para contrataci\u00f3n de cuatro consultores (uno por cada pa\u00eds miembro) especialistas en las \u00e1reas de ciencias de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":3,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43],"tags":[831,667,1104,341],"jnews-series":[],"ppma_author":[830],"class_list":["post-12095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-destacada","tag-mec","tag-mercosur","tag-ministerio-de-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En el marco del Proyecto \u201cFortalecimiento institucional para la implementaci\u00f3n de experiencias basadas en modelos educativos flexibles\u201d, impulsado por la Comisi\u00f3n Ad Hoc de Ense\u00f1anza Media del Sector Educativo del MERCOSUR, se pone a conocimiento la convocatoria para contrataci\u00f3n de cuatro consultores (uno por cada pa\u00eds miembro) especialistas en las \u00e1reas de ciencias de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-13T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales\",\"datePublished\":\"2023-11-13T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/\"},\"wordCount\":157,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mercosur.jpg?fit=1200%2C675&ssl=1\",\"keywords\":[\"destacada\",\"mec\",\"mercosur\",\"ministerio de educaci\u00f3n\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/\",\"name\":\"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mercosur.jpg?fit=1200%2C675&ssl=1\",\"datePublished\":\"2023-11-13T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mercosur.jpg?fit=1200%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mercosur.jpg?fit=1200%2C675&ssl=1\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/13\\\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/","og_locale":"es_ES","og_type":"article","og_title":"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En el marco del Proyecto \u201cFortalecimiento institucional para la implementaci\u00f3n de experiencias basadas en modelos educativos flexibles\u201d, impulsado por la Comisi\u00f3n Ad Hoc de Ense\u00f1anza Media del Sector Educativo del MERCOSUR, se pone a conocimiento la convocatoria para contrataci\u00f3n de cuatro consultores (uno por cada pa\u00eds miembro) especialistas en las \u00e1reas de ciencias de la [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-11-13T06:00:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales","datePublished":"2023-11-13T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/"},"wordCount":157,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1","keywords":["destacada","mec","mercosur","ministerio de educaci\u00f3n"],"articleSection":["Cultura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/","url":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/","name":"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1","datePublished":"2023-11-13T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/13\/sector-educativo-del-mercosur-llama-a-concurso-para-contratacion-temporal-de-profesionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Sector Educativo del Mercosur llama a concurso para contrataci\u00f3n temporal de profesionales"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/12095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=12095"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/12095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/3294"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=12095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=12095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=12095"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=12095"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=12095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}