{"id":12081,"date":"2023-11-11T07:01:00","date_gmt":"2023-11-11T06:01:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/"},"modified":"2023-11-11T07:01:00","modified_gmt":"2023-11-11T06:01:00","slug":"mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/","title":{"rendered":"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">En un comunicado, el <strong>Ministerio de Educaci\u00f3n y Ciencias (MEC)<\/strong> inform\u00f3 que detectaron al menos 1.000 t\u00edtulos adulterados provenientes de institutos de formaci\u00f3n docente que no existen. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El viceministro, <strong>Federico Mora<\/strong>, afirm\u00f3 que las irregularidades fueron comprobadas a partir de denuncias recibidas en la propia instituci\u00f3n del Estado.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong><em>\u201cLo que nosotros tenemos es un proceso de certificaci\u00f3n docente y matriculaci\u00f3n. Estamos hablando exclusivamente de t\u00edtulos de casos para la docencia o para el proceso de registro en el sistema inform\u00e1tico de talento humano que tiene el ministerio y encontramos registros dubitados. Es decir, est\u00e1n en su proceso porque no fueron en su momento t\u00edtulos registrados o que constan en la direcci\u00f3n de registros de t\u00edtulos del MEC\u201d<\/em><\/strong>,&nbsp;indic\u00f3 Mora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u201cSon t\u00edtulos falsos en todo sentido\u201d<\/em><\/strong> y asegur\u00f3 que los t\u00edtulos fraguados <strong><em>\u201cno pasaron el reconocimiento o el registro de t\u00edtulos por parte del MEC\u201d.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Refiri\u00f3 que la pr\u00e1ctica de la falsificaci\u00f3n de t\u00edtulos <em><strong>\u201ces una realidad\u201d <\/strong><\/em>y lament\u00f3 que se recurren a diferentes formas, incluso para participar en concursos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u2b55 Comunicado <a href=\"https:\/\/twitter.com\/hashtag\/MEC?src=hash&amp;ref_src=twsrc%5Etfw\">#MEC<\/a><br><br>\ud83d\udc49 Referente a esquemas de creaci\u00f3n de certificados o t\u00edtulos con contenidos aparentemente falsos y vulneraci\u00f3n de registros acad\u00e9micos. <a href=\"https:\/\/t.co\/071hVfFFc5\">pic.twitter.com\/071hVfFFc5<\/a><\/p>&mdash; MECpy (@MECpy) <a href=\"https:\/\/twitter.com\/MECpy\/status\/1723084385593766090?ref_src=twsrc%5Etfw\">November 10, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><em><strong>\u00abLo que corresponde ahora es la identificaci\u00f3n de cada uno de los casos, remitir a la Fiscal\u00eda y generar los sumarios correspondientes\u00bb<\/strong><\/em>, expres\u00f3 Mora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un comunicado, el Ministerio de Educaci\u00f3n y Ciencias (MEC) inform\u00f3 que detectaron al menos 1.000 t\u00edtulos adulterados provenientes de institutos de formaci\u00f3n docente que no existen. El viceministro, Federico Mora, afirm\u00f3 que las irregularidades fueron comprobadas a partir de denuncias recibidas en la propia instituci\u00f3n del Estado. \u201cLo que nosotros tenemos es un proceso [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":1,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[831,1540,667,341],"jnews-series":[],"ppma_author":[830],"class_list":["post-12081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-federico-mora","tag-mec","tag-ministerio-de-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En un comunicado, el Ministerio de Educaci\u00f3n y Ciencias (MEC) inform\u00f3 que detectaron al menos 1.000 t\u00edtulos adulterados provenientes de institutos de formaci\u00f3n docente que no existen. El viceministro, Federico Mora, afirm\u00f3 que las irregularidades fueron comprobadas a partir de denuncias recibidas en la propia instituci\u00f3n del Estado. \u201cLo que nosotros tenemos es un proceso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-11T06:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/Federico-Mora.webp?fit=994%2C614&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"994\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos\",\"datePublished\":\"2023-11-11T06:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/\"},\"wordCount\":231,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Federico-Mora.webp?fit=994%2C614&ssl=1\",\"keywords\":[\"destacada\",\"federico mora\",\"mec\",\"ministerio de educaci\u00f3n\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/\",\"name\":\"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Federico-Mora.webp?fit=994%2C614&ssl=1\",\"datePublished\":\"2023-11-11T06:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Federico-Mora.webp?fit=994%2C614&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Federico-Mora.webp?fit=994%2C614&ssl=1\",\"width\":994,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/11\\\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/","og_locale":"es_ES","og_type":"article","og_title":"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En un comunicado, el Ministerio de Educaci\u00f3n y Ciencias (MEC) inform\u00f3 que detectaron al menos 1.000 t\u00edtulos adulterados provenientes de institutos de formaci\u00f3n docente que no existen. El viceministro, Federico Mora, afirm\u00f3 que las irregularidades fueron comprobadas a partir de denuncias recibidas en la propia instituci\u00f3n del Estado. \u201cLo que nosotros tenemos es un proceso [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-11-11T06:01:00+00:00","og_image":[{"width":994,"height":614,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/Federico-Mora.webp?fit=994%2C614&ssl=1","type":"image\/webp"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos","datePublished":"2023-11-11T06:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/"},"wordCount":231,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/Federico-Mora.webp?fit=994%2C614&ssl=1","keywords":["destacada","federico mora","mec","ministerio de educaci\u00f3n"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/","url":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/","name":"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/Federico-Mora.webp?fit=994%2C614&ssl=1","datePublished":"2023-11-11T06:01:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/Federico-Mora.webp?fit=994%2C614&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/Federico-Mora.webp?fit=994%2C614&ssl=1","width":994,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/11\/mec-detecto-al-menos-1-000-titulos-adulterados-de-institutos-no-reconocidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"MEC detect\u00f3 al menos 1.000 t\u00edtulos docentes adulterados o de institutos no reconocidos"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/Federico-Mora.webp?fit=994%2C614&ssl=1","_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/12081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=12081"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/12081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/9933"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=12081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=12081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=12081"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=12081"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=12081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}