{"id":11971,"date":"2023-11-01T07:01:00","date_gmt":"2023-11-01T06:01:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/"},"modified":"2023-11-01T07:01:00","modified_gmt":"2023-11-01T06:01:00","slug":"horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/","title":{"rendered":"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El expresidente de la Rep\u00fablica, <strong>Horacio Cartes<\/strong>, con patrocinio de su abogado <strong>Pedro Ovelar<\/strong>, present\u00f3 una nueva ampliaci\u00f3n de su denuncia por persecuci\u00f3n pol\u00edtica. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Los documentos acercados al Ministerio P\u00fablico dan cuenta de las acciones supuestamente orquestadas por el gobierno de <strong>Mario Abdo Ben\u00edtez <\/strong>en contra del exmandatario.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El abogado explic\u00f3 que, en base al hecho de persecuci\u00f3n pol\u00edtica en democracia, se configuran conductas previstas en el C\u00f3digo Penal, sobre los<strong>\u00a0<\/strong>acontecimientos recientes, que demuestran<strong><em> \u201ctodo el plan urdido desde \u00f3rganos del gobierno anterior\u201d.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Agreg\u00f3 que, <strong><em>\u201ccon el fin de instalar mentiras y manipular a la informaci\u00f3n p\u00fablica con informaci\u00f3n falsa, tergiversada y sin prueba alguna\u201d<\/em><\/strong>, la persecuci\u00f3n contra Cartes fue coordinada y publicitada por medios de prensa cercanos al gobierno de Mario Abdo.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><a href=\"https:\/\/www.hoy.com.py\/#facebook\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-21797\" data-id=\"21797\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/10\/ovelar1-scaled.jpg?ssl=1\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-21796\" data-id=\"21796\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/10\/ovelar2-scaled.jpg?ssl=1\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-21795\" data-id=\"21795\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/10\/ovelar3-scaled.jpg?ssl=1\"\/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El expresidente de la Rep\u00fablica, Horacio Cartes, con patrocinio de su abogado Pedro Ovelar, present\u00f3 una nueva ampliaci\u00f3n de su denuncia por persecuci\u00f3n pol\u00edtica. Los documentos acercados al Ministerio P\u00fablico dan cuenta de las acciones supuestamente orquestadas por el gobierno de Mario Abdo Ben\u00edtez en contra del exmandatario. El abogado explic\u00f3 que, en base al [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[138,831,282,197,286],"jnews-series":[],"ppma_author":[830],"class_list":["post-11971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-anr","tag-destacada","tag-horacio-cartes","tag-mario-abdo","tag-partido-colorado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"El expresidente de la Rep\u00fablica, Horacio Cartes, con patrocinio de su abogado Pedro Ovelar, present\u00f3 una nueva ampliaci\u00f3n de su denuncia por persecuci\u00f3n pol\u00edtica. Los documentos acercados al Ministerio P\u00fablico dan cuenta de las acciones supuestamente orquestadas por el gobierno de Mario Abdo Ben\u00edtez en contra del exmandatario. El abogado explic\u00f3 que, en base al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-01T06:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/cartes-saludando.jpg?fit=1600%2C900&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica\",\"datePublished\":\"2023-11-01T06:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/\"},\"wordCount\":149,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cartes-saludando.jpg?fit=1600%2C900&ssl=1\",\"keywords\":[\"anr\",\"destacada\",\"horacio cartes\",\"mario abdo\",\"partido colorado\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/\",\"name\":\"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cartes-saludando.jpg?fit=1600%2C900&ssl=1\",\"datePublished\":\"2023-11-01T06:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cartes-saludando.jpg?fit=1600%2C900&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cartes-saludando.jpg?fit=1600%2C900&ssl=1\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/11\\\/01\\\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/","og_locale":"es_ES","og_type":"article","og_title":"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"El expresidente de la Rep\u00fablica, Horacio Cartes, con patrocinio de su abogado Pedro Ovelar, present\u00f3 una nueva ampliaci\u00f3n de su denuncia por persecuci\u00f3n pol\u00edtica. Los documentos acercados al Ministerio P\u00fablico dan cuenta de las acciones supuestamente orquestadas por el gobierno de Mario Abdo Ben\u00edtez en contra del exmandatario. El abogado explic\u00f3 que, en base al [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-11-01T06:01:00+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/cartes-saludando.jpg?fit=1600%2C900&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica","datePublished":"2023-11-01T06:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/"},"wordCount":149,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/cartes-saludando.jpg?fit=1600%2C900&ssl=1","keywords":["anr","destacada","horacio cartes","mario abdo","partido colorado"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/","url":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/","name":"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/cartes-saludando.jpg?fit=1600%2C900&ssl=1","datePublished":"2023-11-01T06:01:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/cartes-saludando.jpg?fit=1600%2C900&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/cartes-saludando.jpg?fit=1600%2C900&ssl=1","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/11\/01\/horacio-cartes-volvio-a-ampliar-su-denuncia-por-persecucion-politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Horacio Cartes volvi\u00f3 a ampliar su denuncia por persecuci\u00f3n pol\u00edtica"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/cartes-saludando.jpg?fit=1600%2C900&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=11971"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/1271"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=11971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=11971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=11971"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=11971"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=11971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}