{"id":11254,"date":"2023-08-07T09:24:00","date_gmt":"2023-08-07T07:24:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/"},"modified":"2023-08-07T09:24:00","modified_gmt":"2023-08-07T07:24:00","slug":"efrain-alegre-ya-no-es-presidente-del-partido-liberal","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/","title":{"rendered":"Efra\u00edn Alegre ya no es presidente del Partido Liberal"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">En una agitada convenci\u00f3n, dirigentes del <strong>Partido Liberal Radical Aut\u00e9ntico (PLRA)<\/strong>, separaron del cargo de presidente del Directorio del partido a <strong>Efra\u00edn Alegre<\/strong> con 319 votos a favor. En su reemplazo asume el vicepresidente primero, <strong>Hugo Fleitas<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">No obstante, con anterioridad a ser destituido, Efra\u00edn Alegre se retir\u00f3 de la convenci\u00f3n y anunci\u00f3, en sus redes sociales, que \u00e9l no iba a reconocer los resultados.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">A los cartistas atracadores les digo: Hay un solo presidente del PLRA, electo por el voto popular de los liberales y no por el dinero sucio de la mafia.<\/p>&mdash; Efra\u00edn Alegre (@EfrainAlegre) <a href=\"https:\/\/twitter.com\/EfrainAlegre\/status\/1688281553497894912?ref_src=twsrc%5Etfw\">August 6, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Convenci\u00f3n fiscalizada<\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">A pesar de los reclamos del ahora expresidente del PLRA, la convenci\u00f3n que lo destituy\u00f3 cont\u00f3 con la fiscalizaci\u00f3n de la Justicia Electoral, por lo que la decisi\u00f3n tomada ser\u00eda irrevocable. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Se espera que Alegre judicialice la resoluci\u00f3n adoptada por la convenci\u00f3n, lo que podr\u00eda terminar provocando el quiebre definitivo y la divisi\u00f3n del Partido Liberal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una agitada convenci\u00f3n, dirigentes del Partido Liberal Radical Aut\u00e9ntico (PLRA), separaron del cargo de presidente del Directorio del partido a Efra\u00edn Alegre con 319 votos a favor. En su reemplazo asume el vicepresidente primero, Hugo Fleitas. No obstante, con anterioridad a ser destituido, Efra\u00edn Alegre se retir\u00f3 de la convenci\u00f3n y anunci\u00f3, en sus [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[831,296,1570,396,297],"jnews-series":[],"ppma_author":[830],"class_list":["post-11254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-efrain-alegre","tag-hugo-fleitas","tag-partido-liberal","tag-plra"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Efra\u00edn Alegre ya no es presidente del Partido Liberal - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Efra\u00edn Alegre ya no es presidente del Partido Liberal - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En una agitada convenci\u00f3n, dirigentes del Partido Liberal Radical Aut\u00e9ntico (PLRA), separaron del cargo de presidente del Directorio del partido a Efra\u00edn Alegre con 319 votos a favor. En su reemplazo asume el vicepresidente primero, Hugo Fleitas. No obstante, con anterioridad a ser destituido, Efra\u00edn Alegre se retir\u00f3 de la convenci\u00f3n y anunci\u00f3, en sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-07T07:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/08\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Efra\u00edn Alegre ya no es presidente del Partido Liberal\",\"datePublished\":\"2023-08-07T07:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/\"},\"wordCount\":151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1\",\"keywords\":[\"destacada\",\"efra\u00edn alegre\",\"hugo fleitas\",\"partido liberal\",\"plra\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/\",\"name\":\"Efra\u00edn Alegre ya no es presidente del Partido Liberal - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1\",\"datePublished\":\"2023-08-07T07:24:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1\",\"width\":1280,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/08\\\/07\\\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Efra\u00edn Alegre ya no es presidente del Partido Liberal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Efra\u00edn Alegre ya no es presidente del Partido Liberal - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/","og_locale":"es_ES","og_type":"article","og_title":"Efra\u00edn Alegre ya no es presidente del Partido Liberal - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En una agitada convenci\u00f3n, dirigentes del Partido Liberal Radical Aut\u00e9ntico (PLRA), separaron del cargo de presidente del Directorio del partido a Efra\u00edn Alegre con 319 votos a favor. En su reemplazo asume el vicepresidente primero, Hugo Fleitas. No obstante, con anterioridad a ser destituido, Efra\u00edn Alegre se retir\u00f3 de la convenci\u00f3n y anunci\u00f3, en sus [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-08-07T07:24:00+00:00","og_image":[{"width":1280,"height":670,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/08\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Efra\u00edn Alegre ya no es presidente del Partido Liberal","datePublished":"2023-08-07T07:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/"},"wordCount":151,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/08\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1","keywords":["destacada","efra\u00edn alegre","hugo fleitas","partido liberal","plra"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/","url":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/","name":"Efra\u00edn Alegre ya no es presidente del Partido Liberal - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/08\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1","datePublished":"2023-08-07T07:24:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/08\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/08\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1","width":1280,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/08\/07\/efrain-alegre-ya-no-es-presidente-del-partido-liberal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Efra\u00edn Alegre ya no es presidente del Partido Liberal"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/08\/efrain-fleitas.jpg?fit=1280%2C670&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=11254"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/11255"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=11254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=11254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=11254"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=11254"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=11254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}