{"id":11188,"date":"2023-07-30T09:26:00","date_gmt":"2023-07-30T07:26:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/"},"modified":"2023-07-30T09:26:00","modified_gmt":"2023-07-30T07:26:00","slug":"bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/","title":{"rendered":"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">A mediados de los a\u00f1os 90, en casi toda Europa empezaron a aparecer organizaciones que promov\u00edan y celebraban los grandes aportes de la cultura isl\u00e1mica a Occidente. Sin embargo, detr\u00e1s de estas aparentes nobles reivindicaciones hist\u00f3ricas hab\u00eda un elemento oculto, <em>La guerra contra toda la cultura y la tradici\u00f3n judeocristiana de Europa<\/em>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Los hijos de Al\u00e1 y sus aliados, todo el progresismo europeo, intentaban mostrar que todos los grandes pilares de nuestra civilizaci\u00f3n, entre ellas, la filosof\u00eda, son, b\u00e1sicamente, herencias del Islam. La premisa principal de todo era: <em>Ustedes no son nada sin nosotros, por ende, tenemos el derecho de ocupar toda Europa.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">A finales del Siglo 20, la periodista Oriana Fallaci y el pol\u00edtico Hallgrim Berg advirtieron que Occidente estaba siendo traicionado por toda la izquierda, pues, a nombre de \u00abinclusi\u00f3n\u00bb, \u00abtolerancia\u00bb y \u00abdiversidad\u00bb, se le estaba abriendo las puertas a la peor de las amenazas. Sin embargo, sus exhortaciones no se limitaron al Viejo Mundo, sino que, con un gran sentido del peligro, vieron que muchos l\u00edderes de las izquierdas del mundo estaban sirviendo de plataforma para el proyecto del Gran Califato, entre ellos, Hugo Ch\u00e1vez, Fidel Castro y Evo Morales.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/peredo-balderrama.jpg?resize=437%2C129&#038;ssl=1\" alt=\"\" class=\"wp-image-17646\" width=\"437\" height=\"129\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">No es para nada un secreto que dos cosas definieron la Pol\u00edtica Internacional de Bolivia durante el gobierno del cocalero Morales, ahora de Arce Catacora: 1) El sometimiento a Cuba y a la tiran\u00eda de Fidel Castro, 2) La alineaci\u00f3n del pa\u00eds con cuanta organizaci\u00f3n delincuencial, grupo terrorista y dictadura exista, entre ellas, el Foro de Sao Paulo, la mafia de Putin, la dictadura de China y la teocracia Iran\u00ed.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El 8 de septiembre de 2007, durante las presidencias de Morales Ayma y Mahmud Ahmadineyad, Ir\u00e1n y Bolivia establecieron acuerdos diplom\u00e1ticos y de cooperaci\u00f3n. El 1 de septiembre de 2008, Evo lleg\u00f3 por primera vez a la ciudad de Teher\u00e1n (procedente de Libia) en visita a su hom\u00f3logo iran\u00ed. &nbsp;En este encuentro oficial de dos d\u00edas de duraci\u00f3n se ratific\u00f3 la cooperaci\u00f3n econ\u00f3mica y la inversi\u00f3n entre ambos pa\u00edses.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El a\u00f1o 2016, concretamente, el 17 de junio, Evo, en compa\u00f1\u00eda de representantes de Ecuador, Nicaragua, Venezuela e Ir\u00e1n, inaugur\u00f3 la Escuela Militar Antiimperialista. La idea de esa nueva academia castrense era formar militares bajo la doctrina antiestadounidense de la Alianza Bolivariana para los Pueblos de Nuestra Am\u00e9rica (ALBA). En la ocasi\u00f3n, el cocalero afirm\u00f3 lo siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Esta escuela es un compromiso pol\u00edtico y \u00e9tico con el pa\u00eds, con la regi\u00f3n y con el mundo, porque no s\u00f3lo es justo sino moralmente necesario vivir en condiciones de igualdad, de dignidad, hermandad y en complementariedad. Nuestra lucha requiere forjar discursos contestatarios y fijar una unidad respecto a la patria grande para la construcci\u00f3n de un Estado latinoamericano fuerte. Si el imperio ense\u00f1a desde sus escuelas militares a dominar al mundo, nosotros desde esta escuela aprenderemos a liberarnos de la opresi\u00f3n imperial; ser\u00e1 una escuela para la defensa del pueblo y no del imperio.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Es evidente que Morales, cuya ausencia de cultura incluso se refleja en sus r\u00fasticas costumbres, groseros chistes y poca higiene, no era capaz de desarrollar ese discurso sin el apoyo de un grupo de asesores. Al respecto, Carlos S\u00e1nchez Berza\u00edn, jurista y polit\u00f3logo boliviano, en su art\u00edculo: <em>Las dictaduras latinoamericanas y Brasil est\u00e1n subordinados a Rusia, China e Ir\u00e1n, <\/em>dice:<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Las dictaduras de Cuba, Venezuela, Bolivia y Nicaragua respaldan abiertamente la invasi\u00f3n de Rusia a Ucrania y se les unen gobiernos de pa\u00edses democr\u00e1ticos subordinados a las dictaduras, los gobiernos paradictatoriales de L\u00f3pez Obrador en M\u00e9xico, Fern\u00e1ndez\/ Kirchner en Argentina y Lula da Silva en Brasil, quien ha asumido activamente el mando de la pol\u00edtica exterior del grupo dictatorial latinoamericano. Los reg\u00edmenes de Cuba, Venezuela, Bolivia y Nicaragua, todos proclamando su narrativa antiimperialista, se han convertido en plataformas territoriales, pol\u00edticas y militares para las operaciones de China, Rusia e Ir\u00e1n en las Am\u00e9ricas. Todos estos pa\u00edses se han equipado con armamento ruso y chino, asesores militares y con una presencia iran\u00ed en su territorio.\u00a0<\/p><\/blockquote><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/01\/grupo-mote-balderrama.jpg?resize=398%2C216&#038;ssl=1\" alt=\"\" class=\"wp-image-17118\" width=\"398\" height=\"216\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">El <em>Acuerdo de Seguridad y Defensa<\/em> que firmaron Edmundo Novillo Aguilar y Mohammad Reza Ashtiani, ministros de defensa de Bolivia e Ir\u00e1n, respectivamente, confirman que lo afirmado por S\u00e1nchez Berza\u00edn no es nada m\u00e1s que la descripci\u00f3n de una realidad palpable y objetiva, pues Bolivia oficializ\u00f3 su incorporaci\u00f3n al grupo de las tiran\u00edas mundiales que son una amenaza para la libertad, la paz y la democracia.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La Delegaci\u00f3n de Asociaciones Israelitas Argentinas (DAIA), con la firma de su presidente, Jorge Knoblovits, envi\u00f3 un comunicado advirtiendo sobre los riesgos que representa para la seguridad nacional de Argentina el acuerdo entre Ir\u00e1n y Bolivia, ya que es conocido que el gobierno del pa\u00eds isl\u00e1mico est\u00e1 vinculado a la agrupaci\u00f3n terrorista Hezboll\u00e1, responsable del atentado perpetrado contra la sede de la AMIA-DAIA el 18 de julio de 1994, con un saldo de 85 muertos y m\u00e1s de 300 heridos. &nbsp; Es muy triste, pero el cocalero, y ahora Arce Catacora, han convertido a Bolivia en el Disneyland de los narcos, los yihadistas y otras maras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A mediados de los a\u00f1os 90, en casi toda Europa empezaron a aparecer organizaciones que promov\u00edan y celebraban los grandes aportes de la cultura isl\u00e1mica a Occidente. Sin embargo, detr\u00e1s de estas aparentes nobles reivindicaciones hist\u00f3ricas hab\u00eda un elemento oculto, La guerra contra toda la cultura y la tradici\u00f3n judeocristiana de Europa. Los hijos de [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":11189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[39],"tags":[577,831],"jnews-series":[],"ppma_author":[1371],"class_list":["post-11188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-bolivia","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolivia, el Disneyland de los narcos, los yihadistas y otras maras - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"A mediados de los a\u00f1os 90, en casi toda Europa empezaron a aparecer organizaciones que promov\u00edan y celebraban los grandes aportes de la cultura isl\u00e1mica a Occidente. Sin embargo, detr\u00e1s de estas aparentes nobles reivindicaciones hist\u00f3ricas hab\u00eda un elemento oculto, La guerra contra toda la cultura y la tradici\u00f3n judeocristiana de Europa. Los hijos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-30T07:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/narco-bolivia.jpg?fit=1280%2C920&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hugo Marcelo Balderrama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hugobalderrama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hugo Marcelo Balderrama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/\"},\"author\":{\"name\":\"Hugo Marcelo Balderrama\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\"},\"headline\":\"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras\",\"datePublished\":\"2023-07-30T07:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/\"},\"wordCount\":902,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/narco-bolivia.jpg?fit=1280%2C920&ssl=1\",\"keywords\":[\"Bolivia\",\"destacada\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/\",\"name\":\"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/narco-bolivia.jpg?fit=1280%2C920&ssl=1\",\"datePublished\":\"2023-07-30T07:26:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/narco-bolivia.jpg?fit=1280%2C920&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/narco-bolivia.jpg?fit=1280%2C920&ssl=1\",\"width\":1280,\"height\":920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/30\\\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\",\"name\":\"Hugo Marcelo Balderrama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"caption\":\"Hugo Marcelo Balderrama\"},\"description\":\"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hugobalderrama\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/hbalderrama\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/","og_locale":"es_ES","og_type":"article","og_title":"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"A mediados de los a\u00f1os 90, en casi toda Europa empezaron a aparecer organizaciones que promov\u00edan y celebraban los grandes aportes de la cultura isl\u00e1mica a Occidente. Sin embargo, detr\u00e1s de estas aparentes nobles reivindicaciones hist\u00f3ricas hab\u00eda un elemento oculto, La guerra contra toda la cultura y la tradici\u00f3n judeocristiana de Europa. Los hijos de [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2023-07-30T07:26:00+00:00","og_image":[{"width":1280,"height":920,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/narco-bolivia.jpg?fit=1280%2C920&ssl=1","type":"image\/jpeg"}],"author":"Hugo Marcelo Balderrama","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hugobalderrama","twitter_misc":{"Escrito por":"Hugo Marcelo Balderrama","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/"},"author":{"name":"Hugo Marcelo Balderrama","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde"},"headline":"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras","datePublished":"2023-07-30T07:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/"},"wordCount":902,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/narco-bolivia.jpg?fit=1280%2C920&ssl=1","keywords":["Bolivia","destacada"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/","url":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/","name":"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/narco-bolivia.jpg?fit=1280%2C920&ssl=1","datePublished":"2023-07-30T07:26:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/narco-bolivia.jpg?fit=1280%2C920&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/narco-bolivia.jpg?fit=1280%2C920&ssl=1","width":1280,"height":920},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/30\/bolivia-el-disneyland-de-los-narcos-los-yihadistas-y-otras-maras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Bolivia, el Disneyland de los narcos, los yihadistas y otras maras"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde","name":"Hugo Marcelo Balderrama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","caption":"Hugo Marcelo Balderrama"},"description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hugobalderrama"],"url":"https:\/\/informatepy.com\/2024\/author\/hbalderrama\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/narco-bolivia.jpg?fit=1280%2C920&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1371,"user_id":31,"is_guest":0,"slug":"hbalderrama","display_name":"Hugo Marcelo Balderrama","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg"},"author_category":"1","first_name":"Hugo Marcelo","last_name":"Balderrama","user_url":"","job_title":"","description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad."}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=11188"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/11189"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=11188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=11188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=11188"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=11188"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=11188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}