{"id":11081,"date":"2023-07-16T09:45:00","date_gmt":"2023-07-16T07:45:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/"},"modified":"2023-07-16T09:45:00","modified_gmt":"2023-07-16T07:45:00","slug":"la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/","title":{"rendered":"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Se hicieron virales en redes sociales los videos de Hugo Ch\u00e1vez, Nicol\u00e1s Maduro, Rafael Correa y Andr\u00e9s Manuel L\u00f3pez Obrador confesando que el pilar de sus revoluciones es mantener a los pobres en la pobreza, algo tipo: <strong><em>\u00abjodidos, pero con esperanza\u00bb<\/em><\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Para los pandilleros del Socialismo del Siglo 21 los pobres son votantes cautivos, especialmente, en periodos electorales, o grupos de choque en momentos de tensi\u00f3n social. Jam\u00e1s los ven como personas con potencial para superar su situaci\u00f3n, y en caso de hacerlo, se vuelven un enemigo m\u00e1s a combatir.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Empero, ac\u00e1 cabe una pregunta, \u00bfpor qu\u00e9 en Hispanoam\u00e9rica se ha vuelto tan dif\u00edcil superar la pobreza?<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Porque, lastimosamente, somos una de las regiones del mundo que m\u00e1s ataca la propiedad privada, veamos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/peredo-balderrama.jpg?resize=434%2C128&#038;ssl=1\" alt=\"\" class=\"wp-image-17646\" width=\"434\" height=\"128\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">En el <em>\u00cdndice de libertad econ\u00f3mica<\/em> <em>2022<\/em>, elaborado por la Fundaci\u00f3n Heritage, Bolivia ocup\u00f3 el puesto 169 de 184 a nivel mundial. En la regi\u00f3n solo se encuentra delante de Cuba y Venezuela y a nivel global, delante de Corea del Norte, Iraq, Libia y Siria. La inexistencia del Estado de Derecho y el ataque constante a la propiedad privada, en especial, mediante la persecuci\u00f3n tributaria y las confiscaciones arbitrarias, son los factores que colocan a Bolivia en el club de las dictaduras mundiales y entre los pa\u00edses m\u00e1s pobres del mundo. Sucede que la propiedad privada es inseparable del progreso econ\u00f3mico, de la libertad humana, de la democracia y de la civilizaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El progreso econ\u00f3mico, por ende, la reducci\u00f3n de la pobreza, solamente se puede lograr mediante precios libres.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El sistema de precios es, b\u00e1sicamente, un mecanismo que ofrece informaci\u00f3n a los agentes econ\u00f3micos acerca de la abundancia relativa de los bienes y servicios ofertados en el mercado, para que sean los propios agentes econ\u00f3micos los que, ejerciendo su libertad, decidan o no interrelacionarse para completar una transacci\u00f3n. Los precios tienen una gran utilidad a la hora de garantizar una asignaci\u00f3n eficiente de recursos en el mercado. Por ejemplo, si tenemos 30 casas construidas para ser vendidas, pero la demanda es de 50, el precio de la vivienda ser\u00e1 elevado. Sin embargo, esa posibilidad de ganancias motiva a los empresarios a invertir en el sector. Esa llegada de nuevos capitales, primero, crea empleo, y segundo, aumenta la cantidad de construcciones en oferta, eso baja los precios y satisface la necesidad de vivienda. No obstante, todo lo anterior requiere que se respete la propiedad privada de empresarios, ahorristas, constructores y demandantes, pues nadie invierte de no estar seguro de disfrutar del fruto de su trabajo.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong><em>\u00abEn la casa del s\u00fabdito incluso el rey debe tocar la puerta para entrar\u00bb<\/em><\/strong>, era una frase que sol\u00eda usar mi abuela materna de manera frecuente. Esa peque\u00f1a sentencia de sabidur\u00eda popular guarda una gran lecci\u00f3n: <em>La propiedad privada es la mejor forma de garantizar la libertad y desfragmentar el poder. <\/em>Justamente, por eso es por lo que el Socialismo del Siglo 21 ataca la propiedad privada, incluso sataniza el deseo de ser pr\u00f3spero y rico, pues es un impedimento en su af\u00e1n de concentrar todo el poder en sus manos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/01\/grupo-mote-balderrama.jpg?resize=411%2C223&#038;ssl=1\" alt=\"\" class=\"wp-image-17118\" width=\"411\" height=\"223\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Todos los mandatarios paridos por el Foro de Sao Paulo parecen sacados del mismo molde: Primero, mediante leyes infames, implementan el robo del sector productivo, segundo, luego de perpetrada la maniobra todo el mundo queda m\u00e1s pobre y los \u00fanicos que se vuelven millonarios son ellos mismos. Todos empezaron siendo pobres y todos, sin jam\u00e1s haber ejercido otra cosa que no sea el crimen, terminaron millonarios.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">S\u00ed. Son criminales, pues quien tiene por filosof\u00eda perpetrar el robo de la propiedad privada, as\u00ed sea mediante el uso de la fuerza del poder estatal sobre v\u00edctimas desarmadas, es un delincuente, sin importar cu\u00e1n bonitos sean sus discursos y cu\u00e1n bellas sean las palabras que use para etiquetar su filosof\u00eda. Quien use la fuerza o el enga\u00f1o para quedarse con la propiedad privada de un tercero, sin importar el destino que luego haga del bot\u00edn, es un ladr\u00f3n; si encima no reconoce lo que hace y prefiere llamarse altruista, socialista o progresista es, adem\u00e1s, de ladr\u00f3n un hip\u00f3crita.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Por ejemplo, antes de ser candidato a presidente, Lula viv\u00eda en el cuarto de una pensi\u00f3n en el suburbio m\u00e1s pobre de S\u00e3o Paulo, no ten\u00eda una sola propiedad, a tal punto que com\u00eda con las manos, siendo que en su casa no ten\u00eda cubiertos. Hoy, luego de haber planificado y dirigido el Lava Jato, es due\u00f1o de una de las mayores fortunas de Brasil. Lo mismo aplica para gente como Evo Morales, Carlos Mesa, Fidel Castro o Nicolas Maduro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se hicieron virales en redes sociales los videos de Hugo Ch\u00e1vez, Nicol\u00e1s Maduro, Rafael Correa y Andr\u00e9s Manuel L\u00f3pez Obrador confesando que el pilar de sus revoluciones es mantener a los pobres en la pobreza, algo tipo: \u00abjodidos, pero con esperanza\u00bb. Para los pandilleros del Socialismo del Siglo 21 los pobres son votantes cautivos, especialmente, [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":11082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[39],"tags":[831,962,738],"jnews-series":[],"ppma_author":[1371],"class_list":["post-11081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-destacada","tag-foro-de-sao-paulo","tag-socialismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Se hicieron virales en redes sociales los videos de Hugo Ch\u00e1vez, Nicol\u00e1s Maduro, Rafael Correa y Andr\u00e9s Manuel L\u00f3pez Obrador confesando que el pilar de sus revoluciones es mantener a los pobres en la pobreza, algo tipo: \u00abjodidos, pero con esperanza\u00bb. Para los pandilleros del Socialismo del Siglo 21 los pobres son votantes cautivos, especialmente, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-16T07:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/propiedad-privada.jpg?fit=1280%2C954&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"954\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hugo Marcelo Balderrama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hugobalderrama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hugo Marcelo Balderrama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/\"},\"author\":{\"name\":\"Hugo Marcelo Balderrama\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\"},\"headline\":\"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad\",\"datePublished\":\"2023-07-16T07:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/\"},\"wordCount\":813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/propiedad-privada.jpg?fit=1280%2C954&ssl=1\",\"keywords\":[\"destacada\",\"foro de sao paulo\",\"socialismo\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/\",\"name\":\"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/propiedad-privada.jpg?fit=1280%2C954&ssl=1\",\"datePublished\":\"2023-07-16T07:45:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/propiedad-privada.jpg?fit=1280%2C954&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/propiedad-privada.jpg?fit=1280%2C954&ssl=1\",\"width\":1280,\"height\":954},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/07\\\/16\\\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\",\"name\":\"Hugo Marcelo Balderrama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"caption\":\"Hugo Marcelo Balderrama\"},\"description\":\"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hugobalderrama\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/hbalderrama\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/","og_locale":"es_ES","og_type":"article","og_title":"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Se hicieron virales en redes sociales los videos de Hugo Ch\u00e1vez, Nicol\u00e1s Maduro, Rafael Correa y Andr\u00e9s Manuel L\u00f3pez Obrador confesando que el pilar de sus revoluciones es mantener a los pobres en la pobreza, algo tipo: \u00abjodidos, pero con esperanza\u00bb. Para los pandilleros del Socialismo del Siglo 21 los pobres son votantes cautivos, especialmente, [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2023-07-16T07:45:00+00:00","og_image":[{"width":1280,"height":954,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/propiedad-privada.jpg?fit=1280%2C954&ssl=1","type":"image\/jpeg"}],"author":"Hugo Marcelo Balderrama","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hugobalderrama","twitter_misc":{"Escrito por":"Hugo Marcelo Balderrama","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/"},"author":{"name":"Hugo Marcelo Balderrama","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde"},"headline":"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad","datePublished":"2023-07-16T07:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/"},"wordCount":813,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/propiedad-privada.jpg?fit=1280%2C954&ssl=1","keywords":["destacada","foro de sao paulo","socialismo"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/","url":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/","name":"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/propiedad-privada.jpg?fit=1280%2C954&ssl=1","datePublished":"2023-07-16T07:45:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/propiedad-privada.jpg?fit=1280%2C954&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/propiedad-privada.jpg?fit=1280%2C954&ssl=1","width":1280,"height":954},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/07\/16\/la-propiedad-privada-fundamento-de-la-civilizacion-y-la-libertad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"La propiedad privada, fundamento de la civilizaci\u00f3n y la libertad"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde","name":"Hugo Marcelo Balderrama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","caption":"Hugo Marcelo Balderrama"},"description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hugobalderrama"],"url":"https:\/\/informatepy.com\/2024\/author\/hbalderrama\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/07\/propiedad-privada.jpg?fit=1280%2C954&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1371,"user_id":31,"is_guest":0,"slug":"hbalderrama","display_name":"Hugo Marcelo Balderrama","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg"},"author_category":"1","first_name":"Hugo Marcelo","last_name":"Balderrama","user_url":"","job_title":"","description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad."}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=11081"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/11081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/11082"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=11081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=11081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=11081"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=11081"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=11081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}