{"id":10723,"date":"2023-05-28T09:55:00","date_gmt":"2023-05-28T07:55:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/"},"modified":"2023-05-28T09:55:00","modified_gmt":"2023-05-28T07:55:00","slug":"todavia-se-sorprenden","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/","title":{"rendered":"\u00bfTodav\u00eda se sorprenden?"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">En el Coba boliviano (el lenguaje que usa el hampa de mi pa\u00eds) <em>autero <\/em>es el vocablo que describe al ladr\u00f3n especialista en robar autom\u00f3viles. De ah\u00ed que se haya popularizado el chiste sobre la confusi\u00f3n que sufre <strong>Luis Arce Catacora<\/strong> entre gobierno austero y el gobierno de auteros, pues ya es vergonzoso que varios autos robados en Chile est\u00e9n en manos de autoridades bolivianas, incluso del mismo presidente.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Es cierto que es bastante aberrante que un mandatario conduzca y regale veh\u00edculos de lujo robados en Chile, o que la m\u00e1xima ejecutiva de la Aduana Nacional culpe a los chilenos por \u00abdejarse robar\u00bb los coches, pero no es el \u00fanico delito que ha cometido la dictadura boliviana.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El a\u00f1o 2016, en La Sesi\u00f3n Especial de la Asamblea de las Naciones Unidas sobre Drogas, <strong>Evo Morales<\/strong> sincer\u00f3 la posici\u00f3n de los miembros del Foro de Sao Paulo respecto al narcotr\u00e1fico, sus palabras fueron: <strong><em>\u00abEstados Unidos usa la lucha contra el narcotr\u00e1fico como un mecanismo de control pol\u00edtico, un pretexto para el imperialismo\u00bb.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/peredo-balderrama.jpg?resize=491%2C145&#038;ssl=1\" alt=\"\" class=\"wp-image-17646\" width=\"491\" height=\"145\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">La incontinencia verbal del cocalero dej\u00f3 algo en claro: <em>La estrategia antiimperialista de los gobiernos del Socialismo del Siglo 21 tiene fundamento ideol\u00f3gico de defensa del narcotr\u00e1fico y responde a la necesidad pol\u00edtica de legitimar este crimen. <\/em>Objetivamente, eso que <strong>Evo<\/strong> llam\u00f3 como \u00abnacionalizaci\u00f3n\u00bb de la lucha contra las drogas es, en realidad, un pretexto para legalizar el narcotr\u00e1fico. Por ejemplo, con <strong>Morales<\/strong> en el gobierno en Bolivia se han incrementado los cultivos de coca ilegal de 3.000 a m\u00e1s de 40.000 hect\u00e1reas. Otros datos nos muestran que varios polic\u00edas bolivianos de alto rango, entre ellos, el General <strong>Ren\u00e9 Sanabria<\/strong>, han sido parte importante de c\u00e1rteles de drogas.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify\">De igual manera, el cacique de la coca ha usado el dinero del narcotr\u00e1fico para generar conflictos sociales en la provincia peruana de Puno, acciones que le valieron ser investigado por la justicia de ese pa\u00eds. Respecto a la constante intromisi\u00f3n de <strong>Evo<\/strong> en la fallida gesti\u00f3n de <strong>Castillo<\/strong>, <strong>Pedro Yaranga<\/strong>, experto en seguridad y lucha contra el narcotr\u00e1fico, en una entrevista al diario <strong>G<em>estion<\/em><\/strong><em> de Per\u00fa <\/em>(marzo 2021), afirm\u00f3 lo siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Morales habla mucho de sus pol\u00edticas exitosas en lucha contra el narcotr\u00e1fico por expulsar a las bases norteamericanas y a la DEA, pero cuando \u00e9l asumi\u00f3 la presidencia de Bolivia en el 2006 hab\u00eda 12,000 hect\u00e1reas de coca en su pa\u00eds y cuando dej\u00f3 el poder en el 2019, hab\u00edan m\u00e1s de 30,000 hect\u00e1reas. Las avionetas que sacan la droga de Per\u00fa provienen de Bolivia, que se ha convertido en el almac\u00e9n de la coca\u00edna peruana para que luego, a trav\u00e9s de Brasil, llegue a Europa y Asia.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Por su parte, <strong>Carlos S\u00e1nchez Berza\u00edn<\/strong>, jurista boliviano y uno de los miles de perseguidos pol\u00edticos, en un art\u00edculo titulado: <em>Socialismo del Siglo 21 y narcotr\u00e1fico en la ONU<\/em>, manifest\u00f3:<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Los hechos evidencian que quienes han expulsado o forzado el retiro de la DEA y que tambi\u00e9n expulsaron a los embajadores norteamericanos son Ch\u00e1vez-Maduro en Venezuela y Correa en Ecuador, no solo Evo Morales; ha sido Correa en Ecuador quien ha cerrado y expulsado a los EEUU de la Base de Manta; ha sido Correa quien ha puesto en evidencia la protecci\u00f3n que otorgaba a las FARC, con el bombardeo colombiano de Angostura; es desde Venezuela y Cuba donde las mismas FARC reconocidas como guerrilla vinculada al narcotr\u00e1fico han recibido protecci\u00f3n log\u00edstica y pol\u00edtica, hasta llegar a una mesa de negociaci\u00f3n en Cuba; es p\u00fablica y evidente la acci\u00f3n de las FARC en hechos de violencia como los de octubre de 2003 en Bolivia contra gobiernos democr\u00e1ticos dando apoyo terrorista a los hoy gobernantes.\u00a0<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Que Bolivia se ha vuelto un foco de desestabilizaci\u00f3n regional es algo innegable, ya que la realidad objetiva nos muestra que la dictadura boliviana es el trampol\u00edn geoestrat\u00e9gico para exportar el crimen organizado a los pa\u00edses vecinos de Chile, Per\u00fa y Paraguay, los \u00fanicos que, junto con un ensangrentado Ecuador, todav\u00eda est\u00e1n libres de las garras del castrochavismo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/01\/grupo-mote-balderrama.jpg?resize=365%2C198&#038;ssl=1\" alt=\"\" class=\"wp-image-17118\" width=\"365\" height=\"198\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Quien todav\u00eda crea que el Movimiento Al Socialismo (MAS) se ha desviado de sus \u00abverdaderos\u00bb fundamentos ideol\u00f3gicos cae en la ingenuidad. Est\u00e1 muy bien documentado en varios libros, verbigracia, <em>El impostor<\/em>, autor\u00eda de <strong>Nicolas M\u00e1rquez<\/strong>, que el Foro de Sao Paulo aglutin\u00f3 a todos los pandilleros, terroristas, milicianos y sicarios de izquierda que, especialmente, despu\u00e9s del derrumbe sovi\u00e9tico, se hab\u00edan quedado sin recursos ni discurso. Por l\u00f3gica, que en el MAS convivan todos los espec\u00edmenes de la golfer\u00eda boliviana no es nada m\u00e1s que la muestra de su naturaleza delincuencial, pues como lo dir\u00eda el gran <strong>Friedrich Hayek<\/strong>: <strong><em>\u00abSolamente los carentes de escr\u00fapulos se sienten atra\u00eddos por las ideas y reg\u00edmenes totalitarios\u00bb.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Coba boliviano (el lenguaje que usa el hampa de mi pa\u00eds) autero es el vocablo que describe al ladr\u00f3n especialista en robar autom\u00f3viles. De ah\u00ed que se haya popularizado el chiste sobre la confusi\u00f3n que sufre Luis Arce Catacora entre gobierno austero y el gobierno de auteros, pues ya es vergonzoso que varios [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":4751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[39],"tags":[577,831],"jnews-series":[],"ppma_author":[1371],"class_list":["post-10723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-bolivia","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfTodav\u00eda se sorprenden? - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfTodav\u00eda se sorprenden? - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"En el Coba boliviano (el lenguaje que usa el hampa de mi pa\u00eds) autero es el vocablo que describe al ladr\u00f3n especialista en robar autom\u00f3viles. De ah\u00ed que se haya popularizado el chiste sobre la confusi\u00f3n que sufre Luis Arce Catacora entre gobierno austero y el gobierno de auteros, pues ya es vergonzoso que varios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-28T07:55:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hugo Marcelo Balderrama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hugobalderrama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hugo Marcelo Balderrama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/\"},\"author\":{\"name\":\"Hugo Marcelo Balderrama\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\"},\"headline\":\"\u00bfTodav\u00eda se sorprenden?\",\"datePublished\":\"2023-05-28T07:55:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/\"},\"wordCount\":842,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1\",\"keywords\":[\"Bolivia\",\"destacada\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/\",\"name\":\"\u00bfTodav\u00eda se sorprenden? - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1\",\"datePublished\":\"2023-05-28T07:55:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1\",\"width\":1000,\"height\":541},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/28\\\/todavia-se-sorprenden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfTodav\u00eda se sorprenden?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\",\"name\":\"Hugo Marcelo Balderrama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"caption\":\"Hugo Marcelo Balderrama\"},\"description\":\"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hugobalderrama\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/hbalderrama\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfTodav\u00eda se sorprenden? - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfTodav\u00eda se sorprenden? - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"En el Coba boliviano (el lenguaje que usa el hampa de mi pa\u00eds) autero es el vocablo que describe al ladr\u00f3n especialista en robar autom\u00f3viles. De ah\u00ed que se haya popularizado el chiste sobre la confusi\u00f3n que sufre Luis Arce Catacora entre gobierno austero y el gobierno de auteros, pues ya es vergonzoso que varios [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2023-05-28T07:55:00+00:00","og_image":[{"width":1000,"height":541,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1","type":"image\/jpeg"}],"author":"Hugo Marcelo Balderrama","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hugobalderrama","twitter_misc":{"Escrito por":"Hugo Marcelo Balderrama","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/"},"author":{"name":"Hugo Marcelo Balderrama","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde"},"headline":"\u00bfTodav\u00eda se sorprenden?","datePublished":"2023-05-28T07:55:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/"},"wordCount":842,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1","keywords":["Bolivia","destacada"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/","url":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/","name":"\u00bfTodav\u00eda se sorprenden? - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1","datePublished":"2023-05-28T07:55:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1","width":1000,"height":541},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/28\/todavia-se-sorprenden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"\u00bfTodav\u00eda se sorprenden?"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde","name":"Hugo Marcelo Balderrama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","caption":"Hugo Marcelo Balderrama"},"description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hugobalderrama"],"url":"https:\/\/informatepy.com\/2024\/author\/hbalderrama\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/luis-arce-evo-morales.jpg?fit=1000%2C541&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1371,"user_id":31,"is_guest":0,"slug":"hbalderrama","display_name":"Hugo Marcelo Balderrama","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg"},"author_category":"1","first_name":"Hugo Marcelo","last_name":"Balderrama","user_url":"","job_title":"","description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad."}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=10723"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/4751"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=10723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=10723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=10723"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=10723"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=10723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}