{"id":10660,"date":"2023-04-20T19:29:00","date_gmt":"2023-04-20T17:29:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/"},"modified":"2023-04-20T19:29:00","modified_gmt":"2023-04-20T17:29:00","slug":"el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/","title":{"rendered":"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5aC1PTznItQ?start=9&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"https:\/\/www.youtube.com\/watch?v=5aC1PTznItQ&amp;t=9s","protected":false},"author":3,"featured_media":10661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[42],"tags":[831,962],"jnews-series":[],"ppma_author":[830],"class_list":["post-10660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videos","tag-destacada","tag-foro-de-sao-paulo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T17:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay\",\"datePublished\":\"2023-04-20T17:29:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/\"},\"wordCount\":25,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1\",\"keywords\":[\"destacada\",\"foro de sao paulo\"],\"articleSection\":[\"Videos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/\",\"name\":\"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1\",\"datePublished\":\"2023-04-20T17:29:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1\",\"width\":1280,\"height\":631},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/20\\\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/","og_locale":"es_ES","og_type":"article","og_title":"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_url":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-04-20T17:29:00+00:00","og_image":[{"width":1280,"height":631,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay","datePublished":"2023-04-20T17:29:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/"},"wordCount":25,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1","keywords":["destacada","foro de sao paulo"],"articleSection":["Videos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/","url":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/","name":"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1","datePublished":"2023-04-20T17:29:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1","width":1280,"height":631},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/20\/el-foro-de-sao-paulo-tiene-los-ojos-puestos-en-las-elecciones-de-paraguay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"El Foro de Sao Paulo tiene los ojos puestos en las elecciones de Paraguay"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/lugo-esperanza.jpg?fit=1280%2C631&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=10660"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/10661"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=10660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=10660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=10660"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=10660"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=10660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}