{"id":1061,"date":"2019-08-19T20:19:00","date_gmt":"2019-08-19T18:19:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/"},"modified":"2019-08-19T20:19:00","modified_gmt":"2019-08-19T18:19:00","slug":"destituyen-al-presidente-del-ips","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/","title":{"rendered":"Destituyen al presidente del IPS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Poco despu\u00e9s de las 11:00 de este lunes, Abdo Ben\u00edtez confirm\u00f3, a trav\u00e9s de su asesor jur\u00eddico Hern\u00e1n Huttemann, la destituci\u00f3n de Armando Rodr\u00edguez, quien estaba al frente del IPS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, fueron removidos los consejeros de la previsional, el exsenador Julio Vel\u00e1zquez y Edsel Gonz\u00e1lez. Ambos eran representantes del Ejecutivo, inform\u00f3 Radio 1000 AM.<br><br>La determinaci\u00f3n se da luego de la pol\u00e9mica licitaci\u00f3n de guardias de seguridad para la previsional, de hace unos meses. De acuerdo a las denuncias, la contrataci\u00f3n se habr\u00eda dado con precios inflados. Los datos salieron a luz y la adquisici\u00f3n se dej\u00f3 sin efecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora se ver\u00e1 quien asumir\u00e1 el lugar de Rodr\u00edguez, quien hab\u00eda sido nombrado por recomendaci\u00f3n del hermano de Abdo Ben\u00edtez, Benigno L\u00f3pez, quien estuvo tambi\u00e9n en la titularidad de IPS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a Vel\u00e1zquez, se sabe que cay\u00f3 en el ente, al quedar al margen del Senado. \u00c9l pol\u00edtico apoy\u00f3 en campa\u00f1a al ahora titular del Ejecutivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Huttemann no dio detalles acerca de las razones de la remoci\u00f3n y por el momento, no se tiene informaci\u00f3n sobre los posibles reemplazantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poco despu\u00e9s de las 11:00 de este lunes, Abdo Ben\u00edtez confirm\u00f3, a trav\u00e9s de su asesor jur\u00eddico Hern\u00e1n Huttemann, la destituci\u00f3n de Armando Rodr\u00edguez, quien estaba al frente del IPS. Adem\u00e1s, fueron removidos los consejeros de la previsional, el exsenador Julio Vel\u00e1zquez y Edsel Gonz\u00e1lez. Ambos eran representantes del Ejecutivo, inform\u00f3 Radio 1000 AM. La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1062,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[532,129,197],"jnews-series":[],"ppma_author":[47],"class_list":["post-1061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-armando-rodriguez","tag-ips","tag-mario-abdo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destituyen al presidente del IPS - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destituyen al presidente del IPS - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Poco despu\u00e9s de las 11:00 de este lunes, Abdo Ben\u00edtez confirm\u00f3, a trav\u00e9s de su asesor jur\u00eddico Hern\u00e1n Huttemann, la destituci\u00f3n de Armando Rodr\u00edguez, quien estaba al frente del IPS. Adem\u00e1s, fueron removidos los consejeros de la previsional, el exsenador Julio Vel\u00e1zquez y Edsel Gonz\u00e1lez. Ambos eran representantes del Ejecutivo, inform\u00f3 Radio 1000 AM. La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-19T18:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/armando-ridriguez.jpg?fit=659%2C415&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"659\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NicoCPT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NicoCPT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/\"},\"author\":{\"name\":\"NicoCPT\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\"},\"headline\":\"Destituyen al presidente del IPS\",\"datePublished\":\"2019-08-19T18:19:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/\"},\"wordCount\":209,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/armando-ridriguez.jpg?fit=659%2C415&ssl=1\",\"keywords\":[\"armando rodriguez\",\"ips\",\"mario abdo\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/\",\"name\":\"Destituyen al presidente del IPS - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/armando-ridriguez.jpg?fit=659%2C415&ssl=1\",\"datePublished\":\"2019-08-19T18:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/armando-ridriguez.jpg?fit=659%2C415&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/armando-ridriguez.jpg?fit=659%2C415&ssl=1\",\"width\":659,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2019\\\/08\\\/19\\\/destituyen-al-presidente-del-ips\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destituyen al presidente del IPS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/06aa09f3e09a6cf24491fead8baf783e\",\"name\":\"NicoCPT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"NicoCPT\"},\"sameAs\":[\"https:\\\/\\\/informatepy.com\\\/2024\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/nicocpt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destituyen al presidente del IPS - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/","og_locale":"es_ES","og_type":"article","og_title":"Destituyen al presidente del IPS - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Poco despu\u00e9s de las 11:00 de este lunes, Abdo Ben\u00edtez confirm\u00f3, a trav\u00e9s de su asesor jur\u00eddico Hern\u00e1n Huttemann, la destituci\u00f3n de Armando Rodr\u00edguez, quien estaba al frente del IPS. Adem\u00e1s, fueron removidos los consejeros de la previsional, el exsenador Julio Vel\u00e1zquez y Edsel Gonz\u00e1lez. Ambos eran representantes del Ejecutivo, inform\u00f3 Radio 1000 AM. La [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2019-08-19T18:19:00+00:00","og_image":[{"width":659,"height":415,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/armando-ridriguez.jpg?fit=659%2C415&ssl=1","type":"image\/jpeg"}],"author":"NicoCPT","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"NicoCPT","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/"},"author":{"name":"NicoCPT","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e"},"headline":"Destituyen al presidente del IPS","datePublished":"2019-08-19T18:19:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/"},"wordCount":209,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/armando-ridriguez.jpg?fit=659%2C415&ssl=1","keywords":["armando rodriguez","ips","mario abdo"],"articleSection":["Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/","url":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/","name":"Destituyen al presidente del IPS - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/armando-ridriguez.jpg?fit=659%2C415&ssl=1","datePublished":"2019-08-19T18:19:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/armando-ridriguez.jpg?fit=659%2C415&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/armando-ridriguez.jpg?fit=659%2C415&ssl=1","width":659,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2019\/08\/19\/destituyen-al-presidente-del-ips\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Destituyen al presidente del IPS"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/06aa09f3e09a6cf24491fead8baf783e","name":"NicoCPT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"NicoCPT"},"sameAs":["https:\/\/informatepy.com\/2024"],"url":"https:\/\/informatepy.com\/2024\/author\/nicocpt\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/08\/armando-ridriguez.jpg?fit=659%2C415&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":47,"user_id":1,"is_guest":0,"slug":"nicocpt","display_name":"NicoCPT","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"https:\/\/informatepy.com\/2024","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/1061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=1061"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/1061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/1062"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=1061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=1061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=1061"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=1061"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=1061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}