{"id":10572,"date":"2023-05-10T16:02:33","date_gmt":"2023-05-10T14:02:33","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/"},"modified":"2023-05-10T16:02:33","modified_gmt":"2023-05-10T14:02:33","slug":"record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/","title":{"rendered":"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">La cultura y la econom\u00eda del Paraguay est\u00e1 fuertemente ligada al agua. Sin embargo la contaminaci\u00f3n y la pesca indiscriminada se tradujo en una merma de la producci\u00f3n de peces: del record de 30.000 toneladas m\u00e9tricas de peces, en 2010 se logr\u00f3 poco m\u00e1s de la mitad, un 40% menos.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El gobierno paraguayo identific\u00f3 en Taiw\u00e1n a un aliado clave, ya que ellos son expertos mundiales en la piscicultura. Gracias a esa cooperaci\u00f3n inici\u00f3 el Centro Nacional de Producci\u00f3n de Alevines en 2010, para la implementaci\u00f3n de la producci\u00f3n de tilapia, pac\u00fa y surub\u00ed. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">El Centro Nacional de Producci\u00f3n de Alevines mostr\u00f3 un aumento de 2.365 toneladas (2014) a 9.000 toneladas (2020) en la producci\u00f3n de tilapias utilizando tecnolog\u00eda de reversi\u00f3n sexual de esa especie. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">El Pac\u00fa es una de las experiencias exitosas: Los alevines pasaron de costar de 3.000Gs. \/ 1.500Gs. se redujo a 500Gs. la unidad, permitiendo que los peque\u00f1os productores puedan acceder a ello y mejorar su opci\u00f3n de alimentaci\u00f3n y oportunidad comercial. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">El \u201cProyecto Surub\u00ed\u201d (2019-2022) consigui\u00f3 del Centro Nacional de Producci\u00f3n de Alevines permiti\u00f3 reducir el precio de los alevines a 3.000Gs, antes costaban entre 20.000 a 15.000Gs. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Resumiendo: La acuicultura con tecnolog\u00eda de punta taiwanesa permiti\u00f3 que la producci\u00f3n de Pac\u00fa pasara en 2013 de 12.5 toneladas a 56.1 en el a\u00f1o 2020. En cuanto al Surub\u00ed en 2019 era de 200 t. pas\u00f3 a 600 t. en el 2020. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">En el Proyecto de Producci\u00f3n Comercial de Surub\u00ed, se incluye otras especies como boga, salm\u00f3n del r\u00edo Paran\u00e1 y camarones de agua dulce, esperando seguir ampliando los beneficios del proyecto y mejorar las capacidades del cultivo. Es decir, se amplia la cantidad de especies. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Gracias a la cooperaci\u00f3n taiwanesa, le damos un descanso a nuestros r\u00edos. Es importante contemplar la sustentabilidad ambiental en la producci\u00f3n de alimentos, para mitigar el accionar humano sobre los ecosistemas. La acuicultura es una herramienta fundamental para ese fin.<\/p>\n\n\n\n<p><sub>El Par\u00e1metro News<\/sub><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cultura y la econom\u00eda del Paraguay est\u00e1 fuertemente ligada al agua. Sin embargo la contaminaci\u00f3n y la pesca indiscriminada se tradujo en una merma de la producci\u00f3n de peces: del record de 30.000 toneladas m\u00e9tricas de peces, en 2010 se logr\u00f3 poco m\u00e1s de la mitad, un 40% menos. El gobierno paraguayo identific\u00f3 en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[46],"tags":[831,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-10572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-destacada","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"La cultura y la econom\u00eda del Paraguay est\u00e1 fuertemente ligada al agua. Sin embargo la contaminaci\u00f3n y la pesca indiscriminada se tradujo en una merma de la producci\u00f3n de peces: del record de 30.000 toneladas m\u00e9tricas de peces, en 2010 se logr\u00f3 poco m\u00e1s de la mitad, un 40% menos. El gobierno paraguayo identific\u00f3 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-10T14:02:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya\",\"datePublished\":\"2023-05-10T14:02:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/\"},\"wordCount\":344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1\",\"keywords\":[\"destacada\",\"taiwan\"],\"articleSection\":[\"Negocios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/\",\"name\":\"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1\",\"datePublished\":\"2023-05-10T14:02:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/10\\\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/","og_locale":"es_ES","og_type":"article","og_title":"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"La cultura y la econom\u00eda del Paraguay est\u00e1 fuertemente ligada al agua. Sin embargo la contaminaci\u00f3n y la pesca indiscriminada se tradujo en una merma de la producci\u00f3n de peces: del record de 30.000 toneladas m\u00e9tricas de peces, en 2010 se logr\u00f3 poco m\u00e1s de la mitad, un 40% menos. El gobierno paraguayo identific\u00f3 en [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-05-10T14:02:33+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya","datePublished":"2023-05-10T14:02:33+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/"},"wordCount":344,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1","keywords":["destacada","taiwan"],"articleSection":["Negocios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/","url":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/","name":"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1","datePublished":"2023-05-10T14:02:33+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/10\/record-de-produccion-de-peces-mediante-cooperacion-taiwanesa-paraguaya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"R\u00e9cord de producci\u00f3n de peces mediante cooperaci\u00f3n taiwanesa-paraguaya"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/pscicultura-tw-py.jpg?fit=1280%2C960&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=10572"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/10573"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=10572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=10572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=10572"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=10572"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=10572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}