{"id":10546,"date":"2023-05-07T09:05:00","date_gmt":"2023-05-07T07:05:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/"},"modified":"2023-05-07T09:05:00","modified_gmt":"2023-05-07T07:05:00","slug":"bolivia-necesita-politicos-no-caudillos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/","title":{"rendered":"Bolivia necesita pol\u00edticos, no caudillos"},"content":{"rendered":"\n<p class=\"has-text-align-justify\"><em>Entre la libertad y el miedo<\/em>, autor\u00eda de <strong>German Arciniegas <\/strong>(1900 \u2013 1999) se ha convertido en uno de mis libros de cabecera. El trabajo repasa la historia hispanoamericana de las primeras cinco d\u00e9cadas del Siglo 20, y llega a una brillante conclusi\u00f3n: <em>nuestros pa\u00edses son rehenes de toda clase de caudillos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">El problema del caudillo es que no tiene visi\u00f3n de Estado ni de patria, su \u00fanico objetivo es controlar el poder total. El caudillaje no construye instituciones, que son vitales para el desarrollo de los pa\u00edses, sino que somete todo el aparato del Estado a los caprichos del mand\u00f3n de turno.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El Estado Plurinacional de Bolivia, el \u00faltimo experimento caudillista en Bolivia, a pesar de haber contado con unos ingresos jam\u00e1s pensados, nos ha convertido en una de las naciones m\u00e1s atrasadas del continente. Veamos algunos datos.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>El \u00cdndice de Percepci\u00f3n de la Corrupci\u00f3n<\/em> (IPC), elaborado por Transparencia Internacional, se ha convertido en el principal indicador mundial de la corrupci\u00f3n en el sector p\u00fablico. El indicador muestra una especia de fotograf\u00eda instant\u00e1nea anual del grado relativo de corrupci\u00f3n clasificando pa\u00edses y territorios de todo el mundo. En los \u00faltimos a\u00f1os, Bolivia ha descendido su puntaje de 34, en 2012, a 30, en 2021. Ese descenso afect\u00f3 a la imagen del pa\u00eds en los mercados internacionales, pues ya son varias calificadoras de riesgo que le han bajado el pulgar al gobierno boliviano.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En<em> El \u00cdndice de desempe\u00f1o log\u00edstico 2021<\/em>, uno de los indicadores para medir la competitividad del comercio exterior de las naciones, Bolivia obtuvo una calificaci\u00f3n de 2,36, una de las m\u00e1s bajas del mundo y la peor de Sudam\u00e9rica. La estructura caminera es uno de los componentes que peor desempe\u00f1o obtuvo, pues solamente el 13% del pa\u00eds consta con v\u00edas asfaltadas, casi el mismo porcentaje que otra de las dictaduras castrochavistas: Nicaragua.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En septiembre del 2022, El Programa de las Naciones Unidas para el Desarrollo (PNUD) public\u00f3 su informe sobre Desarrollo Humano 2021-2022, en el que sit\u00faa a Bolivia en el puesto 118 de 191 pa\u00edses, a nivel Sudam\u00e9rica, el pa\u00eds s\u00f3lo est\u00e1 por encima de Venezuela.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En cuanto al, siempre \u00e1lgido, tema educativo, seg\u00fan se desprende del Tercer Estudio Regional Comparativo y Explicativo (TERCE), realizado por la UNESCO en la regi\u00f3n el a\u00f1o 2018, Bolivia ocupa uno de los \u00faltimos lugares de Hispanoam\u00e9rica en cuanto a desempe\u00f1o educativo, el puesto n\u00famero 13 de 16 naciones analizadas, Chile y Costa Rica se encuentran en la punta. El peor desempe\u00f1o obtenido por los estudiantes bolivianos se da en las \u00e1reas de lectura y ciencias naturales para sexto de primaria y en escritura de tercer y sexto.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En resumen, El Estado Plurinacional de Bolivia, en lo econ\u00f3mico, est\u00e1 quebrado y, en lo social, estanc\u00f3 a los bolivianos en el fango de la miseria y la ignorancia.<\/p>\n\n\n\n<p>\u00bfHay soluci\u00f3n?<\/p>\n\n\n\n<p>S\u00ed. Sin embargo, es una ruta larga.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El primer paso es entender que la pol\u00edtica no es un monopolio de los partidos, sino una responsabilidad de todos los bolivianos. Es necesario recuperar el concepto de ciudadano, ese que en la Grecia antigua ejerc\u00eda la pol\u00edtica como muestra de su condici\u00f3n de hombre libre.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El gran <strong>Winston Churchill<\/strong> dijo una vez: <strong><em>\u00abEl pol\u00edtico se convierte en estadista cuando piensa en las pr\u00f3ximas generaciones y no en las pr\u00f3ximas elecciones\u00bb<\/em><\/strong>. No obstante, en Bolivia tenemos una pol\u00edtica vac\u00eda de ideas, pero llena de \u00absalvadores\u00bb. Eso nos lleva al segundo paso, desarrollar una propuesta que se sostenga en ideas y planes de pol\u00edtica p\u00fablica. En el debate pol\u00edtico se debe volver a hablar de modelo impositivo, de acuerdos de complementaci\u00f3n comercial, de seguridad y soberan\u00eda, de educaci\u00f3n y salud, pero, en especial, de construir una patria con instituciones s\u00f3lidas. En conclusi\u00f3n, Bolivia necesita pol\u00edticos, no caudillos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre la libertad y el miedo, autor\u00eda de German Arciniegas (1900 \u2013 1999) se ha convertido en uno de mis libros de cabecera. El trabajo repasa la historia hispanoamericana de las primeras cinco d\u00e9cadas del Siglo 20, y llega a una brillante conclusi\u00f3n: nuestros pa\u00edses son rehenes de toda clase de caudillos. El problema del [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":10547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[39],"tags":[577,831],"jnews-series":[],"ppma_author":[1371],"class_list":["post-10546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-bolivia","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolivia necesita pol\u00edticos, no caudillos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia necesita pol\u00edticos, no caudillos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Entre la libertad y el miedo, autor\u00eda de German Arciniegas (1900 \u2013 1999) se ha convertido en uno de mis libros de cabecera. El trabajo repasa la historia hispanoamericana de las primeras cinco d\u00e9cadas del Siglo 20, y llega a una brillante conclusi\u00f3n: nuestros pa\u00edses son rehenes de toda clase de caudillos. El problema del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-07T07:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hugo Marcelo Balderrama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hugobalderrama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hugo Marcelo Balderrama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/\"},\"author\":{\"name\":\"Hugo Marcelo Balderrama\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\"},\"headline\":\"Bolivia necesita pol\u00edticos, no caudillos\",\"datePublished\":\"2023-05-07T07:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/\"},\"wordCount\":670,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1\",\"keywords\":[\"Bolivia\",\"destacada\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/\",\"name\":\"Bolivia necesita pol\u00edticos, no caudillos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1\",\"datePublished\":\"2023-05-07T07:05:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/07\\\/bolivia-necesita-politicos-no-caudillos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolivia necesita pol\u00edticos, no caudillos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\",\"name\":\"Hugo Marcelo Balderrama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"caption\":\"Hugo Marcelo Balderrama\"},\"description\":\"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hugobalderrama\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/hbalderrama\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolivia necesita pol\u00edticos, no caudillos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/","og_locale":"es_ES","og_type":"article","og_title":"Bolivia necesita pol\u00edticos, no caudillos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Entre la libertad y el miedo, autor\u00eda de German Arciniegas (1900 \u2013 1999) se ha convertido en uno de mis libros de cabecera. El trabajo repasa la historia hispanoamericana de las primeras cinco d\u00e9cadas del Siglo 20, y llega a una brillante conclusi\u00f3n: nuestros pa\u00edses son rehenes de toda clase de caudillos. El problema del [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2023-05-07T07:05:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1","type":"image\/jpeg"}],"author":"Hugo Marcelo Balderrama","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hugobalderrama","twitter_misc":{"Escrito por":"Hugo Marcelo Balderrama","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/"},"author":{"name":"Hugo Marcelo Balderrama","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde"},"headline":"Bolivia necesita pol\u00edticos, no caudillos","datePublished":"2023-05-07T07:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/"},"wordCount":670,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1","keywords":["Bolivia","destacada"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/","url":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/","name":"Bolivia necesita pol\u00edticos, no caudillos - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1","datePublished":"2023-05-07T07:05:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/07\/bolivia-necesita-politicos-no-caudillos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Bolivia necesita pol\u00edticos, no caudillos"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde","name":"Hugo Marcelo Balderrama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","caption":"Hugo Marcelo Balderrama"},"description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hugobalderrama"],"url":"https:\/\/informatepy.com\/2024\/author\/hbalderrama\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/bandera-bolivia.jpg?fit=1280%2C960&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1371,"user_id":31,"is_guest":0,"slug":"hbalderrama","display_name":"Hugo Marcelo Balderrama","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg"},"author_category":"1","first_name":"Hugo Marcelo","last_name":"Balderrama","user_url":"","job_title":"","description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad."}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=10546"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/10547"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=10546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=10546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=10546"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=10546"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=10546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}