{"id":10538,"date":"2023-05-06T13:53:21","date_gmt":"2023-05-06T11:53:21","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/"},"modified":"2023-05-06T13:53:21","modified_gmt":"2023-05-06T11:53:21","slug":"la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/","title":{"rendered":"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Para festejar la ubicaci\u00f3n de <strong>Taiw\u00e1n <\/strong>como primer comprador de carne porcina paraguaya, la <strong>Asociaci\u00f3n de Criadores de Cerdos del Paraguay (ACCP)<\/strong> y la <strong>Embajada de la Rep\u00fablica de China (Taiw\u00e1n)<\/strong> organizaron una degustaci\u00f3n de platos de fusi\u00f3n cultural para conmemorar este logro.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Con la presencia del <strong>Embajador Jose Han <\/strong>y el presidente de la Asociaci\u00f3n de Criadores de Cerdo de Paraguay, <strong>Ing. Hugo Schaffrath<\/strong>, los participantes pudieron degustar diferentes platos de carne porcina que combinaban las ricas culturas gastron\u00f3micas de ambos pa\u00edses.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para festejar la ubicaci\u00f3n de Taiw\u00e1n como primer comprador de carne porcina paraguaya, la Asociaci\u00f3n de Criadores de Cerdos del Paraguay (ACCP) y la Embajada de la Rep\u00fablica de China (Taiw\u00e1n) organizaron una degustaci\u00f3n de platos de fusi\u00f3n cultural para conmemorar este logro. Con la presencia del Embajador Jose Han y el presidente de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[34],"tags":[831,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-10538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Para festejar la ubicaci\u00f3n de Taiw\u00e1n como primer comprador de carne porcina paraguaya, la Asociaci\u00f3n de Criadores de Cerdos del Paraguay (ACCP) y la Embajada de la Rep\u00fablica de China (Taiw\u00e1n) organizaron una degustaci\u00f3n de platos de fusi\u00f3n cultural para conmemorar este logro. Con la presencia del Embajador Jose Han y el presidente de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-06T11:53:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/tw-accp.jpg?fit=1280%2C856&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"856\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds\",\"datePublished\":\"2023-05-06T11:53:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/\"},\"wordCount\":114,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/tw-accp.jpg?fit=1280%2C856&ssl=1\",\"keywords\":[\"destacada\",\"taiwan\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/\",\"name\":\"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/tw-accp.jpg?fit=1280%2C856&ssl=1\",\"datePublished\":\"2023-05-06T11:53:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/tw-accp.jpg?fit=1280%2C856&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/tw-accp.jpg?fit=1280%2C856&ssl=1\",\"width\":1280,\"height\":856},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/05\\\/06\\\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/","og_locale":"es_ES","og_type":"article","og_title":"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Para festejar la ubicaci\u00f3n de Taiw\u00e1n como primer comprador de carne porcina paraguaya, la Asociaci\u00f3n de Criadores de Cerdos del Paraguay (ACCP) y la Embajada de la Rep\u00fablica de China (Taiw\u00e1n) organizaron una degustaci\u00f3n de platos de fusi\u00f3n cultural para conmemorar este logro. Con la presencia del Embajador Jose Han y el presidente de la [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-05-06T11:53:21+00:00","og_image":[{"width":1280,"height":856,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/tw-accp.jpg?fit=1280%2C856&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds","datePublished":"2023-05-06T11:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/"},"wordCount":114,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/tw-accp.jpg?fit=1280%2C856&ssl=1","keywords":["destacada","taiwan"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/","url":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/","name":"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/tw-accp.jpg?fit=1280%2C856&ssl=1","datePublished":"2023-05-06T11:53:21+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/tw-accp.jpg?fit=1280%2C856&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/tw-accp.jpg?fit=1280%2C856&ssl=1","width":1280,"height":856},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/05\/06\/la-accp-y-la-embajada-de-taiwan-festejaron-el-desempeno-de-la-carne-porcina-paraguaya-en-ese-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"La ACCP y la Embajada de Taiw\u00e1n festejaron el desempe\u00f1o de la carne porcina paraguaya en ese pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/05\/tw-accp.jpg?fit=1280%2C856&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=10538"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/10539"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=10538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=10538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=10538"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=10538"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=10538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}