{"id":10320,"date":"2023-04-13T09:21:00","date_gmt":"2023-04-13T07:21:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/"},"modified":"2023-04-13T09:21:00","modified_gmt":"2023-04-13T07:21:00","slug":"un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/","title":{"rendered":"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Los taiwaneses se apresuran a comprar parches usados por sus pilotos de la fuerza a\u00e9rea que representan a <strong>un oso negro de Formosa golpeando a Winnie the Pooh<\/strong>, que representa al presidente de China, <strong>Xi Jinping<\/strong>, como un s\u00edmbolo desafiante de la resistencia de la isla a los juegos de guerra chinos.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">China comenz\u00f3<strong> <a href=\"https:\/\/informatepy.com\/2022\/2023\/04\/09\/china-comunista-rodea-taiwan-y-lleva-las-tensiones-al-maximo-en-la-region\/\" target=\"_blank\" rel=\"noreferrer noopener\">ejercicios militares&nbsp;alrededor de Taiw\u00e1n <\/a><\/strong>el s\u00e1bado, un d\u00eda despu\u00e9s de que la presidenta de la isla, <strong>Tsai Ing-wen<\/strong>, regresara de una breve visita a Estados Unidos, donde se reuni\u00f3 con el presidente de la C\u00e1mara de Representantes de Estados Unidos, <strong>Kevin McCarthy<\/strong>, a pesar de las amenazas de Beijing.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Los censores chinos han apuntado durante mucho tiempo a las representaciones de Winnie the Pooh, creadas por el autor brit\u00e1nico <strong>A.A. Milne<\/strong>, a trav\u00e9s de memes de Internet que comparan al oso ficticio con el presidente de China.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong>Alec Hsu<\/strong>, quien dise\u00f1\u00f3 el parche, lo ha estado vendiendo en su tienda desde el a\u00f1o pasado, pero vio un aumento en los pedidos despu\u00e9s de que la agencia de noticias militar de Taiw\u00e1n publicara el s\u00e1bado una foto del parche en el brazo de un piloto que inspeccionaba un avi\u00f3n de combate.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"zh\" dir=\"ltr\">\u53f0\u7063\u7a7a\u8ecdIDF\u6230\u6a5f\u806f\u968a\u65b0\u81c2\u7ae0\uff1a\u9ed1\u718a\u6253\u7dad\u5c3c<br>One punch ! <a href=\"https:\/\/t.co\/bPaqz0K0OQ\">https:\/\/t.co\/bPaqz0K0OQ<\/a> <a href=\"https:\/\/t.co\/oQvuqt4Wc5\">pic.twitter.com\/oQvuqt4Wc5<\/a><\/p>&mdash; \u65b0\u2027\u4e8c\u4e03\u90e8\u968a \u8ecd\u4e8b\u96dc\u8ac7 (New 27 Brigade)\ud83c\uddf9\ud83c\uddfc\ud83c\uddfa\ud83c\udde6\ud83c\uddee\ud83c\uddf1 (@new27brigade) <a href=\"https:\/\/twitter.com\/new27brigade\/status\/1645032643225075712?ref_src=twsrc%5Etfw\">April 9, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">El parche muestra a un oso negro de Formosa enojado sosteniendo la bandera de Taiw\u00e1n y golpeando a Winnie the Pooh, con el lema \u00ab\u00a1Scramble!\u00bb, refiri\u00e9ndose a lo que los pilotos de la isla han tenido que hacer con una mayor frecuencia en los \u00faltimos tres a\u00f1os a medida que China env\u00eda m\u00e1s aviones a la zona de identificaci\u00f3n de defensa a\u00e9rea de Taiw\u00e1n.<\/p>\n\n\n\n<p><sub>Con informaci\u00f3n de Reuters<\/sub><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los taiwaneses se apresuran a comprar parches usados por sus pilotos de la fuerza a\u00e9rea que representan a un oso negro de Formosa golpeando a Winnie the Pooh, que representa al presidente de China, Xi Jinping, como un s\u00edmbolo desafiante de la resistencia de la isla a los juegos de guerra chinos. China comenz\u00f3 ejercicios [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[33],"tags":[207,831,689],"jnews-series":[],"ppma_author":[830],"class_list":["post-10320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-china","tag-destacada","tag-taiwan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Los taiwaneses se apresuran a comprar parches usados por sus pilotos de la fuerza a\u00e9rea que representan a un oso negro de Formosa golpeando a Winnie the Pooh, que representa al presidente de China, Xi Jinping, como un s\u00edmbolo desafiante de la resistencia de la isla a los juegos de guerra chinos. China comenz\u00f3 ejercicios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-13T07:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\"},\"headline\":\"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral\",\"datePublished\":\"2023-04-13T07:21:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/\"},\"wordCount\":319,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1\",\"keywords\":[\"china\",\"destacada\",\"taiwan\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/\",\"name\":\"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1\",\"datePublished\":\"2023-04-13T07:21:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/13\\\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/98728344b91c548ef8544c80daf58463\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/","og_locale":"es_ES","og_type":"article","og_title":"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Los taiwaneses se apresuran a comprar parches usados por sus pilotos de la fuerza a\u00e9rea que representan a un oso negro de Formosa golpeando a Winnie the Pooh, que representa al presidente de China, Xi Jinping, como un s\u00edmbolo desafiante de la resistencia de la isla a los juegos de guerra chinos. China comenz\u00f3 ejercicios [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-04-13T07:21:00+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463"},"headline":"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral","datePublished":"2023-04-13T07:21:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/"},"wordCount":319,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1","keywords":["china","destacada","taiwan"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/","url":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/","name":"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1","datePublished":"2023-04-13T07:21:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/13\/un-punetazo-en-la-cara-para-la-caricatura-de-xi-la-insignia-de-la-fuerza-aerea-de-taiwan-que-se-vuelve-viral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Un pu\u00f1etazo en la cara para la caricatura de Xi: la insignia de la fuerza a\u00e9rea de Taiw\u00e1n que se vuelve viral"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/98728344b91c548ef8544c80daf58463","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png9c354f01c536b2d49dbb929e96603401","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2024\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/04\/parche-piloto-taiwan.jpg?fit=960%2C640&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":830,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/cropped-Isologo-sin-fondo.png"},"author_category":"1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=10320"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/10321"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=10320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=10320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=10320"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=10320"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=10320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}