{"id":10236,"date":"2023-04-02T10:00:00","date_gmt":"2023-04-02T08:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/"},"modified":"2023-04-02T10:00:00","modified_gmt":"2023-04-02T08:00:00","slug":"bolivia-del-blindaje-a-la-suplica","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/","title":{"rendered":"Bolivia: del blindaje a la s\u00faplica"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Un par de semanas atr\u00e1s, mientras participaba en una mesa debate sobre la econom\u00eda de Bolivia, un exaltado contertulio cort\u00f3 mi participaci\u00f3n de manera violenta. Sus palabras fueron: <em><strong>\u00abNo milito en el Movimiento Al Socialismo, pero no me parece correcto que afirme que la econom\u00eda boliviana est\u00e1 en ca\u00edda. Personalmente, considero que el equipo econ\u00f3mico del gobierno est\u00e1 conformado por los mejores economistas del pa\u00eds\u00bb<\/strong><\/em>.\u00a0<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La interrupci\u00f3n del iracundo participante me dio la oportunidad de continuar el evento mostrando datos del desastre que causaron <strong>Evo Morales <\/strong>y sus bandoleros. Pero, como dir\u00edan <strong>Mark Twain<\/strong>: <em><strong>\u00abninguna cantidad de evidencia convence a un idiota\u00bb.<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Pocos d\u00edas despu\u00e9s de esa surrealista escena, empiezan las colas por conseguir d\u00f3lares, las calificadoras de riesgo, entre ellas, Moody\u2019s y Fitch Ratings, alertaron sobre la econom\u00eda boliviana, adem\u00e1s, seg\u00fan Bloomberg, los bonos soberanos de Bolivia han generado p\u00e9rdidas del 7% en lo que va de este a\u00f1o. En este punto es necesario aclarar, \u00bfu oscurecer?, el panorama: <em>Las AFPS fueron forzadas a comprar los bonos soberanos. Es decir que las jubilaciones de millones de bolivianos est\u00e1n \u00abinvertidas\u00bb en unos t\u00edtulos que van en picada.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/02\/peredo-balderrama.jpg?resize=464%2C137&#038;ssl=1\" alt=\"\" class=\"wp-image-17646\" width=\"464\" height=\"137\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Ante las bajas calificaciones internacionales, <strong>Marcelo Montenegro<\/strong>, ministro de econom\u00eda, afirm\u00f3 que Moody\u2019s no consider\u00f3 otras variables, tampoco tom\u00f3 en cuenta el efecto de la guerra entre Rusia y Ucrania. En sencillo, culp\u00f3 de los desastres a otros, menos al verdadero causante de la tragedia: <em>El Modelo Econ\u00f3mico Social Comunitario Productivo (MESCP). <\/em>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Adem\u00e1s, seg\u00fan los datos del Instituto Nacional de Estad\u00edstica (INE), Bolivia, al empezar a adquirir del exterior m\u00e1s combustible que el que vende a otros pa\u00edses, se convirti\u00f3 en abril de 2022 en un importador neto de energ\u00eda. Otro dato que tira al tacho el mito de la gran gesti\u00f3n econ\u00f3mica y energ\u00e9tica de <strong>Evo Morales<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Pero eso no es todo, <strong>Arce Catacora<\/strong>, que en Bolivia es un mudo pol\u00edglota, porque est\u00e1 callado en todos los idiomas posibles,aprovech\u00f3 la m\u00e1s reciente asamblea de la ONU para pedir, por tercera vez desde que arranc\u00f3 su presidencia, la condonaci\u00f3n de la deuda externa a los pa\u00edses en desarrollo.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\u00bfQu\u00e9 significa que las principales calificadoras de riesgo hayan puesto a Bolivia en zonas rojas y que el presidente boliviano lloriquee por no pagar las deudas que adquiri\u00f3 durante su \u00e9poca de ministro?<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Simple, ya nadie en el ambiente internacional se come el chamuyo sobre la fortaleza del modelo econ\u00f3mico boliviano, ni siquiera su propio creador.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2023\/01\/grupo-mote-balderrama.jpg?resize=440%2C239&#038;ssl=1\" alt=\"\" class=\"wp-image-17118\" width=\"440\" height=\"239\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Empero, todav\u00eda hay m\u00e1s cap\u00edtulos en la tragedia nacional, ya que el gobierno, en su desesperaci\u00f3n por conseguir recursos, decidi\u00f3 reponer la Ley 1386 (renumerada como 280). El proyecto habla, una vez m\u00e1s, de \u00abfortalecer la lucha contra la legitimaci\u00f3n de ganancias il\u00edcitas\u00bb. Sin embargo, tras sus maquillajes sem\u00e1nticos, se repite la intenci\u00f3n de establecer un sistema de vigilancia y asalto al trabajo del ciudadano de a pie, en especial, al sector informal. Es evidente que la dictadura est\u00e1 dispuesta a todo para mantener a flote su caduco modelo. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Tengo la esperanza que la informalidad y otros sectores del capitalismo popular, ante este nuevo atentado contra la propiedad privada, rompan definitivamente su romance antinatural con el MAS. Pues es il\u00f3gico que ese segmento de la poblaci\u00f3n, con pr\u00e1cticas de emprendimiento y muy cercanas al libre mercado, haya adoptado simbolog\u00eda y lenguaje socialista. Asimismo, es una buena oportunidad para que la oposici\u00f3n democr\u00e1tica construya puentes con los sectores de la econom\u00eda informal, la sinergia entre lo popular y lo electoral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un par de semanas atr\u00e1s, mientras participaba en una mesa debate sobre la econom\u00eda de Bolivia, un exaltado contertulio cort\u00f3 mi participaci\u00f3n de manera violenta. Sus palabras fueron: \u00abNo milito en el Movimiento Al Socialismo, pero no me parece correcto que afirme que la econom\u00eda boliviana est\u00e1 en ca\u00edda. Personalmente, considero que el equipo econ\u00f3mico [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":4871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_food_recipe":[],"enable_food_recipe":"","food_recipe_title":"","food_recipe_description":"","food_recipe_serve":"","food_recipe_time":"","food_recipe_prep":"","food_recipe_level":"","food_recipe_keywords":"","food_recipe_category":"","food_recipe_cuisine":"","food_recipe_yield":"","food_recipe_calories":"","enable_print_recipe":"","ingredient":[],"instruction":"","jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"jnews_podcast_option":[],"jnews_podcast_series":[],"footnotes":""},"categories":[39],"tags":[577,831],"jnews-series":[],"ppma_author":[1371],"class_list":["post-10236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-bolivia","tag-destacada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolivia: del blindaje a la s\u00faplica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia: del blindaje a la s\u00faplica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"og:description\" content=\"Un par de semanas atr\u00e1s, mientras participaba en una mesa debate sobre la econom\u00eda de Bolivia, un exaltado contertulio cort\u00f3 mi participaci\u00f3n de manera violenta. Sus palabras fueron: \u00abNo milito en el Movimiento Al Socialismo, pero no me parece correcto que afirme que la econom\u00eda boliviana est\u00e1 en ca\u00edda. Personalmente, considero que el equipo econ\u00f3mico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/\" \/>\n<meta property=\"og:site_name\" content=\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-02T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hugo Marcelo Balderrama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hugobalderrama\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hugo Marcelo Balderrama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/\"},\"author\":{\"name\":\"Hugo Marcelo Balderrama\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\"},\"headline\":\"Bolivia: del blindaje a la s\u00faplica\",\"datePublished\":\"2023-04-02T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/\"},\"wordCount\":629,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"keywords\":[\"Bolivia\",\"destacada\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/\",\"name\":\"Bolivia: del blindaje a la s\u00faplica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"datePublished\":\"2023-04-02T08:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"width\":1280,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/2023\\\/04\\\/02\\\/bolivia-del-blindaje-a-la-suplica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolivia: del blindaje a la s\u00faplica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"description\":\"InformatePy\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#organization\",\"name\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1\",\"width\":500,\"height\":94,\"caption\":\"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/#\\\/schema\\\/person\\\/ab3c2d3aa316b6d887beec94bd4bfcde\",\"name\":\"Hugo Marcelo Balderrama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hugo-balderrama.jpg\",\"caption\":\"Hugo Marcelo Balderrama\"},\"description\":\"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hugobalderrama\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2024\\\/author\\\/hbalderrama\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolivia: del blindaje a la s\u00faplica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/","og_locale":"es_ES","og_type":"article","og_title":"Bolivia: del blindaje a la s\u00faplica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","og_description":"Un par de semanas atr\u00e1s, mientras participaba en una mesa debate sobre la econom\u00eda de Bolivia, un exaltado contertulio cort\u00f3 mi participaci\u00f3n de manera violenta. Sus palabras fueron: \u00abNo milito en el Movimiento Al Socialismo, pero no me parece correcto que afirme que la econom\u00eda boliviana est\u00e1 en ca\u00edda. Personalmente, considero que el equipo econ\u00f3mico [&hellip;]","og_url":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/","og_site_name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","article_published_time":"2023-04-02T08:00:00+00:00","og_image":[{"width":1280,"height":700,"url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","type":"image\/jpeg"}],"author":"Hugo Marcelo Balderrama","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hugobalderrama","twitter_misc":{"Escrito por":"Hugo Marcelo Balderrama","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/"},"author":{"name":"Hugo Marcelo Balderrama","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde"},"headline":"Bolivia: del blindaje a la s\u00faplica","datePublished":"2023-04-02T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/"},"wordCount":629,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","keywords":["Bolivia","destacada"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/","url":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/","name":"Bolivia: del blindaje a la s\u00faplica - Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","isPartOf":{"@id":"https:\/\/informatepy.com\/2024\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","datePublished":"2023-04-02T08:00:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","width":1280,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2024\/2023\/04\/02\/bolivia-del-blindaje-a-la-suplica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2024\/"},{"@type":"ListItem","position":2,"name":"Bolivia: del blindaje a la s\u00faplica"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2024\/#website","url":"https:\/\/informatepy.com\/2024\/","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","description":"InformatePy","publisher":{"@id":"https:\/\/informatepy.com\/2024\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2024\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2024\/#organization","name":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma","url":"https:\/\/informatepy.com\/2024\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2024\/02\/Logotipo-sin-fondo-informate-py500.png?fit=500%2C94&ssl=1","width":500,"height":94,"caption":"Informate Py Creemos en la libertad de expresi\u00f3n y en la capacidad de la gente de reflexionar\u00a0por\u00a0si\u00a0misma"},"image":{"@id":"https:\/\/informatepy.com\/2024\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/informatepy.com\/2024\/#\/schema\/person\/ab3c2d3aa316b6d887beec94bd4bfcde","name":"Hugo Marcelo Balderrama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg15a746afa8230efe7f311abfd5d4dba9","url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","contentUrl":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","caption":"Hugo Marcelo Balderrama"},"description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hugobalderrama"],"url":"https:\/\/informatepy.com\/2024\/author\/hbalderrama\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2024\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"authors":[{"term_id":1371,"user_id":31,"is_guest":0,"slug":"hbalderrama","display_name":"Hugo Marcelo Balderrama","avatar_url":{"url":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg","url2x":"https:\/\/informatepy.com\/2024\/wp-content\/uploads\/2026\/02\/hugo-balderrama.jpg"},"author_category":"1","first_name":"Hugo Marcelo","last_name":"Balderrama","user_url":"","job_title":"","description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad."}],"_links":{"self":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/comments?post=10236"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/posts\/10236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media\/4871"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/media?parent=10236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/categories?post=10236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/tags?post=10236"},{"taxonomy":"jnews-series","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/jnews-series?post=10236"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2024\/wp-json\/wp\/v2\/ppma_author?post=10236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}