{"id":6399,"date":"2021-12-25T09:00:00","date_gmt":"2021-12-25T09:00:00","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/"},"modified":"2021-12-25T09:00:00","modified_gmt":"2021-12-25T09:00:00","slug":"eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/","title":{"rendered":"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Las Fuerzas Armadas de Jap\u00f3n y Estados Unidos elaboraron un plan preliminar para una operaci\u00f3n conjunta ante una posible emergencia en Taiw\u00e1n<\/strong>, inform\u00f3 el jueves la agencia de noticias japonesa&nbsp;<em>Kyodo<\/em>, citando fuentes gubernamentales japonesas an\u00f3nimas, en medio de&nbsp;<strong>crecientes tensiones entre la isla y China.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">China asegura que la democr\u00e1tica Taiw\u00e1n es su propio territorio \u201csagrado\u201d y en los \u00faltimos dos a\u00f1os ha&nbsp;<strong>intensificado la presi\u00f3n militar y diplom\u00e1tica para hacer valer sus reclamos de soberan\u00eda, alimentando la ira en Taipei y la preocupaci\u00f3n en Washington.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En ese contexto,<strong>\u00a0el anuncio acent\u00faa la crisis entre Taiw\u00e1n y Beijing,<\/strong>\u00a0que ha proclamado que perseguir\u00e1 la reunificaci\u00f3n de la isla que fue colonia japonesa, apelando, si fuera necesario, a la fuerza.<\/p>\n\n\n\n<h6 class=\"has-text-align-center wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" height=\"3558\" width=\"5337\" alt=\"El destructor estadounidense USS Dewey navega por las aguas del Oc\u00e9ano Pac\u00edfico (Foto: REUTERS)\" src=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/GU6MNY235HSE5JUFY35MV526EU.jpg%20420w\">El destructor estadounidense USS Dewey navega por las aguas del Oc\u00e9ano Pac\u00edfico (Foto: REUTERS)<\/h6>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El gobierno de Taiw\u00e1n dice que quiere la&nbsp;<strong>paz<\/strong>, pero tambi\u00e9n de que&nbsp;<strong>se defender\u00e1 si es necesario.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Seg\u00fan el plan acordado el jueves, que se encuentra en una etapa inicial, la&nbsp;<strong>Marina de EEUU establecer\u00e1 una base temporal en el archipi\u00e9lago Nansei, ubicado estrat\u00e9gicamente entre Jap\u00f3n y Taiw\u00e1n, para reaccionar en caso de que fuera necesario.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Las fuerzas armadas japonesas brindar\u00edan&nbsp;<strong>apoyo log\u00edstico en \u00e1reas como municiones y suministros de combustible,<\/strong>&nbsp;agreg\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El emplazamiento final se baraja entre 40 candidatos.<strong>\u00a0El archipi\u00e9lago cuenta con unas 200 islas, entre ellas, algunas deshabitadas, y se extiende desde Kyushu<\/strong>, una de las cuatro islas principales de Jap\u00f3n, hasta Taiw\u00e1n.<\/p>\n\n\n\n<h6 class=\"has-text-align-center wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" height=\"2560\" width=\"3840\" alt=\"Soldados marchan en un ejercicio militar de evasi\u00f3n extranjera en Taiw\u00e1n (Foto: REUTERS)\" src=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/XLTWV6PBDOB65MWT2A7VBIQEUI.jpg%20420w\">Soldados marchan en un ejercicio militar de evasi\u00f3n extranjera en Taiw\u00e1n (Foto: REUTERS)<\/h6>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Jap\u00f3n \u2014ex gobierno colonial de Taiw\u00e1n\u2014 junto a Estados Unidos, probablemente llegar\u00e1n a un acuerdo para&nbsp;<strong>que el plan preliminar pase a ser oficial en una reuni\u00f3n \u201c2 + 2\u2033 de ministros de Relaciones Exteriores y Defensa a principios del pr\u00f3ximo a\u00f1o<\/strong>, dijo la agencia de noticias.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Mientras tanto, el portaaviones chino\u00a0<strong>Liaoning realiz\u00f3 simulacros militares al este de Okinawa que involucraron operaciones de aviones de combate y helic\u00f3pteros,\u00a0demostrando una mayor capacidad de combate<\/strong>, dijo un observador citado el mi\u00e9rcoles por el\u00a0<em>South China Morning Post<\/em>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>China ve al Taiw\u00e1n democr\u00e1tico como una provincia descarriada,<\/strong>&nbsp;esperando el d\u00eda en que la isla pueda ser puesta bajo su control, pac\u00edfica o militarmente, sin derecho a las relaciones entre estados.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Estados Unidos, mantiene una l\u00ednea ambigua sobre Taiw\u00e1n, pero\u00a0<strong>Washington es el mayor proveedor y aliado de armas de la isla y est\u00e1 obligado por ley a ayudarla a defenderse.<\/strong><\/p>\n\n\n\n<h6 class=\"has-text-align-center wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" height=\"4938\" width=\"7586\" alt=\"El presidente de EEUU, Joe Biden junto al primer ministro japon\u00e9s Yoshihide Suga en la Casa Blanca (Foto: REUTERS\/Tom Brenner)\" src=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/G4LX477D3AVK366NGWNIPSAEPU.jpg%20420w\">El presidente de EEUU, Joe Biden junto al primer ministro japon\u00e9s Yoshihide Suga en la Casa Blanca (Foto: REUTERS\/Tom Brenner)<\/h6>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Jap\u00f3n y Estados Unidos destacaron en una\u00a0<strong>declaraci\u00f3n conjunta la importancia de \u201cla paz y la estabilidad en el Estrecho de Taiw\u00e1n\u201d cuando Joe Biden se reuni\u00f3 en abril con el entonces primer ministro Yoshihide Suga.<\/strong>\u00a0Fue la primera vez en medio siglo que los l\u00edderes de ambos pa\u00edses mencionaron a Taiw\u00e1n en un comunicado.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><em>Infobae (Con informaci\u00f3n de Reuters)<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Aunque se trata de un plan preliminar, est\u00e1 previsto que ministros de ambos pa\u00edses lo formalicen a principios del pr\u00f3ximo a\u00f1o. Prev\u00e9 la instalaci\u00f3n de bases provisorias y la colaboraci\u00f3n log\u00edstica<\/p>\n","protected":false},"author":1,"featured_media":6394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[1],"tags":[],"ppma_author":[998],"class_list":["post-6399","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sin-categoria"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"Aunque se trata de un plan preliminar, est\u00e1 previsto que ministros de ambos pa\u00edses lo formalicen a principios del pr\u00f3ximo a\u00f1o. Prev\u00e9 la instalaci\u00f3n de bases provisorias y la colaboraci\u00f3n log\u00edstica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-25T09:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"1307\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/51a66e4894ad41947ebb945804418db8\"},\"headline\":\"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n\",\"datePublished\":\"2021-12-25T09:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/\"},\"wordCount\":557,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/\",\"name\":\"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1\",\"datePublished\":\"2021-12-25T09:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1\",\"width\":1960,\"height\":1307},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/12\\\/25\\\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/51a66e4894ad41947ebb945804418db8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2022\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/","og_locale":"es_ES","og_type":"article","og_title":"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n - Informatepy.com","og_description":"Aunque se trata de un plan preliminar, est\u00e1 previsto que ministros de ambos pa\u00edses lo formalicen a principios del pr\u00f3ximo a\u00f1o. Prev\u00e9 la instalaci\u00f3n de bases provisorias y la colaboraci\u00f3n log\u00edstica","og_url":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-12-25T09:00:00+00:00","og_image":[{"width":1960,"height":1307,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/51a66e4894ad41947ebb945804418db8"},"headline":"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n","datePublished":"2021-12-25T09:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/"},"wordCount":557,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/","url":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/","name":"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1","datePublished":"2021-12-25T09:00:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1","width":1960,"height":1307},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/51a66e4894ad41947ebb945804418db8","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/informatepy.com\/2022"],"url":"https:\/\/informatepy.com\/2022\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1960%2C1307&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":998,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"","user_url":"http:\/\/informatepy.com\/2022","last_name":"","first_name":"","job_title":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/6399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=6399"}],"version-history":[{"count":0,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/6399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/6394"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=6399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=6399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=6399"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=6399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}