{"id":6010,"date":"2021-11-24T16:40:04","date_gmt":"2021-11-24T16:40:04","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/"},"modified":"2022-09-28T00:01:16","modified_gmt":"2022-09-28T00:01:16","slug":"la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/","title":{"rendered":"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La \u201cdoctora\u201d Yolanda Gonz\u00e1lez Barrios cumpli\u00f3 su promesa, <strong><a href=\"https:\/\/informatepy.com\/2021\/2021\/10\/27\/la-doctora-yolanda-gonzalez-barrios-dejara-volar-alto-a-los-pacientes-de-covid-que-lleguen-a-su-hospital-sin-vacunar\/\" target=\"_blank\" rel=\"noreferrer noopener\">y pretende que aquellos que no se inocularon contra el COVID 19 \u201cvuelen alto\u201d.<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy circul\u00f3 en redes sociales un video donde el personal del Hospital que la \u201cdoctora\u201d dirige, como un neo tribunal inquisidor, amo y se\u00f1or de la vida y la muerte (y de los recursos del Estado) exig\u00eda a quienes pretend\u00edan ingresar al nosocomio el carnet de vacunaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 de la violaci\u00f3n a su juramento hipocr\u00e1tico, Yolanda Gonz\u00e1lez Barrios est\u00e1 incurriendo en discriminaci\u00f3n y, lo que es peor a\u00fan, es omisi\u00f3n de auxilio, violaci\u00f3n del derecho a la salud, violaci\u00f3n de la igualdad de acceso a la atenci\u00f3n de la salud, privaci\u00f3n del acceso a la salud garantizado, todos derechos garantizados por la Constituci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/VidayLibertadPy?ref_src=twsrc%5Etfw\">@VidayLibertadPy<\/a> <a href=\"https:\/\/twitter.com\/Alanredick1?ref_src=twsrc%5Etfw\">@Alanredick1<\/a> <a href=\"https:\/\/twitter.com\/enriquevp?ref_src=twsrc%5Etfw\">@enriquevp<\/a> <a href=\"https:\/\/twitter.com\/InformatePy1?ref_src=twsrc%5Etfw\">@InformatePy1<\/a> <a href=\"https:\/\/twitter.com\/nunez_lider?ref_src=twsrc%5Etfw\">@nunez_lider<\/a> <a href=\"https:\/\/twitter.com\/CPR132?ref_src=twsrc%5Etfw\">@CPR132<\/a> @MarchiCiciolli <a href=\"https:\/\/twitter.com\/jorge_a_bozzano?ref_src=twsrc%5Etfw\">@jorge_a_bozzano<\/a> <a href=\"https:\/\/twitter.com\/Jorgebritez1984?ref_src=twsrc%5Etfw\">@Jorgebritez1984<\/a> esto es ciertooo??? <a href=\"https:\/\/t.co\/xr8HbCuGzF\">pic.twitter.com\/xr8HbCuGzF<\/a><\/p>&mdash; Romy\ud83d\ude0a\u270c\ud83c\udffb (@romy01_) <a href=\"https:\/\/twitter.com\/romy01_\/status\/1463527339615215619?ref_src=twsrc%5Etfw\">November 24, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Es tiempo de exigir que la ley se cumpla, en redes sociales, en los juzgados o en la calle; que el <strong>inoperante ministro de salud, Julio Borba<\/strong>, elija como quiere que la gente le exija que haga su trabajo, solo d\u00edgalo y el pueblo se va a ocupar. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ah, nos est\u00e1bamos olvidando. \u201cDoctora\u201d, no lo mande a su encargado de comunicaci\u00f3n a que nos escriba para \u201cpedirnos explicaciones\u201d, <strong>porque tambi\u00e9n es nuestro empleado y, de \u00faltima, si su encargado de comunicaci\u00f3n la quiere defender como un hombre (ya que es su esposo) <\/strong>que se presente como su esposo y no como encargado de comunicaci\u00f3n del HNI y a vemos como resolver el tema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u201cdoctora\u201d Yolanda Gonz\u00e1lez Barrios cumpli\u00f3 su promesa, y pretende que aquellos que no se inocularon contra el COVID 19 \u201cvuelen alto\u201d. Hoy circul\u00f3 en redes sociales un video donde el personal del Hospital que la \u201cdoctora\u201d dirige, como un neo tribunal inquisidor, amo y se\u00f1or de la vida y la muerte (y de los [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[18],"tags":[871,1389,1343],"ppma_author":[1037],"class_list":["post-6010","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-destacada","tag-hospital-nacional-itaugua","tag-yolanda-gonzalez-barrios"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"La \u201cdoctora\u201d Yolanda Gonz\u00e1lez Barrios cumpli\u00f3 su promesa, y pretende que aquellos que no se inocularon contra el COVID 19 \u201cvuelen alto\u201d. Hoy circul\u00f3 en redes sociales un video donde el personal del Hospital que la \u201cdoctora\u201d dirige, como un neo tribunal inquisidor, amo y se\u00f1or de la vida y la muerte (y de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-24T16:40:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T00:01:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua\",\"datePublished\":\"2021-11-24T16:40:04+00:00\",\"dateModified\":\"2022-09-28T00:01:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/\"},\"wordCount\":283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1\",\"keywords\":[\"destacada\",\"hospital nacional itaugua\",\"yolanda gonzalez barrios\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/\",\"name\":\"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2021-11-24T16:40:04+00:00\",\"dateModified\":\"2022-09-28T00:01:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/11\\\/24\\\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/","og_locale":"es_ES","og_type":"article","og_title":"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua - Informatepy.com","og_description":"La \u201cdoctora\u201d Yolanda Gonz\u00e1lez Barrios cumpli\u00f3 su promesa, y pretende que aquellos que no se inocularon contra el COVID 19 \u201cvuelen alto\u201d. Hoy circul\u00f3 en redes sociales un video donde el personal del Hospital que la \u201cdoctora\u201d dirige, como un neo tribunal inquisidor, amo y se\u00f1or de la vida y la muerte (y de los [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-11-24T16:40:04+00:00","article_modified_time":"2022-09-28T00:01:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua","datePublished":"2021-11-24T16:40:04+00:00","dateModified":"2022-09-28T00:01:16+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/"},"wordCount":283,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1","keywords":["destacada","hospital nacional itaugua","yolanda gonzalez barrios"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/","url":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/","name":"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1","datePublished":"2021-11-24T16:40:04+00:00","dateModified":"2022-09-28T00:01:16+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2021\/11\/24\/la-renuncia-no-es-suficiente-despido-y-enjuiciamiento-a-la-directora-del-hospital-nacional-de-itaugua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"La renuncia no es suficiente. Despido y enjuiciamiento a la directora del Hospital Nacional de Itaugua"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/yolanda-gonzalez-barrios.jpeg?fit=1200%2C630&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1037,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png"},"author_category":"","user_url":"","last_name":"","first_name":"Redacci\u00f3n","job_title":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/6010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=6010"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/6010\/revisions"}],"predecessor-version":[{"id":13367,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/6010\/revisions\/13367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/5767"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=6010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=6010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=6010"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=6010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}